{"id":15192,"date":"2017-03-03T07:28:41","date_gmt":"2017-03-03T10:28:41","guid":{"rendered":"http:\/\/caririemacao.com\/1\/?p=15192"},"modified":"2017-03-03T07:28:41","modified_gmt":"2017-03-03T10:28:41","slug":"horario-de-verao-gerou-economia-de-r-159-milhoes-com-reducao-do-uso-de-termicas","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2017\/03\/03\/horario-de-verao-gerou-economia-de-r-159-milhoes-com-reducao-do-uso-de-termicas\/","title":{"rendered":"Hor\u00e1rio de ver\u00e3o gerou economia de R$ 159 milh\u00f5es com redu\u00e7\u00e3o do uso de t\u00e9rmicas"},"content":{"rendered":"<p>O hor\u00e1rio de ver\u00e3o deste ano possibilitou uma economia de R$ 159,5 milh\u00f5es, decorrentes da redu\u00e7\u00e3o do acionamento de usinas t\u00e9rmicas durante o per\u00edodo de vig\u00eancia da medida. O n\u00famero \u00e9 maior do que previsto pelo governo, que esperava uma economia de R$ 147,5 milh\u00f5es, mas ficou abaixo do resultado do ano passado, quando o total chegou a R$ 162 milh\u00f5es.<\/p>\n<p>Segundo o Operador Nacional do Sistema El\u00e9trico, no Sistema Sul, houve uma redu\u00e7\u00e3o da ordem de 4,3% na demanda no hor\u00e1rio de pico (entre as 18h e as 21h), o que equivale, aproximadamente, ao atendimento do dobro da carga da cidade de Florian\u00f3polis neste hor\u00e1rio. No Sistema Sudeste\/Centro-Oeste, a redu\u00e7\u00e3o da demanda foi equivalente ao atendimento da metade da carga da cidade do Rio de Janeiro no hor\u00e1rio de ponta, aproximadamente.<\/p>\n<p>Esta edi\u00e7\u00e3o do hor\u00e1rio de ver\u00e3o durou 126 dias, de 16 de outubro de 2016 a 19 de fevereiro de 2017. De acordo com o Minist\u00e9rio de Minas e Energia, al\u00e9m da economia de dinheiro, a medida gera ganhos qualitativos com a redu\u00e7\u00e3o do consumo no hor\u00e1rio de pico noturno, diminuindo os carregamentos no sistema de transmiss\u00e3o, proporcionando maior flexibilidade operativa para realiza\u00e7\u00e3o de manuten\u00e7\u00f5es em equipamentos e redu\u00e7\u00e3o de cortes de carga em situa\u00e7\u00f5es de emerg\u00eancia, o que gera um aumento na seguran\u00e7a do atendimento ao consumidor final.<\/p>\n<p><strong>CARIRI EM A\u00c7\u00c3O<\/strong><\/p>\n<p>Com \u00a0Ag\u00eancia Brasil\/ Foto: Reprodu\u00e7\u00e3o Google<\/p>\n<p><strong>Leia mais not\u00edcias em\u00a0<a href=\"http:\/\/caririemacao.com\/\">caririemacao.com<\/a>, siga nossa p\u00e1gina no\u00a0<a href=\"https:\/\/www.facebook.com\/ads\/growth\/aymt\/homepage\/panel\/redirect\/?data=%7B%22ad_account_ids%22%3A%5B410861159029450%5D%2C%22object_ids%22%3A%5B302749469861083%2C534983029888737%5D%2C%22campaign_ids%22%3A%5B%5D%2C%22selected_ad_account_id%22%3A410861159029450%2C%22selected_object_id%22%3A302749469861083%2C%22selected_time_range%22%3A%22%22%2C%22is_panel_collapsed%22%3A0%2C%22is_advertiser_valid%22%3A0%2C%22section%22%3A%22Object+Section%22%2C%22clicked_target%22%3A%22Selected+Object%22%2C%22event%22%3A%22click%22%7D&amp;redirect_url=https%3A%2F%2Fwww.facebook.com%2FCaririEmAcao%2F%3Fref%3Daymt_homepage_panel\">Facebook\u00a0<\/a>e\u00a0<a href=\"https:\/\/www.instagram.com\/cariri_em_acao\/?hl=pt-br\">Instagram<\/a>\u00a0veja nossas mat\u00e9rias e fotos. Voc\u00ea tamb\u00e9m pode enviar informa\u00e7\u00f5es \u00e0 Reda\u00e7\u00e3o do Portal Cariri em A\u00e7\u00e3o pelo WhatsApp (83) 9 9634.5791, (83) 9 9601-1162 ou (83) 9 99418939.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O hor\u00e1rio de ver\u00e3o deste ano possibilitou uma economia de R$ 159,5 milh\u00f5es, decorrentes da redu\u00e7\u00e3o do acionamento de usinas t\u00e9rmicas durante o per\u00edodo de&hellip; <\/p>\n","protected":false},"author":2,"featured_media":15194,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-15192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/15192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=15192"}],"version-history":[{"count":0,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/15192\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/15194"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=15192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=15192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=15192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}