{"id":167573,"date":"2020-05-05T14:41:52","date_gmt":"2020-05-05T17:41:52","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=167573"},"modified":"2020-05-05T14:41:52","modified_gmt":"2020-05-05T17:41:52","slug":"mortes-por-covid-19-podem-chegar-a-3-mil-por-dia-nos-eua-ate-junho-diz-documento","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2020\/05\/05\/mortes-por-covid-19-podem-chegar-a-3-mil-por-dia-nos-eua-ate-junho-diz-documento\/","title":{"rendered":"Mortes por Covid-19 podem chegar a 3 mil por dia nos EUA at\u00e9 junho, diz documento"},"content":{"rendered":"\n<p>Um documento interno do Centro de Controle de Doen\u00e7as (CDC) nos&nbsp;<a href=\"https:\/\/g1.globo.com\/tudo-sobre\/estados-unidos\/\">Estados Unidos<\/a>&nbsp;vazado \u00e0 imprensa revela previs\u00f5es de uma piora acentuada na crise gerada pelo novo coronav\u00edrus nos EUA.<\/p>\n\n\n\n<p>Segundo reportagens divulgadas nesta segunda-feira (4) pelos jornais &#8220;The New York Times&#8221; e &#8220;Washington Post&#8221;, o n\u00famero de infe\u00e7\u00f5es di\u00e1rias no pa\u00eds pode aumentar em at\u00e9 oito vezes, chegando a 200 mil at\u00e9 o in\u00edcio de junho, em contraste com a m\u00e9dia de 25 mil novos casos registrados diariamente no pa\u00eds.<\/p>\n\n\n\n<p>De acordo com o documento, a contagem di\u00e1ria de mortos no pa\u00eds pode aumentar significativamente e chegar a 3 mil at\u00e9 o final de maio. Segundo estimativas, a m\u00e9dia di\u00e1ria dos \u00f3bitos \u00e9 atualmente de cerca de 2 mil no pa\u00eds, que j\u00e1 e o mais atingido pela pandemia de Covid-19, a doen\u00e7a causada pelo novo coronav\u00edrus. As proje\u00e7\u00f5es se baseiam em dados compilados pela Ag\u00eancia Federal de Gerenciamento de Emerg\u00eancias.<\/p>\n\n\n\n<p>O &#8220;Washington Post&#8221; citou um professor de epidemiologia da Escola Bloomberg de Sa\u00fade P\u00fablica da Universidade Johns Hopkins que afirma que o documento vazado \u00e0 imprensa se baseia em dados de uma ampla variedade de possibilidades e de modelos que foram apresentados ao CDC como um trabalho ainda em andamento.<\/p>\n\n\n\n<p>Em todo o pa\u00eds, 1.015 mortes foram registradas nesta segunda-feira, o menor n\u00famero de \u00f3bitos di\u00e1rios desde o in\u00edcio de abril, o que aumentou as esperan\u00e7as de um poss\u00edvel retorno \u00e0 normalidade. At\u00e9 o momento, foram registradas mais de 1,1 milh\u00e3o de casos e mais de 68 mil mortes em decorr\u00eancia da Covid-19 no pa\u00eds, segundo dados da Universidade Johns Hopkins.<\/p>\n\n\n\n<p>A Casa Branca minimizou o vazamento dos dados, afirmando se tratar de um documento interno que n\u00e3o havia sido coordenado com outras autoridades e que ainda n\u00e3o sido submetido \u00e0 equipe do presidente\u00a0<a href=\"https:\/\/g1.globo.com\/tudo-sobre\/donald-trump\/\">Donald Trump<\/a>.<\/p>\n\n\n\n<p>No domingo (3), o presidente admitiu que o n\u00famero de v\u00edtimas da doen\u00e7a no pa\u00eds pode vir a passar de 100 mil. Ele, por\u00e9m havia inicialmente previsto em torno de 60 mil a 70 mil mortes.<\/p>\n\n\n\n<p>Segundo as reportagens do New York Times e do Washington Post, os c\u00e1lculos do CDC se baseiam no fato de que alguns estados e distritos n\u00e3o tomaram medidas en\u00e9rgicas para conter a dissemina\u00e7\u00e3o do Sars-Cov-2, ou relaxaram precocemente as medidas de preven\u00e7\u00e3o. Nos EUA, a responsabilidade pelas medidas de combate \u00e0 doen\u00e7a est\u00e3o, em grande parte, a cargo dos governos estaduais e das autoridades locais.<\/p>\n\n\n\n<p>O pr\u00f3prio Trump vem pressionando pelo retorno \u00e0 normalidade e pela reabertura da economia do pa\u00eds, com vistas \u00e0s elei\u00e7\u00f5es presidenciais em novembro.<\/p>\n\n\n\n<p>Paralelamente aos dados do CDC, outro modelo estat\u00edstico mencionado como refer\u00eancia pela Casa Branca fez uma revis\u00e3o de suas estimativas, afirmando que o n\u00famero de \u00f3bitos pode dobrar nos EUA nos pr\u00f3ximos meses, um progn\u00f3stico bem mais sombrio do que o quem vem sendo apontado pela equipe de Trump designada para lidar com a crise.<\/p>\n\n\n\n<p>O Instituto de M\u00e9trica e Avalia\u00e7\u00e3o de Sa\u00fade (IHME) da Universidade de Washington estima que 135 mil americanos devem perder suas vidas at\u00e9 o in\u00edcio de agosto em raz\u00e3o do relaxamento das medidas de preven\u00e7\u00e3o e do aumento da movimenta\u00e7\u00e3o de pessoas em 31 estados at\u00e9 o dia 11 de maio. O modelo do instituto, utilizado pelo governo, associa o aumento nas mortes ao maior contato entre as pessoas, o que possibilitaria a transmiss\u00e3o do novo coronav\u00edrus.<\/p>\n\n\n\n<p>Com G1PB<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um documento interno do Centro de Controle de Doen\u00e7as (CDC) nos&nbsp;Estados Unidos&nbsp;vazado \u00e0 imprensa revela previs\u00f5es de uma piora acentuada na crise gerada pelo novo&hellip; <\/p>\n","protected":false},"author":1,"featured_media":167577,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[50],"tags":[],"class_list":["post-167573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/167573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=167573"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/167573\/revisions"}],"predecessor-version":[{"id":167581,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/167573\/revisions\/167581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/167577"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=167573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=167573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=167573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}