{"id":17116,"date":"2017-04-04T12:28:37","date_gmt":"2017-04-04T15:28:37","guid":{"rendered":"http:\/\/caririemacao.com\/1\/?p=17116"},"modified":"2017-04-04T12:28:37","modified_gmt":"2017-04-04T15:28:37","slug":"prefeitura-de-monteiro-lanca-oficialmente-novas-atividades-do-grupo-de-idosos","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2017\/04\/04\/prefeitura-de-monteiro-lanca-oficialmente-novas-atividades-do-grupo-de-idosos\/","title":{"rendered":"Prefeitura de Monteiro lan\u00e7a oficialmente novas atividades do grupo de idosos"},"content":{"rendered":"<p>A Prefeitura de Monteiro, atrav\u00e9s da Secretaria de Desenvolvimento Social, lan\u00e7ou oficialmente na manh\u00e3 desta segunda-feira (2), o calend\u00e1rio de atividades do grupo da melhor idade do Servi\u00e7o de Conviv\u00eancia e Fortalecimento de V\u00ednculos.<\/p>\n<p>O pr\u00e9dio onde funciona o SCFV, que fica por tr\u00e1s da subesta\u00e7\u00e3o de energia, passou por uma ampla reforma, inclusive com melhorias na cozinha, salas de aula, e outros ambientes. Na ocasi\u00e3o foi inaugurada a nova sala de v\u00eddeo, que servir\u00e1 tamb\u00e9m como sala para palestras educativas e sociais.<\/p>\n<p>\u201cAs atividades do grupo de idosos passar\u00e3o a ser realizadas sempre \u00e0s segundas-feiras, e as quintas-feiras ficar\u00e3o reservadas para o planejamento dos monitores e a entrega de frutas e verduras que acontece a cada 15 dias\u201d, explicou a secret\u00e1ria Rosa Aleixo.<\/p>\n<p>Hoje o SCFV atende no grupo de idosos cerca de 130 homens e mulheres que participam de atividades de recrea\u00e7\u00e3o, m\u00fasica, dan\u00e7a, artes, cultura e s\u00e3o prioritariamente inclu\u00eddos e inseridos no calend\u00e1rio de comemora\u00e7\u00f5es e eventos anuais.<\/p>\n<p>Al\u00e9m da Secretaria de Desenvolvimento Social Rosa Aleixo, marcaram presen\u00e7a no evento as secret\u00e1rias executivas de Sa\u00fade Viviane Ferreira, e de Desenvolvimento Social Silv\u00e2nia Mayer.<\/p>\n<p>Na ocasi\u00e3o foi servido um caf\u00e9 da manh\u00e3, e houve tamb\u00e9m apresenta\u00e7\u00f5es de forr\u00f3 p\u00e9 de serra e outras m\u00fasicas regionais.<\/p>\n<p><strong><span style=\"font-family: 'Georgia','serif'; color: #333333;\">CARIRI EM A\u00c7\u00c3O\u00a0<\/span><\/strong><\/p>\n<p style=\"font-variant-ligatures: normal; font-variant-caps: normal; orphans: 2; text-align: start; widows: 2; -webkit-text-stroke-width: 0px; text-decoration-style: initial; text-decoration-color: initial; word-spacing: 0px;\"><span style=\"font-family: 'Georgia','serif'; color: #333333;\">Com SECOM-PMM\/Foto: Reprodu\u00e7\u00e3o<\/span><\/p>\n<p style=\"font-variant-ligatures: normal; font-variant-caps: normal; orphans: 2; text-align: start; widows: 2; -webkit-text-stroke-width: 0px; text-decoration-style: initial; text-decoration-color: initial; word-spacing: 0px;\"><strong><span style=\"font-family: 'Georgia','serif'; color: #333333;\">Leia mais not\u00edcias em\u00a0<\/span><\/strong><span><a href=\"http:\/\/www.caririemacao.com\/\"><strong><span>caririemacao.com<\/span><\/strong><\/a><strong><span>, siga nossa p\u00e1gina no<\/span><\/strong><a href=\"https:\/\/www.facebook.com\/CaririEmAcao\/\"><strong><span>\u00a0Facebook<\/span><\/strong><\/a><strong><span>\u00a0e\u00a0<a href=\"https:\/\/www.instagram.com\/cariri_em_acao\/?hl=pt-br\">Instagram<\/a>\u00a0veja nossas mat\u00e9rias e fotos. Voc\u00ea tamb\u00e9m pode enviar informa\u00e7\u00f5es \u00e0 Reda\u00e7\u00e3o do Portal Cariri em A\u00e7\u00e3o pelo WhatsApp (83) 9 9634.5791, (83) 9 9601-1162 ou (83) 9 994189.<\/span><\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Monteiro, atrav\u00e9s da Secretaria de Desenvolvimento Social, lan\u00e7ou oficialmente na manh\u00e3 desta segunda-feira (2), o calend\u00e1rio de atividades do grupo da melhor&hellip; <\/p>\n","protected":false},"author":2,"featured_media":17119,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-17116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/17116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=17116"}],"version-history":[{"count":0,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/17116\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/17119"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=17116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=17116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=17116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}