{"id":17167,"date":"2017-04-04T14:54:24","date_gmt":"2017-04-04T17:54:24","guid":{"rendered":"http:\/\/caririemacao.com\/1\/?p=17167"},"modified":"2017-04-04T14:54:24","modified_gmt":"2017-04-04T17:54:24","slug":"lula-diz-defender-eleicao-direta-em-caso-de-cassacao-de-dilmatemer","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2017\/04\/04\/lula-diz-defender-eleicao-direta-em-caso-de-cassacao-de-dilmatemer\/","title":{"rendered":"Lula diz defender elei\u00e7\u00e3o direta em caso de cassa\u00e7\u00e3o de Dilma\/Temer"},"content":{"rendered":"<p>O ex-presidente Luiz In\u00e1cio Lula da Silva disse nesta ter\u00e7a-feira concordar com o ex-presidente Fernando Henrique Cardoso, de que uma elei\u00e7\u00e3o indireta \u00e9 \u201cmais confus\u00e3o\u201d para o Brasil. Em entrevista a uma r\u00e1dio de Pernambuco, transmitida na p\u00e1gina de Lula em rede social, o ex-presidente, falando hipoteticamente sobre uma eventual cassa\u00e7\u00e3o da chapa Dilma-Temer, disse acreditar que \u201cse fosse convocada elei\u00e7\u00e3o direta o mais rapidamente poss\u00edvel, seria o tanto quanto melhor para o Brasil\u201d.<\/p>\n<p>\u2014 Concordo, se for para antecipar elei\u00e7\u00e3o eu concordo \u2014 disse Lula, quando indagado sobre declara\u00e7\u00f5es de Fernando Henrique Cardoso na v\u00e9spera de que \u201cse Congresso vai eleger uma pessoa, que eu n\u00e3o sei quem \u00e9, para ser presidente por um ano no momento da elei\u00e7\u00e3o? \u00c9 mais confus\u00e3o\u201d.<\/p>\n<p>Lula se disse convencido, no entanto, da inoc\u00eancia de Dilma Rousseff.<\/p>\n<p>\u2014 Mas vamos aguardar o julgamento (&#8230;). At\u00e9 porque a Justi\u00e7a Eleitoral, que vai julgar, j\u00e1 aprovou as as contas da Dillma e do Temer.<\/p>\n<p>Na opini\u00e3o do ex-presidente, o PSDB (autor da a\u00e7\u00e3o no TSE) \u201ctentou fazer um carnaval ap\u00f3s perder a elei\u00e7\u00e3o\u201d.<\/p>\n<p>\u2014 Mas eu acho que n\u00e3o tem procedimento essa queixa do PSDB, mas devemos esperar o resultado \u2014 declarou Lula, afirmando n\u00e3o ter ponto de vista formado sobre a quest\u00e3o por n\u00e3o conhecer os autos do processo. \u2014 Portanto espero que os ministros que v\u00e3o julgar isso tomem a decis\u00e3o melhor interessante para se fazer justi\u00e7a no Brasil.<\/p>\n<p>Sobre a realiza\u00e7\u00e3o de eventuais elei\u00e7\u00f5es diretas, Lula disse que \u00e9 preciso esperar, mas que tem gente com \u201cmuito menos possibilidade\u201d do que ele que j\u00e1 \u00e9 candidato.<\/p>\n<p>\u2014 Eu estou na expectativa, eu ando muito preocupado com o Brasil \u2014 declarou Lula, afirmando que o governo atual n\u00e3o \u201csabe o que fazer\u201d com o Brasil, que, segundo Lula, est\u00e1 numa situa\u00e7\u00e3o pior do que antes do impeachment.<\/p>\n<p><strong>EFEITO DORIA<\/strong><\/p>\n<p>Indagado sobre se uma eventual candidatura do prefeito de S\u00e3o Paulo, Jo\u00e3o Doria (PSDB), o assusta, Lula disse que acha \u201cdesagrad\u00e1vel falar sobre uma pessoa que sequer \u00e9 conhecida no Brasil; uma pessoa que sequer est\u00e1 fazendo seu dever como prefeito da cidade de S\u00e3o Paulo\u201d.<\/p>\n<p>\u2014 H\u00e1 tempos ele vem me provocando na tentativa de que eu aceite o debate para ele poder se projetar nacionalmente. Ele que fa\u00e7a campanha com o partido dele, que v\u00e1 pro PMDB. Eu tenho outtras preocupa\u00e7\u00f5es (&#8230;) Acho que o Brasil precisa voltar a crescer.<\/p>\n<p>Lula diz que \u00e9 preciso aguardar sobre uma eventual candidatura sua \u00e0 Presid\u00eancia, mas especulou, durante a entrevista, sobre uma poss\u00edvel volta sua \u00e0 Presid\u00eancia. Disse n\u00e3o saber se teria for\u00e7a no Congresso para reverter quest\u00f5es como a terceiriza\u00e7\u00e3o e a reforma da previd\u00eancia.<\/p>\n<p>\u2014 Eu tenho experi\u00eancia de vida, n\u00e3o estou teorizando, Esse pa\u00eds s\u00f3 tem jeito nesse instante (&#8230;.) se colocarmos o pobre de volta ao or\u00e7amento da Uni\u00e3o (&#8230;). Eu tenho consci\u00eancia do que \u00e9 preciso fazer nesse pa\u00eds para a gente voltar a crescer.<\/p>\n<p class=\"autor-not\"><strong><span style=\"font-family: 'Georgia','serif'; color: #333333;\">CARIRI EM A\u00c7\u00c3O\u00a0<\/span><\/strong><\/p>\n<p style=\"font-variant-ligatures: normal; font-variant-caps: normal; orphans: 2; text-align: start; widows: 2; -webkit-text-stroke-width: 0px; text-decoration-style: initial; text-decoration-color: initial; word-spacing: 0px;\"><span style=\"font-family: 'Georgia','serif'; color: #333333;\">Com O Globo\/Foto: Reprodu\u00e7\u00e3o Google\u00a0<\/span><\/p>\n<p style=\"font-variant-ligatures: normal; font-variant-caps: normal; orphans: 2; text-align: start; widows: 2; -webkit-text-stroke-width: 0px; text-decoration-style: initial; text-decoration-color: initial; word-spacing: 0px;\"><strong><span style=\"font-family: 'Georgia','serif'; color: #333333;\">Leia mais not\u00edcias em\u00a0<\/span><\/strong><span><a href=\"http:\/\/www.caririemacao.com\/\"><strong><span>caririemacao.com<\/span><\/strong><\/a><strong><span>, siga nossa p\u00e1gina no<\/span><\/strong><a href=\"https:\/\/www.facebook.com\/CaririEmAcao\/\"><strong><span>\u00a0Facebook<\/span><\/strong><\/a><strong><span>\u00a0e\u00a0<a href=\"https:\/\/www.instagram.com\/cariri_em_acao\/?hl=pt-br\">Instagram<\/a>\u00a0veja nossas mat\u00e9rias e fotos. Voc\u00ea tamb\u00e9m pode enviar informa\u00e7\u00f5es \u00e0 Reda\u00e7\u00e3o do Portal Cariri em A\u00e7\u00e3o pelo WhatsApp (83) 9 9634.5791, (83) 9 9601-1162 ou (83) 9 994189.<\/span><\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ex-presidente Luiz In\u00e1cio Lula da Silva disse nesta ter\u00e7a-feira concordar com o ex-presidente Fernando Henrique Cardoso, de que uma elei\u00e7\u00e3o indireta \u00e9 \u201cmais confus\u00e3o\u201d&hellip; <\/p>\n","protected":false},"author":2,"featured_media":11047,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[11],"tags":[],"class_list":["post-17167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/17167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=17167"}],"version-history":[{"count":0,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/17167\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/11047"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=17167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=17167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=17167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}