{"id":172128,"date":"2020-05-30T05:55:14","date_gmt":"2020-05-30T08:55:14","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=172128"},"modified":"2020-05-30T05:55:14","modified_gmt":"2020-05-30T08:55:14","slug":"auxilio-emergencial-caixa-comeca-a-liberar-saques-e-transferencias-da-2a-parcela-depositada-em-poupanca-digital","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2020\/05\/30\/auxilio-emergencial-caixa-comeca-a-liberar-saques-e-transferencias-da-2a-parcela-depositada-em-poupanca-digital\/","title":{"rendered":"Aux\u00edlio Emergencial: Caixa come\u00e7a a liberar saques e transfer\u00eancias da 2\u00aa parcela depositada em poupan\u00e7a digital"},"content":{"rendered":"\n<p>Aux\u00edlio Emergencial: Caixa come\u00e7a a liberar saques e transfer\u00eancias da 2\u00aa parcela depositada em poupan\u00e7a digital<\/p>\n\n\n\n<p>As\u00a0libera\u00e7\u00f5es v\u00e3o seguir um cronograma ligado ao m\u00eas de nascimento do trabalhador. Os primeiros a receber ser\u00e3o 2,6 milh\u00f5es de benefici\u00e1rios nascidos em janeiro. At\u00e9 a data de libera\u00e7\u00e3o, os recursos j\u00e1 depositados nas poupan\u00e7as podem ser usados apenas para pagamento de contas, de boletos e compras por meio do cart\u00e3o de d\u00e9bito virtual.<\/p>\n\n\n\n<p>Para os trabalhadores que\u00a0receberam a primeira parcela do benef\u00edcio em outra conta, os recursos depositados na poupan\u00e7a digital ser\u00e3o transferidos automaticamente tamb\u00e9m na data de libera\u00e7\u00e3o dos saques e transfer\u00eancias. Com isso, esses benefici\u00e1rios ter\u00e3o que procurar os bancos em que t\u00eam conta caso queiram sacar o dinheiro.<\/p>\n\n\n\n<p>Veja o calend\u00e1rio para libera\u00e7\u00e3o de saques e transfer\u00eancias da poupan\u00e7a social digital:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/s2.glbimg.com\/DwT_mVVdGc_cTMutN5P0x8uE2UE=\/0x0:1340x1180\/984x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2020\/1\/S\/2o4dfyRhCtGJXHTi9iyw\/ntwig-saque-e-transfer-ncia-da-poupan-a-social-nbsp-.png\" alt=\"Aux\u00edlio Emergencial segunda parcela - saque e transfer\u00eancia da poupan\u00e7a social \u2014 Foto: Economia G1\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/figure>\n\n\n\n<p>Aux\u00edlio Emergencial segunda parcela &#8211; saque e transfer\u00eancia da poupan\u00e7a social \u2014 Foto: Economia G1<\/p>\n\n\n\n<p>Para pagar o beneficio, a Caixa vai abrir 2.213 ag\u00eancias em todo o pa\u00eds das 8h \u00e0s 12h para atendimento exclusivo do Aux\u00edlio Emergencial. A lista das ag\u00eancias pode ser verificada&nbsp;<a href=\"http:\/\/www.caixa.gov.br\/Downloads\/atendimento\/CAIXA_ABERTURA_AGENCIAS_SABADO_30_MAIO_2020.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">neste link<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pagamentos<\/h2>\n\n\n\n<p>A Caixa concluiu esta semana os pagamentos da segunda parcela do Aux\u00edlio Emergencial para os benefici\u00e1rios que receberam a primeira at\u00e9 30 de abril. O calend\u00e1rio da terceira parcela, que estava prevista para maio, continua sem defini\u00e7\u00e3o.<\/p>\n\n\n\n<p>Um&nbsp;<strong>segundo grupo de aprovados recebeu a primeira parcela tamb\u00e9m esta semana<\/strong>&nbsp;&#8211; para estes, a data de pagamento da segunda n\u00e3o est\u00e1 confirmada mas, segundo o presidente da Caixa, o benef\u00edcio deve ser liberado em um m\u00eas.<\/p>\n\n\n\n<p>At\u00e9 sexta-feira (29),&nbsp;<strong>ainda havia 10,6 milh\u00f5es de pedidos de Aux\u00edlio Emergencial aguardando an\u00e1lise<\/strong>, segundo a Caixa. N\u00e3o h\u00e1 previs\u00e3o de quando essas pessoas ir\u00e3o receber o benef\u00edcio.<\/p>\n\n\n\n<p>Os trabalhadores podem consultar a situa\u00e7\u00e3o do benef\u00edcio pelo aplicativo do aux\u00edlio emergencial ou pelo site&nbsp;<a href=\"http:\/\/auxilio.caixa.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">auxilio.caixa.gov.br<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Balan\u00e7o<\/h2>\n\n\n\n<p>At\u00e9 a sexta-feira, a Caixa Econ\u00f4mica Federal (CEF) j\u00e1 havia pagado R$ 76,6 bilh\u00f5es em Aux\u00edlio Emergencial, para 58,6 milh\u00f5es de benefici\u00e1rios. Ao todo, foram 108,5 milh\u00f5es de pagamentos, uma vez que muitos benefici\u00e1rios j\u00e1 come\u00e7aram a receber a segunda parcela de R$ 600.<\/p>\n\n\n\n<p>Ainda segundo a Caixa, foram processados pela Dataprev 101,2 milh\u00f5es de cadastros, dos quais 59 milh\u00f5es foram considerados eleg\u00edveis &#8211; destes, 19,2 milh\u00f5es de benefici\u00e1rios do Bolsa Fam\u00edlia, 10,5 milh\u00f5es do Cadastro \u00danico e 29,3 milh\u00f5es de trabalhadores que se inscreveram por meio do site e do aplicativo do programa.<\/p>\n\n\n\n<p>Outros 5,2 milh\u00f5es de cadastros feitos pelo app e site est\u00e3o em rean\u00e1lise, e 5,4 milh\u00f5es ainda passam pela primeira an\u00e1lise.<\/p>\n\n\n\n<p>Com G1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aux\u00edlio Emergencial: Caixa come\u00e7a a liberar saques e transfer\u00eancias da 2\u00aa parcela depositada em poupan\u00e7a digital As\u00a0libera\u00e7\u00f5es v\u00e3o seguir um cronograma ligado ao m\u00eas de&hellip; <\/p>\n","protected":false},"author":1,"featured_media":172129,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[50,2],"tags":[],"class_list":["post-172128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-geral"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/172128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=172128"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/172128\/revisions"}],"predecessor-version":[{"id":172130,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/172128\/revisions\/172130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/172129"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=172128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=172128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=172128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}