{"id":173597,"date":"2020-06-10T06:47:43","date_gmt":"2020-06-10T09:47:43","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=173597"},"modified":"2020-06-10T06:47:43","modified_gmt":"2020-06-10T09:47:43","slug":"82-dos-casos-de-covid-19-em-campina-grande-estao-recuperados-informa-secretaria-de-saude","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2020\/06\/10\/82-dos-casos-de-covid-19-em-campina-grande-estao-recuperados-informa-secretaria-de-saude\/","title":{"rendered":"82% dos casos de Covid-19 em Campina Grande est\u00e3o recuperados, informa Secretaria de Sa\u00fade"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\"><\/h1>\n\n\n\n<p>A Prefeitura de Campina Grande, comemorou nesta ter\u00e7a-feira (9), o n\u00famero de 2176 pacientes recuperados da Covid-19 \u2013 doen\u00e7a causada pelo novo Coronav\u00edrus -, representando mais de 82% dos casos confirmados: 2650. Os dados s\u00e3o do boletim epidemiol\u00f3gico divulgado pela Secretaria Municipal de Sa\u00fade.<\/p>\n\n\n\n<p>A Secretaria ainda informa que 59 \u00f3bitos foram notificados, 1143 casos s\u00e3o classificados como suspeitos e o n\u00famero de testes negativos chega a 2675. A taxa de ocupa\u00e7\u00e3o de leitos da rede municipal de Sa\u00fade \u00e9 de 63% em UTI e 54% em enfermaria.<\/p>\n\n\n\n<p><strong>RECUPERADOS<\/strong><\/p>\n\n\n\n<p>O n\u00famero de recuperados apresentou um crescimento consider\u00e1vel nos \u00faltimos dias, mas sem confirma\u00e7\u00e3o oficial para o feito. Suspeita-se que o uso da cloroquina tenha ajudado no tratamento de pacientes com Covid-19.<\/p>\n\n\n\n<p>O prefeito Romero Rodrigues (PSD) adotou o medicamento em meio a questionamentos sobre sua efic\u00e1cia. A Prefeitura por meio da Secretaria de Sa\u00fade prescreve a cloroquina juntamente com outras drogas no atendimento inicial na Unidade Pronto Antedimento (UPA) do Alto Branco e no Hospital Pedro I, com base em um protocolo elaborado pelas autoridades de Sa\u00fade locais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Campina Grande, comemorou nesta ter\u00e7a-feira (9), o n\u00famero de 2176 pacientes recuperados da Covid-19 \u2013 doen\u00e7a causada pelo novo Coronav\u00edrus -, representando&hellip; <\/p>\n","protected":false},"author":2,"featured_media":173598,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-173597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/173597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=173597"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/173597\/revisions"}],"predecessor-version":[{"id":173599,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/173597\/revisions\/173599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/173598"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=173597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=173597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=173597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}