{"id":173621,"date":"2020-06-10T09:58:25","date_gmt":"2020-06-10T12:58:25","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=173621"},"modified":"2020-06-10T09:58:25","modified_gmt":"2020-06-10T12:58:25","slug":"camara-de-vereadores-de-sume-aprova-projeto-que-suspende-parcelas-de-consignados-de-servidores-ativos-e-inativos-do-municipio","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2020\/06\/10\/camara-de-vereadores-de-sume-aprova-projeto-que-suspende-parcelas-de-consignados-de-servidores-ativos-e-inativos-do-municipio\/","title":{"rendered":"C\u00e2mara de Vereadores de Sum\u00e9 aprova projeto que suspende parcelas de consignados de servidores ativos e inativos do munic\u00edpio"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\"><\/h1>\n\n\n\n<p>A C\u00e2mara de Vereadores de Sum\u00e9 se reuniu nesta ter\u00e7a-feira, na oportunidade foi aprovado o projeto de lei de autoria do Poder Executivo, que suspende a cobran\u00e7a dos empr\u00e9stimos consignados contra\u00eddos pelos servidores p\u00fablicos, ativos e inativos, do Munic\u00edpio de Sum\u00e9, incluindo os servidores do Legislativo.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"http:\/\/noticiasemdestaque.com\/cd\/wp-content\/uploads\/2020\/06\/e5ca009e-387b-4be4-92d3-816f7649c10b.jpg\"><img decoding=\"async\" data-src=\"http:\/\/noticiasemdestaque.com\/cd\/wp-content\/uploads\/2020\/06\/e5ca009e-387b-4be4-92d3-816f7649c10b.jpg\" alt=\"\" class=\"wp-image-25286 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure><\/div>\n\n\n\n<p>Na ocasi\u00e3o foram aprovadas tr\u00eas emendas ao projeto, uma de autoria do vereador&nbsp;<a href=\"https:\/\/www.facebook.com\/antoniocarlos.sarmento?__tn__=K-R-R&amp;eid=ARDy2HkUFnRFBAvPkQ9f7aISXpAorqx7_0BHJOmyvLd-FybztFjQR8HBxqJFWYAxtnVX-VwRNdHZxKlt&amp;fref=mentions&amp;__xts__%5B0%5D=68.ARDK4gQU5G0mmLsvEEFRnt65jm6fS24ltJzned5l0_fq872S6eNP9L7DnB8Tek79XfsvR2g46TwOuwyu0DW_6GhCVh8PZSSwNFLd09e2s8Xn3GiaqSQaOFv5hoZV97MxoYxJyF8Yzl5Gd2EVt7-slBJA2T9brBd15NpN0SzdkWdueEKLkpSCt8ZysEbGLKYXgaA_geHokdrIiXQRV34tZwe498QbLjVd6Awj-g2QNOHyRp3faj2Sj6DARXZ014_1CyMM-kivFOd_KNdTNyEuCfr4gkvZbgPbQwl4Cxq1OyLPjjg2ALA6kJhzpNcFySJOkBSh\">Antonio Carlos Sarmento<\/a>&nbsp;autor da indica\u00e7\u00e3o do PL, que aumenta de 120 para 180 dias (seis meses), o prazo de suspens\u00e3o das parcelas.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"http:\/\/noticiasemdestaque.com\/cd\/wp-content\/uploads\/2020\/06\/e96503be-ef8d-4e5f-a751-f6169c4117fb.jpg\"><img decoding=\"async\" data-src=\"http:\/\/noticiasemdestaque.com\/cd\/wp-content\/uploads\/2020\/06\/e96503be-ef8d-4e5f-a751-f6169c4117fb.jpg\" alt=\"\" class=\"wp-image-25287 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure><\/div>\n\n\n\n<p>Foi aprovada a emenda do vereador&nbsp;<a href=\"https:\/\/www.facebook.com\/profile.php?id=100012282723868&amp;__tn__=K-R-R&amp;eid=ARBHZdN4b8gYZFn9F3rLgvlgmXBzegmnBxS-YgvrfwpAoRw-FIFSV4WgLfmH0W49081EMqs5A3_gjg_7&amp;fref=mentions&amp;__xts__%5B0%5D=68.ARDK4gQU5G0mmLsvEEFRnt65jm6fS24ltJzned5l0_fq872S6eNP9L7DnB8Tek79XfsvR2g46TwOuwyu0DW_6GhCVh8PZSSwNFLd09e2s8Xn3GiaqSQaOFv5hoZV97MxoYxJyF8Yzl5Gd2EVt7-slBJA2T9brBd15NpN0SzdkWdueEKLkpSCt8ZysEbGLKYXgaA_geHokdrIiXQRV34tZwe498QbLjVd6Awj-g2QNOHyRp3faj2Sj6DARXZ014_1CyMM-kivFOd_KNdTNyEuCfr4gkvZbgPbQwl4Cxq1OyLPjjg2ALA6kJhzpNcFySJOkBSh\">Ver Jos\u00e9 Ant\u00f4nio<\/a>, que torna autom\u00e1tico o beneficio, o servidor que n\u00e3o desejar que haja a suspens\u00e3o do seu empr\u00e9stimo consignado dever\u00e1 fazer requerimento direcionado \u00e0 administra\u00e7\u00e3o municipal.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"http:\/\/noticiasemdestaque.com\/cd\/wp-content\/uploads\/2020\/06\/309fb5e5-18a6-4462-9470-adf46115f6ae.jpg\"><img decoding=\"async\" data-src=\"http:\/\/noticiasemdestaque.com\/cd\/wp-content\/uploads\/2020\/06\/309fb5e5-18a6-4462-9470-adf46115f6ae.jpg\" alt=\"\" class=\"wp-image-25284 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure><\/div>\n\n\n\n<p>Foi aprovada ainda, uma emenda do vereador&nbsp;<a href=\"https:\/\/www.facebook.com\/daniel.lela.9?__tn__=K-R-R&amp;eid=ARBru8RXnDOaER752rIlpQHrJtHKE1MfT6MdJqpHXk1yKS1oRlemWTo1E5MWmfIdEHom85YxxEYXi0Fk&amp;fref=mentions&amp;__xts__%5B0%5D=68.ARDK4gQU5G0mmLsvEEFRnt65jm6fS24ltJzned5l0_fq872S6eNP9L7DnB8Tek79XfsvR2g46TwOuwyu0DW_6GhCVh8PZSSwNFLd09e2s8Xn3GiaqSQaOFv5hoZV97MxoYxJyF8Yzl5Gd2EVt7-slBJA2T9brBd15NpN0SzdkWdueEKLkpSCt8ZysEbGLKYXgaA_geHokdrIiXQRV34tZwe498QbLjVd6Awj-g2QNOHyRp3faj2Sj6DARXZ014_1CyMM-kivFOd_KNdTNyEuCfr4gkvZbgPbQwl4Cxq1OyLPjjg2ALA6kJhzpNcFySJOkBSh\">Daniel L\u00eala<\/a>, que pro\u00edbe a institui\u00e7\u00e3o financeira que concedeu o empr\u00e9stimo incluir o nome do servidor publico em qualquer \u00f3rg\u00e3o de restri\u00e7\u00e3o de cr\u00e9dito em decorr\u00eancia da suspens\u00e3o prevista na lei.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"http:\/\/noticiasemdestaque.com\/cd\/wp-content\/uploads\/2020\/06\/685ce3e2-ed50-43a6-9d0f-a04a0177dce5.jpg\"><img decoding=\"async\" data-src=\"http:\/\/noticiasemdestaque.com\/cd\/wp-content\/uploads\/2020\/06\/685ce3e2-ed50-43a6-9d0f-a04a0177dce5.jpg\" alt=\"\" class=\"wp-image-25285 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure><\/div>\n\n\n\n<p>O presidente da C\u00e2mara de Vereadores, Bomba, parabenizou todos os vereadores pela aprova\u00e7\u00e3o do projeto de lei e ressaltou que a a\u00e7\u00e3o tr\u00e1s um m\u00ednimo de seguran\u00e7a financeira \u00e0 popula\u00e7\u00e3o benefici\u00e1ria, neste momento de pandemia do coronav\u00edrus.<\/p>\n\n\n\n<p>Ascom\/C\u00e2mara<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara de Vereadores de Sum\u00e9 se reuniu nesta ter\u00e7a-feira, na oportunidade foi aprovado o projeto de lei de autoria do Poder Executivo, que suspende&hellip; <\/p>\n","protected":false},"author":2,"featured_media":173622,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-173621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/173621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=173621"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/173621\/revisions"}],"predecessor-version":[{"id":173623,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/173621\/revisions\/173623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/173622"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=173621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=173621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=173621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}