{"id":177644,"date":"2020-07-07T06:44:58","date_gmt":"2020-07-07T09:44:58","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=177644"},"modified":"2020-07-07T06:44:58","modified_gmt":"2020-07-07T09:44:58","slug":"bolsonaro-anuncia-sancao-de-mp-sobre-reducao-de-jornada-e-salario-na-pandemia","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2020\/07\/07\/bolsonaro-anuncia-sancao-de-mp-sobre-reducao-de-jornada-e-salario-na-pandemia\/","title":{"rendered":"Bolsonaro anuncia san\u00e7\u00e3o de MP sobre redu\u00e7\u00e3o de jornada e sal\u00e1rio na pandemia"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\"><\/h1>\n\n\n\n<p>O presidente Jair Bolsonaro anunciou nesta segunda-feira (6) em uma rede social a san\u00e7\u00e3o da medida provis\u00f3ria (MP) que permite a redu\u00e7\u00e3o da jornada de trabalho e do sal\u00e1rio em raz\u00e3o da pandemia do novo coronav\u00edrus.<\/p>\n\n\n\n<p>Bolsonaro n\u00e3o informou se houve vetos a trechos da proposta aprovada pelo Congresso Nacional. O texto foi aprovado pelo Senado em 16 de junho.<\/p>\n\n\n\n<p>&#8220;Sancionada hoje a Lei que instituiu o Programa Emergencial de Manuten\u00e7\u00e3o do Emprego e da Renda (MP-936). Todos os benef\u00edcios ser\u00e3o custeados com recursos da Uni\u00e3o, operacionalizado e pago pelo @MinEconomia diretamente ao empregado&#8221;, publicou Bolsonaro.<\/p>\n\n\n\n<p>A san\u00e7\u00e3o da medida, contudo, n\u00e3o havia sido publicada no &#8220;Di\u00e1rio Oficial da Uni\u00e3o&#8221; at\u00e9 a publica\u00e7\u00e3o desta reportagem.<\/p>\n\n\n\n<p>A medida provis\u00f3ria<\/p>\n\n\n\n<p>O objetivo da medida, editada pelo governo federal em abril, \u00e9 preservar empregos e renda neste per\u00edodo de pandemia, em que a crise econ\u00f4mica foi agravada.<\/p>\n\n\n\n<p>O texto permitiu \u00e0s empresas reduzirem a jornada de trabalho com a diminui\u00e7\u00e3o proporcional de sal\u00e1rios.<\/p>\n\n\n\n<p>A MP tamb\u00e9m autorizou a suspens\u00e3o tempor\u00e1ria de contratos de trabalho.<\/p>\n\n\n\n<p>As regras estavam em vig\u00eancia desde a edi\u00e7\u00e3o da medida. Com a aprova\u00e7\u00e3o da proposta pelo Congresso e com a san\u00e7\u00e3o presidencial, o texto da MP foi transformado em lei.<\/p>\n\n\n\n<p>De acordo com o Minist\u00e9rio da Economia, at\u00e9 o meados de junho, o chamado Programa Emergencial de Manuten\u00e7\u00e3o do Emprego e da Renda \u2013 criado pela MP \u2013 j\u00e1 preservou mais de 10 milh\u00f5es de postos de trabalho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente Jair Bolsonaro anunciou nesta segunda-feira (6) em uma rede social a san\u00e7\u00e3o da medida provis\u00f3ria (MP) que permite a redu\u00e7\u00e3o da jornada de&hellip; <\/p>\n","protected":false},"author":2,"featured_media":177645,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[11],"tags":[],"class_list":["post-177644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/177644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=177644"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/177644\/revisions"}],"predecessor-version":[{"id":177646,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/177644\/revisions\/177646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/177645"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=177644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=177644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=177644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}