{"id":177713,"date":"2020-07-07T13:47:49","date_gmt":"2020-07-07T16:47:49","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=177713"},"modified":"2020-07-07T13:47:49","modified_gmt":"2020-07-07T16:47:49","slug":"paraiba-disponibiliza-pacote-de-dados-gratuito-para-alunos-e-professores","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2020\/07\/07\/paraiba-disponibiliza-pacote-de-dados-gratuito-para-alunos-e-professores\/","title":{"rendered":"Para\u00edba disponibiliza pacote de dados gratuito para alunos e professores"},"content":{"rendered":"\n<p>O Governo da Para\u00edba, por meio da Secretaria de Estado da Educa\u00e7\u00e3o e da Ci\u00eancia e tecnologia, disponibilizou, nesta segunda-feira (6), para smartphones o Aplicativo Para\u00edba Educa, com pacote de dados gratuito para estudantes e professores da Rede Estadual de Ensino da Para\u00edba.<\/p>\n\n\n\n<p>O aplicativo faz parte das ferramentas de ensino remoto disponibilizadas durante a suspens\u00e3o das aulas presenciais por conta da pandemia do novo coronav\u00edrus.<\/p>\n\n\n\n<p>A Secretaria fez contrato com quatro operadoras de telefonia para garantir que os estudantes paraibanos acessem os conte\u00fados do Regime Especial de Ensino sem nenhum custo. No aplicativo \u00e9 disponibilizado o acesso \u00e0 sala de aula do Google Classroom, ao site Para\u00edba Educa e ao sistema Saber.<\/p>\n\n\n\n<p>O governador Jo\u00e3o Azev\u00eado comentou, durante o programa Fala Governador, que a Para\u00edba implementou v\u00e1rios processos tecnol\u00f3gicos para garantir que os alunos assistam aulas on-line durante a pandemia.<\/p>\n\n\n\n<p>\u201cMas n\u00f3s identificamos que chegamos a praticamente 90% da rede, por\u00e9m 10% dos estudantes n\u00e3o tinham acesso a todas as informa\u00e7\u00f5es. Ent\u00e3o, fizemos um conv\u00eanio com a TV Assembleia e j\u00e1 estamos disponibilizando aulas atrav\u00e9s da TV aberta, isso permite que os alunos possam assistir \u00e0s aulas. Esses investimentos que estamos fazendo na TV Para\u00edba Educa e no lan\u00e7amento do aplicativo Para\u00edba Educa permite uma maior intera\u00e7\u00e3o e eu fico extremamente feliz, porque isso faz com que a educa\u00e7\u00e3o chegue ao maior n\u00famero poss\u00edvel de estudantes\u201d, ressaltou.<\/p>\n\n\n\n<p>O governador adiantou que essa experi\u00eancia de ensino a dist\u00e2ncia implantada pelo Governo do Estado est\u00e1 sendo repassada para 150 munic\u00edpios da Para\u00edba. \u201cEstamos transferindo essa forma de fazer esse ensino on-line para que os munic\u00edpios possam tamb\u00e9m utiliz\u00e1-la no dia a dia de cada local\u201d, disse Jo\u00e3o Azev\u00eado.<\/p>\n\n\n\n<p>Para baixar o aplicativo Para\u00edba Educa basta ir \u00e0 Play Store em um smartphone com vers\u00e3o Android, digitar Para\u00edba Educa na busca, selecionar e baixar. Para acessar o conte\u00fado \u00e9 s\u00f3 usar o mesmo login e senha que alunos e professores cadastraram na plataforma Para\u00edba Educa. Para quem n\u00e3o tem nenhum acesso a smartphone ou computador, a escola est\u00e1 entregando as atividades impressas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Governo da Para\u00edba, por meio da Secretaria de Estado da Educa\u00e7\u00e3o e da Ci\u00eancia e tecnologia, disponibilizou, nesta segunda-feira (6), para smartphones o Aplicativo&hellip; <\/p>\n","protected":false},"author":2,"featured_media":177714,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[14],"tags":[],"class_list":["post-177713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/177713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=177713"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/177713\/revisions"}],"predecessor-version":[{"id":177715,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/177713\/revisions\/177715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/177714"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=177713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=177713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=177713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}