{"id":191745,"date":"2020-10-10T05:59:11","date_gmt":"2020-10-10T08:59:11","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=191745"},"modified":"2020-10-10T05:59:13","modified_gmt":"2020-10-10T08:59:13","slug":"paraiba-tem-24-agencias-do-inss-abertas-para-atendimento-quatro-delas-ofertam-pericias-medicas","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2020\/10\/10\/paraiba-tem-24-agencias-do-inss-abertas-para-atendimento-quatro-delas-ofertam-pericias-medicas\/","title":{"rendered":"Para\u00edba tem 24 ag\u00eancias do INSS abertas para atendimento; quatro delas ofertam per\u00edcias m\u00e9dicas"},"content":{"rendered":"\n<p>Ap\u00f3s quase um m\u00eas do retorno das atividades presenciais nas ag\u00eancias do Instituto Nacional do Seguro Social (INSS),&nbsp;nem todas as unidades est\u00e3o em funcionamento. Das 37 instaladas na Para\u00edba, atualmente 24 est\u00e3o abertas e&nbsp;o atendimento s\u00f3 \u00e9 feito por agendamento via aplicativo e Central telef\u00f5nica 135. Desse total, quatro atendem o servi\u00e7o de per\u00edcias m\u00e9dicas.&nbsp;<\/p>\n\n\n\n<p>O retorno presencial come\u00e7ou no dia 14 de setembro e apenas dez unidades reabriram ao p\u00fablico para&nbsp;atendimentos de cumprimentos de exig\u00eancia, reabilita\u00e7\u00e3o profissional e avalia\u00e7\u00e3o social. J\u00e1 para as per\u00edcias voltaram a ser feitas no dia 21 de setembro em apenas duas unidades do INSS na Para\u00edba. Hoje, quatro est\u00e3o com a oferta do servi\u00e7o. Em Jo\u00e3o Pessoas s\u00e3o duas ag\u00eancias: uma na&nbsp;Rua Paulino dos Santos Coelho, n\u00ba 30, no bairro Jardim Cidade Universit\u00e1ria; e a outra na Avenida Dom Pedro I, n\u00ba 215, t\u00e9rreo, no Centro.&nbsp;<\/p>\n\n\n\n<p>As outras duas ag\u00eancias ficam localizadas na Rua Sabiniano Maia, n\u00ba 903, no munic\u00edpio de Guarabira e a \u00faltima\u00a0na Avenida Dinam\u00e9rica Alves Correia, s\/n, na cidade de Campina Grande. Ao todo, na Para\u00edba, s\u00e3o\u00a037 ag\u00eancias do INSS, sendo 20 da Ger\u00eancia Executiva de Jo\u00e3o Pessoa e 17 na Ger\u00eancia Executiva de Campina Grande. Atualmente apenas 24 est\u00e3o em funcionamento.\u00a0O agendamento pode ser realizado pelo segurado por meio de tr\u00eas canais: site \u2018Meu INSS\u2019; aplicativo de celular \u2018Meu INSS\u2019 e pela Central telef\u00f4nica 135.<\/p>\n\n\n\n<p>Com ClickPb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s quase um m\u00eas do retorno das atividades presenciais nas ag\u00eancias do Instituto Nacional do Seguro Social (INSS),&nbsp;nem todas as unidades est\u00e3o em funcionamento. Das&hellip; <\/p>\n","protected":false},"author":6,"featured_media":191746,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[50,104],"tags":[],"class_list":["post-191745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-paraiba"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/191745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=191745"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/191745\/revisions"}],"predecessor-version":[{"id":191747,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/191745\/revisions\/191747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/191746"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=191745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=191745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=191745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}