{"id":191779,"date":"2020-10-10T08:24:12","date_gmt":"2020-10-10T11:24:12","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=191779"},"modified":"2020-10-10T08:24:14","modified_gmt":"2020-10-10T11:24:14","slug":"saiba-quais-sao-as-regras-para-a-selecao-de-beneficiarios-do-programa-parceiros-da-habitacao","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2020\/10\/10\/saiba-quais-sao-as-regras-para-a-selecao-de-beneficiarios-do-programa-parceiros-da-habitacao\/","title":{"rendered":"Saiba quais s\u00e3o as regras para a sele\u00e7\u00e3o de benefici\u00e1rios do Programa Parceiros da Habita\u00e7\u00e3o"},"content":{"rendered":"\n<p>O Di\u00e1rio Oficial do Estado deste s\u00e1bado (10) traz a regulamenta\u00e7\u00e3o do processos de sele\u00e7\u00e3o dos benefici\u00e1rios do Programa Parceiros da Habita\u00e7\u00e3o, voltado para a constru\u00e7\u00e3o de casa populares na Para\u00edba. De acordo com o documento, \u00e9 preciso estar cadastrado na Companhia Estadual de Habita\u00e7\u00e3o Popular (Cehap) para participar.<\/p>\n\n\n\n<p>Al\u00e9m do cadastro na Cehap, o interessado dever\u00e1 se inscrever tamb\u00e9m junto ao ente parceiro que far\u00e1 o empreendimento e que deve divulgar o cadastro.<\/p>\n\n\n\n<p>Ser\u00e3o verificadas as informa\u00e7\u00f5es cadastrais e financeiras dos candidatos inscritos nos seguintes sistemas: Cadmut (Cadastro Nacional de Mutu\u00e1rios); Cad\u00danico (Cadastro \u00danico para Programas Sociais); Arquivos de mutu\u00e1rios da Cehap.<\/p>\n\n\n\n<p>Com a pesquisa, candidato pode ser considerado compat\u00edvel; pendente, que s\u00e3o candidatos habilitados a participar do processo de sele\u00e7\u00e3o, por\u00e9m com restri\u00e7\u00e3o e necessidade de regulariza\u00e7\u00e3o de pend\u00eancia junto ao Cad\u00danico antes da assinatura do Termo de Colabora\u00e7\u00e3o; incompat\u00edvel, que s\u00e3o candidatos com renda familiar acima do limite do programa e\/ou impedidos por constarem no Cadmut e\/ ou nos arquivos de mutu\u00e1rios da Cehap.<\/p>\n\n\n\n<p>Ter\u00e3o prefer\u00eancia as fam\u00edlias chefiadas por mulheres; fam\u00edlias com pessoa(s) com defici\u00eancia; fam\u00edlias com filhos menores de 18 anos; fam\u00edlias monoparentais (constitu\u00edda somente pela m\u00e3e, somente pelo pai ou somente por um respons\u00e1vel legal por crian\u00e7as e adolescentes); fam\u00edlias com pessoa(s) idosa(s); fam\u00edlias em situa\u00e7\u00e3o de coabita\u00e7\u00e3o involunt\u00e1ria; fam\u00edlias com \u00f4nus excessivo de aluguel; fam\u00edlias residentes em \u00e1reas que ser\u00e3o removidas e\/ ou reassentadas por empreendimentos do programa.<\/p>\n\n\n\n<p>Al\u00e9m disso, no m\u00ednimo 3% das unidades habitacionais do empreendimento devem ser direcionadas para: pessoas idosas, na condi\u00e7\u00e3o de titulares do benef\u00edcio habitacional; pessoas com defici\u00eancia, ou fam\u00edlias de que fa\u00e7am parte pessoas com defici\u00eancia; e pessoas portadoras do v\u00edrus HIV \u2013 AIDS ou as fam\u00edlias que possuam em seu seio.<\/p>\n\n\n\n<p>Ap\u00f3s a finaliza\u00e7\u00e3o do processo de sele\u00e7\u00e3o, os candidatos aprovados participaram do sorteio das unidades habitacionais.<\/p>\n\n\n\n<p>com ClickPb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Di\u00e1rio Oficial do Estado deste s\u00e1bado (10) traz a regulamenta\u00e7\u00e3o do processos de sele\u00e7\u00e3o dos benefici\u00e1rios do Programa Parceiros da Habita\u00e7\u00e3o, voltado para a&hellip; <\/p>\n","protected":false},"author":6,"featured_media":191780,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[50],"tags":[],"class_list":["post-191779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/191779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=191779"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/191779\/revisions"}],"predecessor-version":[{"id":191781,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/191779\/revisions\/191781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/191780"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=191779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=191779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=191779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}