{"id":191785,"date":"2020-10-10T08:53:29","date_gmt":"2020-10-10T11:53:29","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=191785"},"modified":"2020-10-10T08:53:31","modified_gmt":"2020-10-10T11:53:31","slug":"sume-registra-06-casos-positivos-de-coronavirus-e-20-recuperados-nesta-quinta-feira-08","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2020\/10\/10\/sume-registra-06-casos-positivos-de-coronavirus-e-20-recuperados-nesta-quinta-feira-08\/","title":{"rendered":"Sum\u00e9 registra 06 casos positivos de coronav\u00edrus e 20 recuperados nesta quinta-feira, 08"},"content":{"rendered":"\n<p>A Secretaria Municipal de Sa\u00fade de Sum\u00e9 informa que foram registrados 06 casos positivos para o Coronav\u00edrus nesta quinta-feira, 08.<\/p>\n\n\n\n<p>1\u00ba caso: sexo masculino, 45 anos, sem comorbidades, Alto Alegre;<\/p>\n\n\n\n<p>2\u00ba caso: sexo masculino, 67 anos, com comorbidades, V\u00e1rzea Redonda;<\/p>\n\n\n\n<p>3\u00ba caso: sexo masculino, 20 anos, com comorbidades, Alto Alegre;<\/p>\n\n\n\n<p>4\u00ba caso: sexo feminino, 75 anos, com comorbidades, Conjunto Habitacional;<\/p>\n\n\n\n<p>5\u00ba caso: sexo masculino, 73 anos, com comorbidades, Frei Dami\u00e3o;<\/p>\n\n\n\n<p>6\u00ba caso: sexo masculino, 66 anos, com comorbidades, Santa Rosa.<\/p>\n\n\n\n<p>O munic\u00edpio registrou 20 casos recuperados nesta data.<\/p>\n\n\n\n<p>N\u00e3o se descuide, ao sair use m\u00e1scara, cubra bem o nariz e a boca, lave sempre as m\u00e3os e use \u00e1lcool em gel 70%.<\/p>\n\n\n\n<p>Ascom PMS<\/p>\n\n\n\n<p>Com Blog Teixeirinha da Prata<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria Municipal de Sa\u00fade de Sum\u00e9 informa que foram registrados 06 casos positivos para o Coronav\u00edrus nesta quinta-feira, 08. 1\u00ba caso: sexo masculino, 45&hellip; <\/p>\n","protected":false},"author":6,"featured_media":191786,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[50,16,95],"tags":[],"class_list":["post-191785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-saude","category-sume"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/191785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=191785"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/191785\/revisions"}],"predecessor-version":[{"id":191787,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/191785\/revisions\/191787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/191786"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=191785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=191785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=191785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}