{"id":198358,"date":"2020-12-12T06:44:21","date_gmt":"2020-12-12T09:44:21","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=198358"},"modified":"2020-12-12T06:44:23","modified_gmt":"2020-12-12T09:44:23","slug":"prefeitura-de-sume-paga-decimo-terceiro-salario-nesta-sexta-aos-servidores-municipais","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2020\/12\/12\/prefeitura-de-sume-paga-decimo-terceiro-salario-nesta-sexta-aos-servidores-municipais\/","title":{"rendered":"Prefeitura de Sum\u00e9 paga d\u00e9cimo terceiro sal\u00e1rio nesta sexta aos servidores municipais"},"content":{"rendered":"\n<p>A Prefeitura de Sum\u00e9 est\u00e1 pagando nesta sexta-feira, 11, o 13\u00b0 sal\u00e1rio dos seus servidores. O pagamento de dezembro se refere \u00e0 segunda parcela, tendo a primeira sido paga em junho.<\/p>\n\n\n\n<p>A segunda parcela do 13\u00ba corresponde ao valor de meio milh\u00e3o de reais que estar\u00e1 aquecendo a economia do munic\u00edpio neste per\u00edodo.<\/p>\n\n\n\n<p>O prefeito \u00c9den Duarte sempre zelou pelo pagamento em dia dos servidores municipais, fato que prevaleceu ao longo de seu mandato nos \u00faltimos quatro anos, que al\u00e9m da valoriza\u00e7\u00e3o do quadro de pessoal tamb\u00e9m \u00e9 fruto de uma boa gest\u00e3o fiscal e de equil\u00edbrio financeiro mantido por \u00c9den e sua equipe.<\/p>\n\n\n\n<p>De acordo com a Secretaria de Finan\u00e7as, o pagamento referente ao m\u00eas de dezembro tamb\u00e9m estar\u00e1 sendo depositado nas contas dos servidores dentro do m\u00eas.<\/p>\n\n\n\n<p>Vitrine do Cariri<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Sum\u00e9 est\u00e1 pagando nesta sexta-feira, 11, o 13\u00b0 sal\u00e1rio dos seus servidores. O pagamento de dezembro se refere \u00e0 segunda parcela, tendo&hellip; <\/p>\n","protected":false},"author":6,"featured_media":198359,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[50,95],"tags":[],"class_list":["post-198358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-sume"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/198358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=198358"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/198358\/revisions"}],"predecessor-version":[{"id":198360,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/198358\/revisions\/198360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/198359"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=198358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=198358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=198358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}