{"id":204933,"date":"2021-02-02T06:47:14","date_gmt":"2021-02-02T09:47:14","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=204933"},"modified":"2021-02-02T06:47:16","modified_gmt":"2021-02-02T09:47:16","slug":"apos-vitoria-de-pacheco-bolsonaro-destaca-voto-impresso-e-ministros-parabenizam-novo-presidente-do-senado","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2021\/02\/02\/apos-vitoria-de-pacheco-bolsonaro-destaca-voto-impresso-e-ministros-parabenizam-novo-presidente-do-senado\/","title":{"rendered":"Ap\u00f3s vit\u00f3ria de Pacheco, Bolsonaro destaca voto impresso e ministros parabenizam novo presidente do Senado"},"content":{"rendered":"\n<p>O presidente Jair Bolsonaro (sem partido) publicou nesta segunda-feira (1\u00ba) uma mensagem sobre a elei\u00e7\u00e3o de seu aliado, Rodrigo Pacheco (DEM-MG), para a presid\u00eancia do Senado Federal. No Facebook, Bolsonaro apenas destacou que a escolha de Pacheco, que venceu com 57 votos, ocorreu por vota\u00e7\u00e3o em c\u00e9dula de papel.<\/p>\n\n\n\n<p>&#8220;Em c\u00e9dula de papel, o Senado Federal elegeu o Senador Rodrigo Pacheco (57 votos de 81 poss\u00edveis) para presidir a Casa no bi\u00eanio 2021\/22&#8221;, escreveu.<\/p>\n\n\n\n<p>O presidente \u00e9 um defensor do voto impresso e j\u00e1 disse que, sem as c\u00e9dulas de papel nas elei\u00e7\u00f5es de 2022, &#8220;vamos ter problema pior que nos Estados Unidos&#8221; -numa refer\u00eancia \u00e0 invas\u00e3o do Capit\u00f3lio em Washington por partid\u00e1rios do ex-presidente Donald Trump.<\/p>\n\n\n\n<p>Pacheco foi o nome apoiado por Bolsonaro e venceu a disputa contra a senadora Simone Tebet (MDB-MS), que teve 21 votos. O coment\u00e1rio de Bolsonaro nas redes sociais foi publicado poucos minutos ap\u00f3s a proclama\u00e7\u00e3o do resultado. Outros ministros do governo tamb\u00e9m saudaram a vit\u00f3ria do mineiro.<\/p>\n\n\n\n<p>Respons\u00e1vel pela articula\u00e7\u00e3o pol\u00edtica do governo, o ministro Luiz Eduardo Ramos (Secretaria de Governo) parabenizou Pacheco.<\/p>\n\n\n\n<p>&#8220;Parabenizo a vit\u00f3ria do presidente Rodrigo Pacheco no Senado Federal! Ao lado do presidente Bolsonaro, acompanhei o desenrolar de um processo leg\u00edtimo e democr\u00e1tico na tarde de hoje. \u00c9 com base nesses princ\u00edpios que seguiremos articulando em busca do desenvolvimento do nosso Pa\u00eds!&#8221;<\/p>\n\n\n\n<p>Acompanhando a mensagem, Ramos publico uma foto em que ele e Bolsonaro aparecem acompanhando a sess\u00e3o do Senado.<\/p>\n\n\n\n<p>F\u00e1bio Faria (PSD), ministro das Comunica\u00e7\u00f5es, disse que o governo est\u00e1 confiante na atua\u00e7\u00e3o de Pacheco na &#8220;pauta liberal e nas reformas necess\u00e1rias ao pa\u00eds&#8221;. &#8220;Desejo uma excelente jornada no comando da casa legislativa&#8221;.<\/p>\n\n\n\n<p>ClickPB<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente Jair Bolsonaro (sem partido) publicou nesta segunda-feira (1\u00ba) uma mensagem sobre a elei\u00e7\u00e3o de seu aliado, Rodrigo Pacheco (DEM-MG), para a presid\u00eancia do&hellip; <\/p>\n","protected":false},"author":6,"featured_media":204934,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2,11],"tags":[],"class_list":["post-204933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","category-politica"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/204933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=204933"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/204933\/revisions"}],"predecessor-version":[{"id":204935,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/204933\/revisions\/204935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/204934"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=204933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=204933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=204933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}