{"id":204936,"date":"2021-02-02T06:52:48","date_gmt":"2021-02-02T09:52:48","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=204936"},"modified":"2021-02-02T06:52:50","modified_gmt":"2021-02-02T09:52:50","slug":"paraiba-confirma-1-014-novos-casos-de-covid-19-e-12-obitos-nesta-segunda-feira","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2021\/02\/02\/paraiba-confirma-1-014-novos-casos-de-covid-19-e-12-obitos-nesta-segunda-feira\/","title":{"rendered":"Para\u00edba confirma 1.014 novos casos de Covid-19 e 12 \u00f3bitos nesta segunda-feira"},"content":{"rendered":"\n<p>A Para\u00edba registrou, nesta segunda (1\u00b0), 1.014 casos da Covid- 19. Tamb\u00e9m foram confirmados 12 novos \u00f3bitos desde a \u00faltima atualiza\u00e7\u00e3o, sendo 08 deles nas \u00faltimas 24h.&nbsp;De acordo com o boletim epidemiol\u00f3gico divulgado pela Secretaria de Estado da Sa\u00fade ao&nbsp;<strong>ClickPB<\/strong>&nbsp;desde a \u00faltima atualiza\u00e7\u00e3o, a Para\u00edba totaliza 192.598 casos confirmados da doen\u00e7a, que est\u00e3o distribu\u00eddos por todos os 223 munic\u00edpios.<\/p>\n\n\n\n<p><strong>N\u00fameros Totais<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Casos Confirmados: 192.598<\/li><li>\u00d3bitos Confirmados: 4.068<\/li><li>Casos Recuperados: 149.235<\/li><li>Testes Realizados: 594.858<\/li><\/ul>\n\n\n\n<p>At\u00e9 o momento, 594.858 testes para diagn\u00f3stico da Covid-19 j\u00e1 foram realizados.<\/p>\n\n\n\n<p>Entre os confirmados hoje, 11 (1,08%) s\u00e3o casos de pacientes hospitalizados e 1.003 (98,92%) s\u00e3o leves.&nbsp;Os \u00f3bitos ocorreram entre os dias 23 de janeiro e 1\u00b0 de fevereiro, sendo tr\u00eas deles em hospitais privados e os demais em hospitais p\u00fablicos. Com isso, o estado totaliza 4.068 mortes. O boletim registra ainda um total de 149.235 pacientes recuperados da doen\u00e7a.<\/p>\n\n\n\n<p><strong>Concentra\u00e7\u00e3o de casos<\/strong><\/p>\n\n\n\n<p>Cinco munic\u00edpios concentram 691 novos casos, o que corresponde a 68,14% dos casos registrados nesta segunda.&nbsp;<\/p>\n\n\n\n<p>S\u00e3o eles:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Jo\u00e3o Pessoa, com 471 novos casos, totalizando 50.249;&nbsp;<\/li><li>Bayeux, com 82 novos casos, totalizando 3.147;&nbsp;<\/li><li>Santa Rita, com 51 novos casos, totalizando 4.914;&nbsp;<\/li><li>Campina Grande, com 44 novos casos, totalizando 17.346;&nbsp;<\/li><li>Guarabira, com 43 novos casos, totalizando 5.656.<\/li><\/ul>\n\n\n\n<p>* Dados oficiais preliminares (fonte: e-sus VE, Sivep Gripe e SIM) extra\u00eddos \u00e0s 10h do dia 01\/02\/2021, sujeitos a altera\u00e7\u00e3o por parte dos munic\u00edpios.<\/p>\n\n\n\n<p><strong>\u00d3bitos<\/strong><\/p>\n\n\n\n<p>At\u00e9 esta segunda, 201 cidades paraibanas registraram \u00f3bitos por Covid-19. Os 12 \u00f3bitos confirmados neste boletim ocorreram entre residentes dos munic\u00edpios de Alagoa Grande (1), Assun\u00e7\u00e3o (1), Bananeiras (1), Cabedelo (2), Campina Grande (2), Jo\u00e3o Pessoa (2), Juazeirinho (1), Santa Rita (1) e S\u00e3o Jos\u00e9 de Piranhas (1). As v\u00edtimas s\u00e3o 07 homens e 05 mulheres, com idades entre 48 e 91 anos. Cardiopatia e hipertens\u00e3o foram as comorbidades mais freq\u00fcentes e quatro deles n\u00e3o apresentavam comorbidade.<\/p>\n\n\n\n<p><strong>Ocupa\u00e7\u00e3o de leitos Covid-19<\/strong><\/p>\n\n\n\n<p>A ocupa\u00e7\u00e3o total de leitos de UTI (adulto, pedi\u00e1trico e obst\u00e9trico) em todo o estado \u00e9 de 50%. Fazendo um recorte apenas dos leitos de UTI para adultos na Regi\u00e3o Metropolitana de Jo\u00e3o Pessoa, a taxa de ocupa\u00e7\u00e3o chega a 52%. Em Campina Grande est\u00e3o ocupados 61% dos leitos de UTI adulto e no sert\u00e3o 58% dos leitos de UTI para adultos. De acordo com o Centro estadual de regula\u00e7\u00e3o hospitalar, 21 pacientes foram internados nas \u00faltimas 24h.<\/p>\n\n\n\n<p><strong>Cobertura Vacinal<\/strong><\/p>\n\n\n\n<p>At\u00e9 a \u00faltima atualiza\u00e7\u00e3o de 1\u00b0 de fevereiro, foi registrado no sistema de informa\u00e7\u00e3o SI-PNI a aplica\u00e7\u00e3o de 38.399 doses.<\/p>\n\n\n\n<p>ClickPB<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Para\u00edba registrou, nesta segunda (1\u00b0), 1.014 casos da Covid- 19. Tamb\u00e9m foram confirmados 12 novos \u00f3bitos desde a \u00faltima atualiza\u00e7\u00e3o, sendo 08 deles nas&hellip; <\/p>\n","protected":false},"author":6,"featured_media":204937,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2,104],"tags":[],"class_list":["post-204936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","category-paraiba"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/204936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=204936"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/204936\/revisions"}],"predecessor-version":[{"id":204938,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/204936\/revisions\/204938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/204937"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=204936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=204936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=204936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}