{"id":204948,"date":"2021-02-02T08:30:03","date_gmt":"2021-02-02T11:30:03","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=204948"},"modified":"2021-02-02T08:30:05","modified_gmt":"2021-02-02T11:30:05","slug":"entenda-a-decisao-de-arthur-lira-que-anulou-a-eleicao-para-cargos-da-mesa-da-camara","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2021\/02\/02\/entenda-a-decisao-de-arthur-lira-que-anulou-a-eleicao-para-cargos-da-mesa-da-camara\/","title":{"rendered":"Entenda a decis\u00e3o de Arthur Lira que anulou a elei\u00e7\u00e3o para cargos da mesa da C\u00e2mara"},"content":{"rendered":"\n<p>Logo ap\u00f3s ter sido eleito presidente da C\u00e2mara, o deputado\u00a0Arthur Lira (PP-AL) anulou na noite desta segunda-feira (1\u00ba) a vota\u00e7\u00e3o para os demais cargos da Mesa Diretora\u00a0e determinou a realiza\u00e7\u00e3o de uma nova elei\u00e7\u00e3o para a escolha de seus integrantes. Entenda a decis\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>A elei\u00e7\u00e3o para a renova\u00e7\u00e3o da Mesa Diretora da C\u00e2mara \u00e9 feita a cada dois anos. Os deputados escolhem um candidato a presidente; e escolhem tamb\u00e9m candidatos a cada um dos demais cargos da mesa diretora (primeiro-vice-presidente; segundo-vice-presidente; primeiro-secret\u00e1rio; segundo-secret\u00e1rio; terceiro-secret\u00e1rio; quarto-secret\u00e1rio; e quatro suplentes de secret\u00e1rios)<\/li><li>A defini\u00e7\u00e3o dos candidatos a vice-presidentes, secret\u00e1rios e suplentes \u00e9 feita com base em crit\u00e9rios de proporcionalidade entre os blocos partid\u00e1rios formados para a elei\u00e7\u00e3o, em um c\u00e1lculo efetuado pela Secretaria-Geral da C\u00e2mara \u2014 os maiores blocos ganham prioridade de escolha.<\/li><li>Na elei\u00e7\u00e3o deste ano, foram formados dois blocos. O de Arthur Lira e o de Baleia Rossi (MDB-SP).<\/li><li>Em reuni\u00e3o nesta segunda, antes da elei\u00e7\u00e3o, os dois blocos acertaram entre si a divis\u00e3o dos cargos na mesa, respeitando a proporcionalidade. Os maior bloco tem direito a escolher primeiro os cargos de sua prefer\u00eancia. Apenas candidatos desse bloco ou partido poder\u00e3o se candidatar para a cadeira.<\/li><li>Na divis\u00e3o, o bloco de Lira ficaria com cinco cargos na Mesa Diretora. O de Baleia, com quatro.<\/li><li>Os partidos se re\u00fanem em blocos a fim de ampliar as possibilidades de ocupar um dos cargos da mesa. Isoladamente, um partido teria mais dificuldade para obter uma das vagas na mesa. No bloco, a possibilidade \u00e9 maior porque a bancada do partido se soma \u00e0 de outros e se torna maior a chance de que, proporcionalmente, esse partido possa indicar um deputado para algum dos cargos na mesa.<\/li><li>O prazo para os partidos se inscreverem em um dos blocos (o que apoiava Lira e o que apoiava Baleia Rossi) se encerrava \u00e0s 12h desta segunda-feira (1\u00ba).<\/li><li>Os integrantes do bloco de apoio a Lira argumentaram que um dos partidos do bloco de Baleia, o PT, efetuou a inscri\u00e7\u00e3o fora do prazo (\u00e0s 12h06).<\/li><li>Mesmo assim, o presidente da C\u00e2mara naquele momento, o deputado Rodrigo Maia (DEM-RJ), decidiu tomar uma decis\u00e3o isolada, sem levar o caso ao plen\u00e1rio, e aceitou a inscri\u00e7\u00e3o do PT no bloco de Rossi.<\/li><li>Aliados de Arthur Lira, ent\u00e3o, amea\u00e7aram ir ao Supremo Tribunal Federal para impedir. Mas Lira decidiu ceder naquele momento, a fim de que as diverg\u00eancias n\u00e3o prejudicassem a elei\u00e7\u00e3o para presidente, na qual era o favorito \u2014&nbsp;<a href=\"https:\/\/g1.globo.com\/politica\/noticia\/2021\/02\/01\/arthur-lira-do-pp-e-eleito-presidente-da-camara-em-1o-turno-com-apoio-de-bolsonaro.ghtml\">ele ganhou com 302 votos, mais que o dobro dos votos de Baleia Rossi<\/a>&nbsp;(145).<\/li><li>A apura\u00e7\u00e3o eletr\u00f4nica dos votos \u00e9 feita em dois momentos: primeiro, o painel do plen\u00e1rio da C\u00e2mara indica o candidato vencedor para presidente, que assume o posto imediatamente. Depois, s\u00e3o revelados os votos para os demais cargos na mesa.<\/li><li>Mas, ao assumir, Arthur Lira n\u00e3o determinou a apura\u00e7\u00e3o dos votos para os demais cargos e anunciou a anula\u00e7\u00e3o da decis\u00e3o de Rodrigo Maia. Lira determinou \u00e0 Secretaria-Geral um novo c\u00e1lculo de proporcionalidade, sem considerar o bloco de Baleia Rossi, e marcou uma nova elei\u00e7\u00e3o para esses cargos para esta ter\u00e7a-feira (2).<\/li><li>Pelo crit\u00e9rio da proporcionalidade e com base na decis\u00e3o de Maia, o PT, piv\u00f4 de todo o epis\u00f3dio, ficaria com um dos cargos mais importantes da mesa, a Primeira Secretaria. Com a decis\u00e3o de Lira, o partido, detentor da maior bancada da C\u00e2mara, dever\u00e1 ocupar uma vaga menor.<\/li><li>No final da noite, os partidos que apoiavam Baleia Rossi se reuniram, argumentaram que o ato de Lira foi ilegal e autorit\u00e1rio e&nbsp;<a href=\"https:\/\/g1.globo.com\/politica\/noticia\/2021\/02\/02\/aliados-de-baleia-anunciam-acao-no-stf-contra-decisao-de-lira-sobre-cargos-da-mesa-da-camara.ghtml\">decidiram mover uma a\u00e7\u00e3o contra a decis\u00e3o no Supremo Tribunal Federal<\/a>&nbsp;(STF).<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Os cargos da Mesa Diretora<\/h4>\n\n\n\n<p>S\u00e3o as seguintes as atribui\u00e7\u00f5es dos ocupantes de cada um dos cargos da Mesa Diretora da C\u00e2mara:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>1\u00ba Vice-presidente<\/strong>: substitui o presidente e elabora pareceres sobre projetos de resolu\u00e7\u00e3o;<\/li><li><strong>2\u00ba Vice-presidente<\/strong>: substitui o presidente ou o 1\u00ba vice e examina os pedidos de ressarcimento de despesa m\u00e9dica dos deputados;<\/li><li><strong>1\u00ba Secret\u00e1rio<\/strong>: respons\u00e1vel pelo gerenciamento das despesas da C\u00e2mara, aprovando, por exemplo, obras e reformas;<\/li><li><strong>2\u00ba Secret\u00e1rio<\/strong>: trata de assuntos pertinentes a passaportes diplom\u00e1ticos;<\/li><li><strong>3\u00ba Secret\u00e1rio<\/strong>: autoriza reembolso de passagens a\u00e9reas e analisa pedidos de licen\u00e7a e justificativas de faltas;<\/li><li><strong>4\u00ba Secret\u00e1rio<\/strong>: supervisiona a concess\u00e3o de apartamentos funcionais ou o pagamento de aux\u00edlio-moradia aos deputados;<\/li><li><strong>Suplentes de secret\u00e1rio<\/strong>: s\u00e3o quatro suplentes, que substituem os titulares em suas aus\u00eancias e participam de reuni\u00f5es da Mesa.<\/li><\/ul>\n\n\n\n<p>G1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Logo ap\u00f3s ter sido eleito presidente da C\u00e2mara, o deputado\u00a0Arthur Lira (PP-AL) anulou na noite desta segunda-feira (1\u00ba) a vota\u00e7\u00e3o para os demais cargos da&hellip; <\/p>\n","protected":false},"author":6,"featured_media":204928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2,11],"tags":[],"class_list":["post-204948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","category-politica"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/204948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=204948"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/204948\/revisions"}],"predecessor-version":[{"id":204950,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/204948\/revisions\/204950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/204928"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=204948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=204948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=204948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}