{"id":20667,"date":"2017-05-28T13:47:08","date_gmt":"2017-05-28T16:47:08","guid":{"rendered":"http:\/\/caririemacao.com\/1\/?p=20667"},"modified":"2017-05-28T13:47:08","modified_gmt":"2017-05-28T16:47:08","slug":"campina-grande-recebe-copa-br-nordeste","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2017\/05\/28\/campina-grande-recebe-copa-br-nordeste\/","title":{"rendered":"Campina Grande recebe copa BR Nordeste"},"content":{"rendered":"<p>O basquete ser\u00e1 uma das atra\u00e7\u00f5es do final de semana esportivo em Campina Grande. Em uma programa\u00e7\u00e3o que come\u00e7ou ontem, e segue at\u00e9 amanh\u00e3, estar\u00e3o sendo realizados na Arena Facisa, os jogos da primeira fase do Grupo II da Copa Brasil Nordeste.<\/p>\n<p>Equipes da Para\u00edba e do Rio Grande do Norte far\u00e3o parte dos confrontos, que acontecem no sistema onde todos enfrentam todos. Os dois primeiros colocados garantem classifica\u00e7\u00e3o para as quartas de final da fase regional da modalidade.<\/p>\n<p>A competi\u00e7\u00e3o aponta um representante que disputar\u00e1 a Super Copa do Brasil, que re\u00fane as melhores equipes do pa\u00eds.<\/p>\n<p>\u201cAs equipes se prepararam bastante e estamos com muita expectativa. Estamos muito confiantes que vamos conseguir as duas vagas. Jogar em casa tamb\u00e9m ajuda muito\u201d, afirmou Eduardo Schafer, presidente da Federa\u00e7\u00e3o Paraibana de Basquete (FPB).<\/p>\n<p>Esta ser\u00e1 a primeira competi\u00e7\u00e3o realizada na Arena, sendo um evento-teste para a inaugura\u00e7\u00e3o, que deve acontecer em agosto.<\/p>\n<p>Nos confrontos de hoje, o Basquete Para\u00edba\/IFPB enfrenta o ACD Potiguar a partir das 15h. Logo depois, a Unifacisa entra em quadra contra o ACD Potiguar. Amanh\u00e3, \u00e0s 9h, no Clube do Trabalhador\/SESI, o ABC enfrenta o Basquete Para\u00edba\/IFPB, e \u00e0s 11h, Unifacisa x ACD Potiguar encerram a programa\u00e7\u00e3o.<\/p>\n<p><strong>CARIRI EM A\u00c7\u00c3O<\/strong><\/p>\n<p>Correio da Para\u00edba\/Foto: Google<\/p>\n<p><strong>Leia mais not\u00edcias em\u00a0<\/strong><a href=\"http:\/\/www.caririemacao.com\/\"><strong>caririemacao.com<\/strong><\/a><strong>, siga nossa p\u00e1gina no\u00a0<\/strong><a href=\"https:\/\/www.facebook.com\/CaririEmAcao\/?ref=aymt_homepage_panel\"><strong>Facebook<\/strong><\/a><strong>\u00a0e\u00a0<a href=\"https:\/\/www.instagram.com\/cariri_em_acao\/?hl=pt-br\">Instagram<\/a>\u00a0veja nossas mat\u00e9rias e fotos. Voc\u00ea tamb\u00e9m pode enviar informa\u00e7\u00f5es \u00e0 Reda\u00e7\u00e3o do Portal Cariri em A\u00e7\u00e3o pelo WhatsApp (83) 9 9634.5791, (83) 9 9601-1162.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O basquete ser\u00e1 uma das atra\u00e7\u00f5es do final de semana esportivo em Campina Grande. Em uma programa\u00e7\u00e3o que come\u00e7ou ontem, e segue at\u00e9 amanh\u00e3, estar\u00e3o&hellip; <\/p>\n","protected":false},"author":2,"featured_media":20668,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-20667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/20667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=20667"}],"version-history":[{"count":0,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/20667\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/20668"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=20667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=20667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=20667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}