{"id":21214,"date":"2017-06-06T00:07:15","date_gmt":"2017-06-06T03:07:15","guid":{"rendered":"http:\/\/caririemacao.com\/1\/?p=21214"},"modified":"2017-06-06T00:08:52","modified_gmt":"2017-06-06T03:08:52","slug":"profissionais-do-samu-recebem-capacitacao-e-treinamento-em-monteiro","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2017\/06\/06\/profissionais-do-samu-recebem-capacitacao-e-treinamento-em-monteiro\/","title":{"rendered":"Profissionais do SAMU recebem capacita\u00e7\u00e3o e treinamento em Monteiro"},"content":{"rendered":"<p>Os profissionais de atendimento, condutores e equipe de enfermagem, do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia \u2013 SAMU receberam tr\u00eas dias de treinamento e capacita\u00e7\u00e3o no \u00faltimo final de semana em Monteiro. Esta foi uma iniciativa da Prefeitura Municipal por meio da Secretaria de Sa\u00fade.<\/p>\n<p>O 1\u00ba Workshop de APH (Atendimento Pr\u00e9 Hospitalar) teve in\u00edcio na noite da sexta-feira (02) realizado pela empresa patoense Anjos da Vida \u2013 Centro de Treinamento e foi ministrado pelo professor D\u00e1cio Rondinelly na Escola Municipal Tiradentes.<\/p>\n<p>Durante o curso foram abordados temas como Atendimento Inicial ao Politraumatizado, Identifica\u00e7\u00e3o e Imobiliza\u00e7\u00e3o de Fraturas, RCP \u2013 Adulto, Crian\u00e7a e Lactente, Abordagem \u00e0 M\u00faltiplas V\u00edtimas. Dentre o aprendizado te\u00f3rico e pr\u00e1tico, houve simula\u00e7\u00f5es de atendimento envolvendo t\u00e9cnicas de remo\u00e7\u00e3o, de imobiliza\u00e7\u00e3o e de resgate, como tamb\u00e9m refor\u00e7o quanto ao protocolo que envolve o primeiro atendimento, padronizando a conduta dos socorristas.<\/p>\n<p>De acordo a secret\u00e1ria executiva de Sa\u00fade do munic\u00edpio, Viviane Ferreira, os treinamentos que s\u00e3o frequentes \u00e0s equipes do SAMU s\u00e3o uma forma importante de fortalecimento dos conhecimentos a serem empregados nos atendimentos a popula\u00e7\u00e3o da cidade e regi\u00e3o. \u201cS\u00e3o 29 profissionais participando deste Workshop, e nossa inten\u00e7\u00e3o \u00e9 sempre oferecer qualifica\u00e7\u00f5es para que a popula\u00e7\u00e3o atendida receba um servi\u00e7o de qualidade a altura que merecem.\u201d<\/p>\n<p>\u201c\u00c9 imprescind\u00edvel para o nosso dia-a-dia participar deste tipo de capacita\u00e7\u00e3o, pois \u00e9 uma forma de agregar qualidade ao atendimento. \u00c9 importante pra n\u00f3s e para o paciente, pois \u00e9 fundamental que ele se sinta seguro. Com estas capacita\u00e7\u00f5es al\u00e9m das aulas te\u00f3ricas, n\u00f3s tamb\u00e9m treinamos para saber melhor como proceder em cada caso\u201d, disse um dos participantes do Workshop.<\/p>\n<p><strong>CARIRI EM A\u00c7\u00c3O<\/strong><\/p>\n<p>Ascom\/Foto: Divulga\u00e7\u00e3o<\/p>\n<p><strong>Leia mais not\u00edcias em\u00a0<\/strong><a href=\"http:\/\/www.caririemacao.com\/\"><strong>caririemacao.com<\/strong><\/a><strong>, siga nossa p\u00e1gina no\u00a0<\/strong><a href=\"https:\/\/www.facebook.com\/CaririEmAcao\/?ref=aymt_homepage_panel\"><strong>Facebook<\/strong><\/a><strong>\u00a0e\u00a0<a href=\"https:\/\/www.instagram.com\/cariri_em_acao\/?hl=pt-br\">Instagram<\/a>\u00a0veja nossas mat\u00e9rias e fotos. Voc\u00ea tamb\u00e9m pode enviar informa\u00e7\u00f5es \u00e0 Reda\u00e7\u00e3o do Portal Cariri em A\u00e7\u00e3o pelo WhatsApp (83) 9 9634.5791, (83) 9 9601-1162.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os profissionais de atendimento, condutores e equipe de enfermagem, do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia \u2013 SAMU receberam tr\u00eas dias de treinamento e capacita\u00e7\u00e3o&hellip; <\/p>\n","protected":false},"author":2,"featured_media":21216,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[16],"tags":[],"class_list":["post-21214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/21214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=21214"}],"version-history":[{"count":0,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/21214\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/21216"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=21214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=21214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=21214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}