{"id":216789,"date":"2021-05-05T07:37:03","date_gmt":"2021-05-05T10:37:03","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=216789"},"modified":"2021-05-05T07:37:05","modified_gmt":"2021-05-05T10:37:05","slug":"corpo-de-paulo-gustavo-vai-ser-velado-no-teatro-municipal-do-rio-de-janeiro","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2021\/05\/05\/corpo-de-paulo-gustavo-vai-ser-velado-no-teatro-municipal-do-rio-de-janeiro\/","title":{"rendered":"Corpo de Paulo Gustavo vai ser velado no Teatro Municipal do Rio de Janeiro"},"content":{"rendered":"\n<p>O corpo de Paulo Gustavo, um dos grandes nomes da nossa arte nos \u00faltimos anos, que faleceu na noite desta ter\u00e7a-feira (04),&nbsp;\u00e0s 21h12, ser\u00e1 velado no Teatro Municipal do Rio. O pedido foi feito pela fam\u00edlia do artista, prontamente atendido pelo governo do Rio. O vel\u00f3rio ser\u00e1 reservado a familiares, seguindo os protocolos necess\u00e1rios por conta da pandemia.<\/p>\n\n\n\n<p>Acometido pela Covid-19 e internado desde 13 de mar\u00e7o, o ator e humorista lutou bravamente contra a doen\u00e7a desde ent\u00e3o, tendo apresentado sinais de melhora nas \u00faltimas semanas.<\/p>\n\n\n\n<p>Ontem, por\u00e9m, foi constatada uma embolia pulmonar, o que tornou o seu quadro de sa\u00fade extremamente cr\u00edtico. Paulo deixa o marido, Thales, e dois filhos.<\/p>\n\n\n\n<p>Conhecido por levar alegria aos brasileiros, Paulo Gustavo vivia o auge da sua carreira em virtude dos personagens criados. Um deles, em especial, ganhou espa\u00e7o no cora\u00e7\u00e3o do p\u00fablico: Dona Herm\u00ednia, inspirada na querida m\u00e3e do humorista, D\u00e9a Lucia. A personagem estrelou o espet\u00e1culo &#8220;Minha m\u00e3e \u00e9 uma pe\u00e7a&#8221;, sucesso de p\u00fablico por onde passou. A repercuss\u00e3o foi tanta que a produ\u00e7\u00e3o parou nos cinemas. Foram tr\u00eas filmes, sempre com recordes de bilheteria.<\/p>\n\n\n\n<p><em>ClickPB<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O corpo de Paulo Gustavo, um dos grandes nomes da nossa arte nos \u00faltimos anos, que faleceu na noite desta ter\u00e7a-feira (04),&nbsp;\u00e0s 21h12, ser\u00e1 velado&hellip; <\/p>\n","protected":false},"author":6,"featured_media":216790,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-216789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/216789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=216789"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/216789\/revisions"}],"predecessor-version":[{"id":216791,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/216789\/revisions\/216791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/216790"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=216789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=216789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=216789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}