{"id":223826,"date":"2021-07-07T06:42:52","date_gmt":"2021-07-07T09:42:52","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=223826"},"modified":"2021-07-07T06:42:54","modified_gmt":"2021-07-07T09:42:54","slug":"paraiba-confirma-21-mortes-e-475-novos-casos-de-covid-19-nesta-terca-feira","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2021\/07\/07\/paraiba-confirma-21-mortes-e-475-novos-casos-de-covid-19-nesta-terca-feira\/","title":{"rendered":"Para\u00edba confirma 21 mortes e 475 novos casos de Covid-19 nesta ter\u00e7a-feira"},"content":{"rendered":"\n<p>A Para\u00edba&nbsp;registrou, nesta ter\u00e7a (6), 475 casos de Covid-19. Tamb\u00e9m foram confirmados 21 novos \u00f3bitos desde a \u00faltima atualiza\u00e7\u00e3o, sendo 16 ocorridos nas \u00faltimas 24h.&nbsp;De acordo com o boletim epidemiol\u00f3gico divulgado pela Secretaria de Estado da Sa\u00fade ao&nbsp;<strong>ClickPB<\/strong>&nbsp;desde a \u00faltima atualiza\u00e7\u00e3o, 117 (24,63%) s\u00e3o casos de pacientes hospitalizados e 358 (75,37%) s\u00e3o leves.&nbsp;<\/p>\n\n\n\n<p>Agora, a Para\u00edba totaliza 402.175 casos confirmados da doen\u00e7a, que est\u00e3o distribu\u00eddos por todos os 223 munic\u00edpios. At\u00e9 o momento, 1.059.376 testes para diagn\u00f3stico da Covid-19 j\u00e1 foram realizados.<\/p>\n\n\n\n<p>Os \u00f3bitos confirmados neste boletim aconteceram entre os dias 26 de maio e 6 de julho de 2021. Com isso, o estado totaliza 8.724 mortes. O boletim registra ainda um total de 268.966 pacientes recuperados da doen\u00e7a.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/www.clickpb.com.br\/media\/filer_public\/08\/96\/08963f47-0dda-4e10-9627-33fe9369bdce\/whatsapp_image_2021-07-06_at_163338.jpeg\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/figure>\n\n\n\n<p><strong>Concentra\u00e7\u00e3o de casos<\/strong><\/p>\n\n\n\n<p>Cinco munic\u00edpios concentram 166 novos casos, o que corresponde a 34,95% dos casos registrados nesta ter\u00e7a. S\u00e3o eles: Jo\u00e3o Pessoa, com 55 novos casos, totalizando 100.186; Campina Grande, com 49 novos casos, totalizando 37.932; Patos, com 28 novos casos, totalizando 13.178; Santa Rita com 19 novos casos, totalizando 9.154; Pilar, com 15 novos casos, totalizando 1.260.<\/p>\n\n\n\n<p><em>*Dados oficiais preliminares (fonte: e-sus VE, Sivep Gripe e SIM) extra\u00eddos \u00e0s 10h do dia 06\/07\/2021, sujeitos a altera\u00e7\u00e3o por parte dos munic\u00edpios.<\/em><\/p>\n\n\n\n<p><strong>\u00d3bitos<\/strong><\/p>\n\n\n\n<p>At\u00e9 esta ter\u00e7a-feira (6), 222 cidades paraibanas registraram \u00f3bitos por Covid-19. Os 21 \u00f3bitos confirmados neste boletim ocorreram entre residentes dos munic\u00edpios de Ara\u00e7agi (2); Boqueir\u00e3o (1); Cabedelo (1); Cacimba de Dentro (1); Campina Grande (4); Caturit\u00e9 (1); Cubati (1); Guarabira (1); Jo\u00e3o Pessoa (3); Massaranduba (1); Patos (1); Pombal (1); Queimadas (1); Santa Rita (1) e Sol\u00e2nea (1).<\/p>\n\n\n\n<p>As v\u00edtimas s\u00e3o 08 homens e 13 mulheres, com idades entre 37 e 91 anos. Diabetes foi a comorbidade mais frequente e 8 n\u00e3o tinham comorbidades.<\/p>\n\n\n\n<p><strong>Ocupa\u00e7\u00e3o de leitos Covid-19<\/strong><\/p>\n\n\n\n<p>A ocupa\u00e7\u00e3o total de leitos de UTI (adulto, pedi\u00e1trico e obst\u00e9trico) em todo o estado \u00e9 de 45%. Fazendo um recorte apenas dos leitos de UTI para adultos na Regi\u00e3o Metropolitana de Jo\u00e3o Pessoa, a taxa de ocupa\u00e7\u00e3o chega a 45%. Em Campina Grande est\u00e3o ocupados 40% dos leitos de UTI adulto e no sert\u00e3o 60% dos leitos de UTI para adultos. De acordo com o Centro Estadual de Regula\u00e7\u00e3o Hospitalar, 28 pacientes foram internados nas \u00faltimas 24h, \u00e9 o menor n\u00famero registrado desde 15 de fevereiro. Ao todo, 538 pacientes est\u00e3o internados nas unidades de refer\u00eancia.<\/p>\n\n\n\n<p><strong>Cobertura Vacinal<\/strong><\/p>\n\n\n\n<p>Foi registrado no sistema de informa\u00e7\u00e3o SI-PNI a aplica\u00e7\u00e3o de 1.866.485 doses. At\u00e9 o momento, 1.343.394&nbsp; pessoas foram vacinadas com a primeira dose e 543.091 completaram os esquemas vacinais, onde 521.741 tomaram as duas doses e 21.350 utilizaram imunizante de dose \u00fanica. A Para\u00edba j\u00e1 distribuiu um total de 2.145.538 doses de vacina aos munic\u00edpios.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/www.clickpb.com.br\/media\/filer_public\/98\/4d\/984d558b-9e76-475e-9951-ccdf9d7af0b2\/whatsapp_image_2021-07-06_at_163339_1.jpeg\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/figure>\n\n\n\n<p>ClickPB<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Para\u00edba&nbsp;registrou, nesta ter\u00e7a (6), 475 casos de Covid-19. Tamb\u00e9m foram confirmados 21 novos \u00f3bitos desde a \u00faltima atualiza\u00e7\u00e3o, sendo 16 ocorridos nas \u00faltimas 24h.&nbsp;De&hellip; <\/p>\n","protected":false},"author":6,"featured_media":223827,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[124,50,104],"tags":[],"class_list":["post-223826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","category-destaque","category-paraiba"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/223826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=223826"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/223826\/revisions"}],"predecessor-version":[{"id":223828,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/223826\/revisions\/223828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/223827"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=223826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=223826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=223826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}