{"id":230201,"date":"2021-09-09T11:33:51","date_gmt":"2021-09-09T14:33:51","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=230201"},"modified":"2021-09-09T11:33:53","modified_gmt":"2021-09-09T14:33:53","slug":"a-suzy-ta-on-empreendedora-do-congo-se-destaca-promovendo-live-shop","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2021\/09\/09\/a-suzy-ta-on-empreendedora-do-congo-se-destaca-promovendo-live-shop\/","title":{"rendered":"A SUZY T\u00c1 ON: Empreendedora do Congo se destaca promovendo &#8216;Live Shop&#8217;"},"content":{"rendered":"\n<p>Em um mercado t\u00e3o competitivo como \u00e9 o do varejo, Susiane Pereira, a Suzy como \u00e9 carinhosamente chamada pelas suas clientes, vem se destacando e inspirando outras mulheres pelo Cariri. A comerciante da cidade do Congo costuma fazer lives toda quinta-feira no Instagram da sua loja. O detalhe \u00e9 que ela n\u00e3o faz lives apenas para vender, ela faz do momento um entretimento para quem acompanha. Tem cliente que diz que deixa a novela de lado pra assistir a live dela.<\/p>\n\n\n\n<p>E Suzy vai muito al\u00e9m disso. Ela manda, quase diariamente, mensagens de autoestima nas suas listas de transmiss\u00e3o, que tem alguns milhares de clientes, em sua maioria mulheres, e claro, muitas ofertas.<\/p>\n\n\n\n<p>Quem acompanha as lives dela \u00e9 sempre recepcionada com grande irrever\u00eancia e com os \u201cal\u00f4s\u201d que ela manda pra fam\u00edlia inteira de quem entra na live. As pessoas v\u00e3o pedindo e ela vai mandando. Com isso ela mostra que vai al\u00e9m de conhecer apenas os produtos que vende, ela conhece as pessoas. E no meio disso tudo ela ainda arranja um meio de presentear a clientela, ela faz sorteios de brindes no meio das lives.<\/p>\n\n\n\n<p>Nesses encontros semanais que Suzy tem com sua freguesia, ela vende de tudo que tem na sua loja. L\u00e1 ela tem um leque de produtos bem variados que v\u00e3o de pantufas a arm\u00e1rios, passando por cama-box, roupas, perfumes, chocolates, produtos de beleza e produtos importados. Mas o produto de maior import\u00e2ncia que ela tem e n\u00e3o est\u00e1 \u00e0 venda: \u00e9 a confian\u00e7a que a clientela tem nela. Tem gente que j\u00e1 paga antes de come\u00e7ar a live.<\/p>\n\n\n\n<p>As lives dela geralmente levam as suas clientes a irem dormir tarde. Muitas vezes passa da meia-noite e Suzy continua l\u00e1 conversando e dando toda aten\u00e7\u00e3o \u00e0s pessoas. Ela at\u00e9 j\u00e1 retratou o comportamento de suas clientes nas lives num dos muitos v\u00eddeos que ela faz.<\/p>\n\n\n\n<p>Em meio \u00e0 pandemia essa foi a maneira que ela encontrou de levar alegria e reencontrar suas clientes que n\u00e3o podiam ir \u00e0 loja.<\/p>\n\n\n\n<p>Assim ela se aproxima ainda mais de suas clientes, levando alegria e entretimento, inspira\u00e7\u00e3o e autoestima, produtos e ofertas \u00e0s pessoas. Essa foi a forma que ela encontrou de continuar inovando no seu empreendimento.<\/p>\n\n\n\n<p>Voc\u00ea pode acompanhar as lives dela sempre \u00e0s quintas, \u00e0s 19h, no seguinte endere\u00e7o: @lojapereiramoveis<\/p>\n\n\n\n<p>E s\u00f3 pra variar ela n\u00e3o p\u00e1ra. Essa semana ela vai abrir uma loja de chocolates em Monteiro. E o que ela vai fazer?<br>Uma live. S\u00f3 que dessa vez vai ser no Instagram da influenciadora digital monteirense Nay Costa. Mas o dia e o hor\u00e1rio \u00e9 que j\u00e1 virou tradi\u00e7\u00e3o pra quem acompanha Suzy: hoje, quinta-feira, \u00e0s 19h. O endere\u00e7o da live de hoje \u00e9 o seguinte: @naycossta<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em um mercado t\u00e3o competitivo como \u00e9 o do varejo, Susiane Pereira, a Suzy como \u00e9 carinhosamente chamada pelas suas clientes, vem se destacando e&hellip; <\/p>\n","protected":false},"author":6,"featured_media":230202,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[74],"tags":[],"class_list":["post-230201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-congo"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/230201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=230201"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/230201\/revisions"}],"predecessor-version":[{"id":230203,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/230201\/revisions\/230203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/230202"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=230201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=230201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=230201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}