{"id":23226,"date":"2017-07-07T10:20:25","date_gmt":"2017-07-07T13:20:25","guid":{"rendered":"http:\/\/caririemacao.com\/1\/?p=23226"},"modified":"2017-07-07T10:20:25","modified_gmt":"2017-07-07T13:20:25","slug":"anvisa-diz-que-barrara-importacao-comercial-de-inibidores-de-apetite","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2017\/07\/07\/anvisa-diz-que-barrara-importacao-comercial-de-inibidores-de-apetite\/","title":{"rendered":"Anvisa diz que barrar\u00e1 importa\u00e7\u00e3o comercial de inibidores de apetite"},"content":{"rendered":"<p>Apesar da recente aprova\u00e7\u00e3o de uma lei que libera o uso de inibidores de apetite, a importa\u00e7\u00e3o desses produtos para a venda no Brasil continuar\u00e1 vetada.<br \/>\nA afirma\u00e7\u00e3o foi dada \u00e0 Folha pelo diretor-presidente da Anvisa (Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria), Jarbas Barbosa.<\/p>\n<p>Segundo ele, como a lei fala apenas em autorizar &#8220;produ\u00e7\u00e3o, comercializa\u00e7\u00e3o e consumo&#8221;, sem citar a importa\u00e7\u00e3o, a ag\u00eancia passar\u00e1 a vetar tentativas de empresas em trazer os anorex\u00edgenos anfepramona, femproporex e mazindol do exterior.<\/p>\n<p>A a\u00e7\u00e3o tem base nas atuais regras brasileiras, que impedem a importa\u00e7\u00e3o de produtos sem registro na Anvisa para serem vendidos no pa\u00eds.<\/p>\n<p>Para uso pr\u00f3prio, por pessoas f\u00edsicas, por\u00e9m, a importa\u00e7\u00e3o \u00e9 permitida, desde que em quantidade e frequ\u00eancia compat\u00edveis para uso \u2013com receita m\u00e9dica, por exemplo.<\/p>\n<p>&#8220;Como a lei n\u00e3o incluiu a importa\u00e7\u00e3o, e medicamento sem registro s\u00f3 pode ser importado para uso individual, essa seria uma medida que ter\u00edamos de prote\u00e7\u00e3o [\u00e0 sa\u00fade da popula\u00e7\u00e3o]&#8221;, diz Barbosa.<\/p>\n<p>Segundo ele, essa foi a \u00fanica op\u00e7\u00e3o encontrada pela ag\u00eancia para realizar o controle dos medicamentos rec\u00e9m-liberados \u2013ainda assim, somente em parte.<\/p>\n<p>&#8220;\u00c9 a \u00fanica brecha que vimos, mas \u00e9 s\u00f3 uma parte. N\u00e3o elimina os riscos da lei. Em rela\u00e7\u00e3o \u00e0 produ\u00e7\u00e3o no Brasil e comercializa\u00e7\u00e3o, avaliamos que abre a porteira para o mercado paralelo e ilegal&#8221;, diz. &#8220;Esperamos que o Supremo barre isso porque abre um precedente grave.&#8221;<\/p>\n<p>Derivados das anfetaminas, os anorex\u00edgenos anfepramona, femproporex e mazindol foram comercializados por d\u00e9cadas no pa\u00eds, at\u00e9 serem proibidos pela Anvisa em 2011. Na ocasi\u00e3o, a ag\u00eancia alegou que essas subst\u00e2ncias n\u00e3o possu\u00edam comprova\u00e7\u00e3o de efic\u00e1cia e traziam mais riscos que benef\u00edcios.<\/p>\n<p>A proibi\u00e7\u00e3o deu in\u00edcio a uma disputa com entidades m\u00e9dicas e representantes de associa\u00e7\u00f5es de pacientes, que recorreram ao Congresso em busca do retorno dos medicamentos.<\/p>\n<p>&#8220;N\u00e3o \u00e9 s\u00f3 porque \u00e9 de baixo custo. Era uma op\u00e7\u00e3o terap\u00eautica para os pacientes. Se n\u00e3o fossem eficazes, ningu\u00e9m iria tomar&#8221;, afirma a endocrinologista Maria Edna de Melo, da Abeso (Associa\u00e7\u00e3o Brasileira para Estudo da Obesidade), uma das entidades que se posicionou de forma favor\u00e1vel \u00e0 libera\u00e7\u00e3o.<\/p>\n<p>Para Melo, a previs\u00e3o de veto \u00e0 importa\u00e7\u00e3o n\u00e3o se justifica. &#8220;Uma importa\u00e7\u00e3o n\u00e3o deixa de ser atividade comercial&#8221;, afirma ela, que lembra que o texto d\u00e1 aval \u00e0 comercializa\u00e7\u00e3o dos inibidores.<\/p>\n<p><b>NA JUSTI\u00c7A<\/b><\/p>\n<p>Em meio ao impasse, o cen\u00e1rio para os pacientes que buscam o retorno dos emagrecedores ainda \u00e9 incerto.<\/p>\n<p>Inicialmente, representantes da ind\u00fastria declararam considerar pouco prov\u00e1vel que houvesse interesse do setor em fabricar os medicamentos, j\u00e1 que ainda s\u00e3o necess\u00e1rios estudos para comprovar seguran\u00e7a e efic\u00e1cia, considerados de alto custo.<\/p>\n<p>A previs\u00e3o, assim, era que o impacto da lei fosse maior em farm\u00e1cias de manipula\u00e7\u00e3o \u2013antes da proibi\u00e7\u00e3o, elas respondiam por 60% das prescri\u00e7\u00f5es dessas drogas.<\/p>\n<p>Sem o aval para importar as drogas, por\u00e9m, farm\u00e1cias podem ter dificuldade em obter as subst\u00e2ncias, tamb\u00e9m proibidas em outros pa\u00edses.<\/p>\n<p>A Folha procurou a Anfarmag (Associa\u00e7\u00e3o Nacional de Farmac\u00eauticos Magistrais) para comentar o tema, mas n\u00e3o recebeu resposta.<\/p>\n<p>O impasse tamb\u00e9m deve chegar em breve \u00e0 Justi\u00e7a.<\/p>\n<p>Nesta quinta-feira, o CNS (Conselho Nacional de Sa\u00fade) aprovou uma recomenda\u00e7\u00e3o para que as entidades que o comp\u00f5em \u2013associa\u00e7\u00f5es de profissionais de sa\u00fade, pacientes e movimentos populares, al\u00e9m de gestores de sa\u00fade\u2013 entrem com a\u00e7\u00f5es no STF (Supremo Tribunal Federal) questionando a libera\u00e7\u00e3o.<\/p>\n<p>Na ocasi\u00e3o, a CNTS (Confedera\u00e7\u00e3o Nacional de Trabalhadores de Sa\u00fade) e outras entidades informaram que j\u00e1 estudam a possibilidade.<\/p>\n<p>Em 2016, o STF suspendeu os efeitos da lei aprovada pela ex-presidente Dilma Rousseff que liberava a fosfoetanolamina, a &#8220;p\u00edlula do c\u00e2ncer&#8221;.<\/p>\n<p class=\"artHtml5\">COMO AGEM OS INIBIDORES DE APETITE<\/p>\n<p><b>O QUE S\u00c3O OS DERIVADOS DE ANFETAMINA<\/b><br \/>\nS\u00e3o subst\u00e2ncias que agem sobre o c\u00e9rebro, aumentando o ritmo do cora\u00e7\u00e3o e a press\u00e3o do sangue e diminuindo o apetite<\/p>\n<p><b>RISCOS<\/b><\/p>\n<p>Anvisa diz que os rem\u00e9dios causam redu\u00e7\u00e3o modesta de peso corporal, que n\u00e3o \u00e9 mantida com a interrup\u00e7\u00e3o do tratamento. A aus\u00eancia de evid\u00eancias de efic\u00e1cia e os severos efeitos adversos no c\u00e9rebro e sistema cardiovascular tornam insustent\u00e1vel a manuten\u00e7\u00e3o desses medicamentos no mercado<\/p>\n<p><strong>CARIRI EM A\u00c7\u00c3O<\/strong><\/p>\n<p>Com Folha de S\u00e3o Paulo\/Foto: Rafael Hupsel\/Folhapress<\/p>\n<p><strong>Leia mais not\u00edcias em\u00a0<\/strong><a href=\"http:\/\/www.caririemacao.com\/\"><strong>caririemacao.com<\/strong><\/a><strong>, siga nossa p\u00e1gina no\u00a0<\/strong><a href=\"https:\/\/www.facebook.com\/CaririEmAcao\/?ref=aymt_homepage_panel\"><strong>Facebook<\/strong><\/a><strong>\u00a0e\u00a0<a href=\"https:\/\/www.instagram.com\/cariri_em_acao\/?hl=pt-br\">Instagram<\/a>\u00a0veja nossas mat\u00e9rias e fotos. Voc\u00ea tamb\u00e9m pode enviar informa\u00e7\u00f5es \u00e0 Reda\u00e7\u00e3o do Portal Cariri em A\u00e7\u00e3o pelo WhatsApp (83) 9 9634.5791, (83) 9 9601-1162.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apesar da recente aprova\u00e7\u00e3o de uma lei que libera o uso de inibidores de apetite, a importa\u00e7\u00e3o desses produtos para a venda no Brasil continuar\u00e1&hellip; <\/p>\n","protected":false},"author":2,"featured_media":23227,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[16],"tags":[],"class_list":["post-23226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/23226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=23226"}],"version-history":[{"count":0,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/23226\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/23227"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=23226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=23226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=23226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}