{"id":234172,"date":"2021-10-30T07:04:04","date_gmt":"2021-10-30T10:04:04","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=234172"},"modified":"2021-10-30T07:04:06","modified_gmt":"2021-10-30T10:04:06","slug":"brasil-registra-379-mortes-por-covid-em-24-h-e-mais-de-11-mil-casos-da-doenca","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2021\/10\/30\/brasil-registra-379-mortes-por-covid-em-24-h-e-mais-de-11-mil-casos-da-doenca\/","title":{"rendered":"Brasil registra 379 mortes por Covid em 24 h e mais de 11 mil casos da doen\u00e7a"},"content":{"rendered":"\n<p>O Brasil registrou 379 mortes por Covid e 11.287 casos da doen\u00e7a, nesta sexta-feira (29). Com isso, o pa\u00eds chegou a 607.504 \u00f3bitos e a 21.791.761 infec\u00e7\u00f5es pelo Sars-CoV-2 desde o in\u00edcio da pandemia.<\/p>\n\n\n\n<p>As m\u00e9dias m\u00f3veis de mortes e casos continuam em estabilidade, sem varia\u00e7\u00f5es superiores a 15%. No momento, ocorrem 328 \u00f3bitos por dia pela Covid e 11.563 infec\u00e7\u00f5es di\u00e1rias.<\/p>\n\n\n\n<p>Os dados do pa\u00eds, coletados at\u00e9 20h, s\u00e3o fruto de colabora\u00e7\u00e3o entre Folha de S.Paulo, UOL, O Estado de S. Paulo, Extra, O Globo e G1 para reunir e divulgar os n\u00fameros relativos \u00e0 pandemia do novo coronav\u00edrus. As informa\u00e7\u00f5es s\u00e3o recolhidas pelo cons\u00f3rcio de ve\u00edculos de imprensa diariamente com as Secretarias de Sa\u00fade estaduais.<br>Os dados da vacina\u00e7\u00e3o contra a Covid-19, tamb\u00e9m coletados pelo cons\u00f3rcio, foram atualizados em 20 estados e no Distrito Federal.<\/p>\n\n\n\n<p>O Brasil registrou 1.344.005 doses de vacinas contra Covid-19, nesta sexta-feira. De acordo com dados das secretarias estaduais de Sa\u00fade, foram 214.212 primeiras doses e 790.989 segundas. Tamb\u00e9m foram registradas 340.444 doses de refor\u00e7o.<\/p>\n\n\n\n<p>O registro de doses \u00fanicas foi negativo (-1.640), nesta sexta. Isso ocorreu por revis\u00f5es de dados no Cear\u00e1 (-612) e no Esp\u00edrito Santo (-2.920).<\/p>\n\n\n\n<p>Ao todo, 154.479.447 pessoas receberam pelo menos a primeira dose de uma vacina contra a Covid no Brasil \u2013110.515.982 delas j\u00e1 receberam a segunda dose do imunizante. Somadas as doses \u00fanicas da vacina da Janssen contra a Covid, j\u00e1 s\u00e3o 115.042.737 pessoas com esquema vacinal completo no pa\u00eds.<\/p>\n\n\n\n<p>Assim, o pa\u00eds j\u00e1 tem 72,42% da popula\u00e7\u00e3o com a 1\u00aa dose e 53,93% dos brasileiros com esquema vacinal completo. Considerando somente a popula\u00e7\u00e3o adulta, os valores s\u00e3o, respectivamente, de 95,30% e 70,97%.<\/p>\n\n\n\n<p>Mesmo quem completou o esquema vacinal com as duas doses deve manter cuidados b\u00e1sicos, como uso de m\u00e1scara e distanciamento social, afirmam especialistas.<\/p>\n\n\n\n<p>A iniciativa do cons\u00f3rcio de ve\u00edculos de imprensa ocorreu em resposta \u00e0s atitudes do governo Jair Bolsonaro (sem partido), que amea\u00e7ou sonegar dados, atrasou boletins sobre a doen\u00e7a e tirou informa\u00e7\u00f5es do ar, com a interrup\u00e7\u00e3o da divulga\u00e7\u00e3o dos totais de casos e mortes. Al\u00e9m disso, o governo divulgou dados conflitantes.<\/p>\n\n\n\n<p>FolhaPress<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Brasil registrou 379 mortes por Covid e 11.287 casos da doen\u00e7a, nesta sexta-feira (29). Com isso, o pa\u00eds chegou a 607.504 \u00f3bitos e a&hellip; <\/p>\n","protected":false},"author":6,"featured_media":234173,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[123,124,50],"tags":[],"class_list":["post-234172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-covid-19","category-destaque"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/234172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=234172"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/234172\/revisions"}],"predecessor-version":[{"id":234174,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/234172\/revisions\/234174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/234173"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=234172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=234172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=234172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}