{"id":234870,"date":"2021-11-11T08:01:38","date_gmt":"2021-11-11T11:01:38","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=234870"},"modified":"2021-11-11T08:01:42","modified_gmt":"2021-11-11T11:01:42","slug":"ciro-retoma-pre-candidatura-ao-planalto-apos-mudanca-do-pdt-em-votacao-de-pec-dos-precatorios","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2021\/11\/11\/ciro-retoma-pre-candidatura-ao-planalto-apos-mudanca-do-pdt-em-votacao-de-pec-dos-precatorios\/","title":{"rendered":"Ciro retoma pr\u00e9-candidatura ao Planalto ap\u00f3s mudan\u00e7a do PDT em vota\u00e7\u00e3o de PEC dos Precat\u00f3rios"},"content":{"rendered":"\n<p>O ex-ministro Ciro Gomes disse nesta quarta-feira que retomou sua pr\u00e9-candidatura \u00e0 Presid\u00eancia da Rep\u00fablica, ap\u00f3s o que considerou um sinal corajoso de correligion\u00e1rios do PDT que mudaram de posi\u00e7\u00e3o na vota\u00e7\u00e3o da PEC dos Precat\u00f3rios.<\/p>\n\n\n\n<p>Na \u00faltima semana, o presidenci\u00e1vel havia anunciado a suspens\u00e3o de sua pr\u00e9-candidatura ap\u00f3s a constata\u00e7\u00e3o de que o PDT, partido que se identifica com pautas da esquerda, forneceu mais da metade dos votos de sua bancada na C\u00e2mara dos Deputados a favor da PEC na vota\u00e7\u00e3o em primeiro turno.<\/p>\n\n\n\n<p>Na vota\u00e7\u00e3o em segundo turno, na ter\u00e7a-feira, por\u00e9m, a maior parte dos deputados do partido votou contra a proposta.<\/p>\n\n\n\n<p>\u201cVolto \u00e0 luta porque meus companheiros de partido me deram um sinal muito generoso e corajoso, e s\u00f3 fazem esse tipo de gesto aqueles que t\u00eam compostura\u201d, disse o pr\u00e9-candidato em entrevista \u00e0 CNN Brasil.<\/p>\n\n\n\n<p>Considerada priorit\u00e1ria pelo governo federal para abrir margem fiscal e viabilizar programa social em 2022, ano em que o presidente Jair Bolsonaro tentar\u00e1 a reelei\u00e7\u00e3o, a PEC dos Precat\u00f3rios tem sido criticada pela esquerda e at\u00e9 mesmo por siglas liberais, como o Novo, e tem sido chamada de PEC do \u201ccalote\u201d e do \u201cfura teto\u201d.<\/p>\n\n\n\n<p>Ainda assim, a proposta foi aprovada em dois turnos pela C\u00e2mara dos Deputados e j\u00e1 tem previs\u00e3o de vota\u00e7\u00e3o no Senado Federal: na semana dos dias 23 e 24 deste m\u00eas.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ex-ministro Ciro Gomes disse nesta quarta-feira que retomou sua pr\u00e9-candidatura \u00e0 Presid\u00eancia da Rep\u00fablica, ap\u00f3s o que considerou um sinal corajoso de correligion\u00e1rios do&hellip; <\/p>\n","protected":false},"author":6,"featured_media":234871,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[11],"tags":[],"class_list":["post-234870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/234870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=234870"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/234870\/revisions"}],"predecessor-version":[{"id":234872,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/234870\/revisions\/234872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/234871"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=234870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=234870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=234870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}