{"id":234879,"date":"2021-11-11T08:12:48","date_gmt":"2021-11-11T11:12:48","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=234879"},"modified":"2021-11-11T08:12:53","modified_gmt":"2021-11-11T11:12:53","slug":"pfizer-inicia-testes-no-brasil-de-medicamento-experimental-contra-covid-19","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2021\/11\/11\/pfizer-inicia-testes-no-brasil-de-medicamento-experimental-contra-covid-19\/","title":{"rendered":"Pfizer inicia testes no Brasil de medicamento experimental contra Covid-19"},"content":{"rendered":"\n<p>A farmac\u00eautica Pfizer iniciou, no Brasil, estudos cl\u00ednicos da p\u00edlula experimental Paxlovid, medicamento para tratamento contra a Covid-19 que gerou, em resultados preliminares, redu\u00e7\u00e3o de 89% do risco de hospitaliza\u00e7\u00e3o ou morte em adultos vulner\u00e1veis.<\/p>\n\n\n\n<p>Segundo a farmac\u00eautica, os estudos ocorrem em 29 centros de pesquisa nos estados do Amazonas, Bahia, Cear\u00e1, Distrito Federal, Pernambuco, Rio Grande do Norte, Mato Grosso, Minas Gerais, Rio Grande do Sul, Santa Catarina, Rio de Janeiro e S\u00e3o Paulo.<\/p>\n\n\n\n<p>Em Campinas (SP), cerca de 300 volunt\u00e1rios participar\u00e3o do estudo, que \u00e9 de fase 2\/3. O antiviral \u00e9 administrado em duas cl\u00ednicas particulares e no Hospital PUC-Campinas, que come\u00e7a o uso na quinta-feira (11). O medicamento foi encaminhado para o hospital na ter\u00e7a-feira (9).<\/p>\n\n\n\n<p>Em outras cidades do Brasil, os testes come\u00e7aram na segunda semana de outubro. &#8220;Nesses estudos, o f\u00e1rmaco \u00e9 coadministrado com uma baixa dose do ritonavir, um antirretroviral utilizado em tratamento de infec\u00e7\u00e3o pelo v\u00edrus da imunodefici\u00eancia humana (HIV)&#8221;, informou a Pfizer.<\/p>\n\n\n\n<p>Se aprovado, o Paxlovid dever\u00e1 ser usado logo ap\u00f3s o aparecimento dos sintomas em pessoas com alto risco de desenvolver a forma grave da doen\u00e7a.<\/p>\n\n\n\n<p>O medicamento, conhecido como inibidor de protease, \u00e9 desenvolvido para bloquear uma enzima de que o v\u00edrus precisa para se multiplicar. Quando tomado junto com uma dose baixa do ritonavir, permanece no corpo por mais tempo.<\/p>\n\n\n\n<p>Al\u00e9m do Brasil, os testes dessa fase ocorrem nos Estados Unidos, na Hungria, no Jap\u00e3o, na Coreia do Sul, na Mal\u00e1sia, no M\u00e9xico, na Pol\u00f4nia, em Porto Rico, na Tail\u00e2ndia e na Turquia.<\/p>\n\n\n\n<p>A expectativa \u00e9 que, a partir dos resultados obtidos, a Pfizer entre com pedido de autoriza\u00e7\u00e3o para uso no \u00f3rg\u00e3o regulador de medicamentos dos EUA, o FDA (na sigla em ingl\u00eas), e depois para a ag\u00eancia europeia de sa\u00fade. Em seguida, deve ocorrer a solicita\u00e7\u00e3o para Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa), no Brasil.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/www.clickpb.com.br\/media\/filer_public\/92\/a9\/92a93a43-ebb5-4c1e-87d0-5e08d4152c87\/121445462-gettyimages-1304509523.jpg\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/figure>\n\n\n\n<p><em>Pfizer diz que p\u00edlula contra Covid reduziu em 89% interna\u00e7\u00f5es e mortes \u2014 Foto: Getty Images via BBC<\/em><\/p>\n\n\n\n<p><strong>Os testes no Brasil<\/strong><\/p>\n\n\n\n<p>Segundo a Pfizer, tr\u00eas estudos pivotais, randomizados, duplo-cego e controlados por placebo ocorrem nos centros de pesquisa do Brasil.<\/p>\n\n\n\n<p>Um deles busca pacientes n\u00e3o vacinados ou vacinados com suspeita e\/ou diagn\u00f3stico de Covid-19 e com baixo risco de desenvolver doen\u00e7a grave.<\/p>\n\n\n\n<p>O outro re\u00fane volunt\u00e1rios n\u00e3o vacinados com suspeita e\/ou diagn\u00f3stico de Covid-19 e com alto risco de desenvolver doen\u00e7a grave. H\u00e1, ainda, o estudo em pessoas n\u00e3o vacinadas cujos contatos domiciliares est\u00e3o com Covid-19.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/www.clickpb.com.br\/media\/filer_public\/b6\/01\/b601518e-1aa9-4988-9ffb-d93d40b77b8a\/hospital-puc-campinas.jpg\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/figure>\n\n\n\n<p><em>Hospital PUC Campinas \u2014 Foto: Crislaine Gava\/Hospital PUC Campinas<\/em><\/p>\n\n\n\n<p><strong>Volunt\u00e1rios na PUC-Campinas<\/strong><\/p>\n\n\n\n<p>Diretor do centro de pesquisa do Hospital PUC-Campinas, Danilo Villagelin afirma que os volunt\u00e1rios da unidade devem ser contactantes de pessoas com teste positivo para Covid-19. Em geral, podem ser familiares que moram nas mesmas casas, mas n\u00e3o podem ter tomado a vacina.<\/p>\n\n\n\n<p>&#8220;A transmiss\u00e3o da Covid \u00e9 muito alta de indiv\u00edduo para indiv\u00edduo e, geralmente, esse moradores mais pr\u00f3ximos, esses contactantes, s\u00e3o as pessoas mais infectadas quando a gente tem um caso de doen\u00e7a na fam\u00edlia&#8221;, explicou.<\/p>\n\n\n\n<p>&#8220;A ideia \u00e9 dar essa medica\u00e7\u00e3o e, com isso, essa pessoa que teve contato com o v\u00edrus, ela n\u00e3o vai desenvolver a doen\u00e7a. A gente j\u00e1 est\u00e1 conseguindo agir antes da doen\u00e7a aparecer&#8221;.<\/p>\n\n\n\n<p>Villagelin afirma que podem se voluntariar as pessoas que tiveram contato com o v\u00edrus em at\u00e9 cinco dias. Ap\u00f3s o pedido dos volunt\u00e1rios, os pesquisadores avaliam se eles se enquadram nos crit\u00e9rios para participar.<\/p>\n\n\n\n<p>G1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A farmac\u00eautica Pfizer iniciou, no Brasil, estudos cl\u00ednicos da p\u00edlula experimental Paxlovid, medicamento para tratamento contra a Covid-19 que gerou, em resultados preliminares, redu\u00e7\u00e3o de&hellip; <\/p>\n","protected":false},"author":6,"featured_media":234880,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[50],"tags":[],"class_list":["post-234879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/234879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=234879"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/234879\/revisions"}],"predecessor-version":[{"id":234881,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/234879\/revisions\/234881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/234880"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=234879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=234879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=234879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}