{"id":234901,"date":"2021-11-11T11:41:32","date_gmt":"2021-11-11T14:41:32","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=234901"},"modified":"2021-11-11T11:41:34","modified_gmt":"2021-11-11T14:41:34","slug":"mais-de-90-das-pessoas-que-recebem-auxilio-por-incapacidade-na-paraiba-nao-realizaram-pericia-e-podem-perder-beneficio","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2021\/11\/11\/mais-de-90-das-pessoas-que-recebem-auxilio-por-incapacidade-na-paraiba-nao-realizaram-pericia-e-podem-perder-beneficio\/","title":{"rendered":"Mais de 90% das pessoas que recebem aux\u00edlio por incapacidade na Para\u00edba n\u00e3o realizaram per\u00edcia e podem perder benef\u00edcio"},"content":{"rendered":"\n<p>Na Para\u00edba, 2.385 pessoas (92,44%)&nbsp;que recebem aux\u00edlio por incapacidade tempor\u00e1ria (antigo aux\u00edlio-doen\u00e7a)&nbsp;e que foram convocadas pelo Instituto Nacional do Seguro Social (INSS)&nbsp;ainda n\u00e3o realizaram a per\u00edcia m\u00e9dica. Uma lista com nomes foi&nbsp;<a href=\"https:\/\/www.in.gov.br\/en\/web\/dou\/-\/edital-de-convocacao-347888278\">divulgada no Di\u00e1rio Oficial da Uni\u00e3o (DOU)<\/a>&nbsp;em agosto deste ano. Aqueles que n\u00e3o realizarem o procedimento ter\u00e3o o benef\u00edcio suspenso.&nbsp;<\/p>\n\n\n\n<p>Somente no estado paraibano foram chamadas 2.580 pessoas, como apurou o ClickPB. At\u00e9 o momento, apenas 195 realizaram a per\u00edcia em uma das ag\u00eancias do INSS na Para\u00edba. Outras 11 pessoas j\u00e1 agendaram o procedimento, pois para passar pela per\u00edcia \u00e9 necess\u00e1rio agendar por meio do&nbsp;aplicativo &#8216;Meu INSS&#8217; ou site&nbsp;<a href=\"https:\/\/meu.inss.gov.br\/#\/login\">gov.br\/meuinss<\/a>. Al\u00e9m disso, \u00e9 poss\u00edvel ligar para a Central 135, que funciona de segunda a s\u00e1bado, das 7h \u00e0s 22h.<\/p>\n\n\n\n<p>De acordo com o INSS, na&nbsp;data agendada para a realiza\u00e7\u00e3o da per\u00edcia, os benefici\u00e1rios dever\u00e3o apresentar&nbsp;documentos pessoais, al\u00e9m de toda a documenta\u00e7\u00e3o m\u00e9dica que o segurado disponha como laudos com CID, atestados, receitas e exames recentes. O Instituto informou ainda que a&nbsp;partir do dia 19 de novembro, os segurados que ainda n\u00e3o agendaram poder\u00e3o ter seu benef\u00edcio suspenso.<\/p>\n\n\n\n<p>O diretor de Benef\u00edcios Substituto do INSS,&nbsp;Guilherme Serrano, informou que o&nbsp;objetivo \u00e9 de que os segurados compareceram para uma per\u00edcia revisional para avalia\u00e7\u00e3o do seu benef\u00edcio.&nbsp;\u201cEssa convoca\u00e7\u00e3o se estendeu ao longo de agosto. Aqueles que n\u00e3o compareceram e n\u00e3o tinham feito o&nbsp;agendamento, em 27 de setembro foram convocados por meio de edital que foi publicado no Di\u00e1rio Oficial da Uni\u00e3o. Agora, a partir de novembro, aqueles segurados que ainda n\u00e3o compareceram a per\u00edcia ou n\u00e3o realizaram agendamento ter\u00e3o o benef\u00edcio&nbsp;suspenso com o bloqueio do pagamento\u201d, informou.<\/p>\n\n\n\n<p>Em agosto, o INSS iniciou a\u00a0a revis\u00e3o dos benef\u00edcios por incapacidade tempor\u00e1ria mantidos sem per\u00edcia por per\u00edodo superior a seis meses e que n\u00e3o possuam data de cessa\u00e7\u00e3o estipulada ou indica\u00e7\u00e3o de reabilita\u00e7\u00e3o profissional atrav\u00e9s do PRBI, Programa de Revis\u00e3o dos Benef\u00edcios por Incapacidade.<\/p>\n\n\n\n<p>ClickPB<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na Para\u00edba, 2.385 pessoas (92,44%)&nbsp;que recebem aux\u00edlio por incapacidade tempor\u00e1ria (antigo aux\u00edlio-doen\u00e7a)&nbsp;e que foram convocadas pelo Instituto Nacional do Seguro Social (INSS)&nbsp;ainda n\u00e3o realizaram a&hellip; <\/p>\n","protected":false},"author":6,"featured_media":234902,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[104],"tags":[],"class_list":["post-234901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paraiba"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/234901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=234901"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/234901\/revisions"}],"predecessor-version":[{"id":234903,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/234901\/revisions\/234903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/234902"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=234901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=234901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=234901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}