{"id":235922,"date":"2021-11-29T09:08:44","date_gmt":"2021-11-29T12:08:44","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=235922"},"modified":"2021-11-29T09:08:44","modified_gmt":"2021-11-29T12:08:44","slug":"pix-saque-e-pix-troco-estao-disponiveis-a-partir-de-hoje","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2021\/11\/29\/pix-saque-e-pix-troco-estao-disponiveis-a-partir-de-hoje\/","title":{"rendered":"Pix Saque e Pix Troco est\u00e3o dispon\u00edveis a partir de hoje"},"content":{"rendered":"<p>A partir desta\u00a0segunda-feira (29)\u00a0passam a valer duas novas modalidades do Pix: Saque e Troco. Os usu\u00e1rios poder\u00e3o fazer\u00a0saques em locais como padarias, lojas de departamento e supermercados, n\u00e3o apenas em caixas eletr\u00f4nicos.<img decoding=\"async\" data-src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1429462&amp;o=node\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><img decoding=\"async\" data-src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1429462&amp;o=node\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/p>\n<p>Segundo o Banco Central (BC), a oferta dos dois novos produtos da ferramenta aos usu\u00e1rios \u00e9 opcional, cabendo a decis\u00e3o final aos estabelecimentos comerciais, \u00e0s empresas propriet\u00e1rias de redes de autoatendimento e \u00e0s institui\u00e7\u00f5es financeiras.<\/p>\n<h2>Pix Saque<\/h2>\n<p>O Pix Saque permitir\u00e1 que os clientes de qualquer institui\u00e7\u00e3o participante do sistema realizem saque em um dos pontos que ofertar o servi\u00e7o.<\/p>\n<p>Estabelecimentos comerciais, redes de caixas eletr\u00f4nicos compartilhados e participantes do Pix, por meio de seus servi\u00e7os de autoatendimento pr\u00f3prios, poder\u00e3o ofertar o servi\u00e7o. Para\u00a0ter\u00a0acesso aos recursos em esp\u00e9cie, o cliente far\u00e1 um Pix para o agente de saque, em din\u00e2mica similar \u00e0 de um Pix normal, a partir da leitura de um QR Code ou do aplicativo do prestador do servi\u00e7o.<\/p>\n<h2>Pix Troco<\/h2>\n<p>No Pix Troco, a din\u00e2mica \u00e9 praticamente id\u00eantica. A diferen\u00e7a \u00e9 que o saque de recursos em esp\u00e9cie pode ser feito durante o pagamento de uma compra ao estabelecimento. Nesse caso, o Pix \u00e9 feito pelo valor total, ou seja, da compra mais o saque. No extrato do cliente aparecer\u00e1 o valor correspondente ao saque e \u00e0 compra.<\/p>\n<h2>Limite<\/h2>\n<p>O limite m\u00e1ximo das transa\u00e7\u00f5es do Pix Saque e do Pix Troco ser\u00e1 de R$ 500,00 durante o dia, e de R$ 100,00 no per\u00edodo noturno (das 20h \u00e0s 6h). De acordo com o BC, haver\u00e1, no entanto, liberdade para que os ofertantes dos novos produtos do Pix trabalhem com limites inferiores a esses valores, caso considerem mais adequado aos seus fins.<\/p>\n<h2>Tarifas<\/h2>\n<p>De acordo com o BC, n\u00e3o haver\u00e1 cobran\u00e7a de tarifas para clientes pessoas naturais (pessoas f\u00edsicas e microempreendedores individuais) por parte da institui\u00e7\u00e3o detentora da conta de dep\u00f3sitos ou da conta de pagamento pr\u00e9-paga para a realiza\u00e7\u00e3o do Pix Saque ou do Pix Troco em at\u00e9 oito transa\u00e7\u00f5es mensais. A partir da nona transa\u00e7\u00e3o realizada por m\u00eas, as institui\u00e7\u00f5es financeiras ou de pagamentos detentoras da conta do usu\u00e1rio pagador podem cobrar uma tarifa pela transa\u00e7\u00e3o.<\/p>\n<p>O valor da tarifa cobrada \u00e9 de livre estabelecimento pela institui\u00e7\u00e3o e deve ser informado ao usu\u00e1rio pagador antes da etapa de confirma\u00e7\u00e3o da transa\u00e7\u00e3o. \u201cOs usu\u00e1rios nunca poder\u00e3o ser cobrados diretamente pelos agentes de saque\u201d, destacou a institui\u00e7\u00e3o.<\/p>\n<p>O BC explica ainda que os quatro saques tradicionais gratuitos realizados pelo usu\u00e1rio fora do \u00e2mbito do Pix Saque e Pix Troco podem ser descontados da franquia de gratuidades (oito por m\u00eas). Ou seja, se o usu\u00e1rio realizar um saque da sua conta, sem ser por meio do Pix Saque ou Pix Troco, esse saque poder\u00e1 ser contabilizado e sua franquia de gratuidades poder\u00e1 ser reduzida de oito para sete, a crit\u00e9rio da institui\u00e7\u00e3o.<\/p>\n<p>Para o com\u00e9rcio que disponibilizar o servi\u00e7o, as opera\u00e7\u00f5es do Pix Saque e do Pix Troco representar\u00e3o o recebimento de uma tarifa que pode variar de R$ 0,25 a R$ 0,95 por transa\u00e7\u00e3o, a depender da negocia\u00e7\u00e3o com a sua institui\u00e7\u00e3o de relacionamento.<\/p>\n<p>Ag\u00eancia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir desta\u00a0segunda-feira (29)\u00a0passam a valer duas novas modalidades do Pix: Saque e Troco. Os usu\u00e1rios poder\u00e3o fazer\u00a0saques em locais como padarias, lojas de departamento&hellip; <\/p>\n","protected":false},"author":6,"featured_media":235926,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[123],"tags":[],"class_list":["post-235922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/235922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=235922"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/235922\/revisions"}],"predecessor-version":[{"id":235927,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/235922\/revisions\/235927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/235926"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=235922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=235922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=235922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}