{"id":235946,"date":"2021-11-29T11:30:53","date_gmt":"2021-11-29T14:30:53","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=235946"},"modified":"2021-11-29T11:30:53","modified_gmt":"2021-11-29T14:30:53","slug":"prefeitura-de-monteiro-distribui-500-feiras-com-familias-cadastradas-no-programa-cesta-social","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2021\/11\/29\/prefeitura-de-monteiro-distribui-500-feiras-com-familias-cadastradas-no-programa-cesta-social\/","title":{"rendered":"Prefeitura de Monteiro distribui 500 feiras com fam\u00edlias cadastradas no Programa Cesta Social"},"content":{"rendered":"<p>A Secretaria de Desenvolvimento Social da Prefeitura de Monteiro realizou na tarde da \u00faltima sexta-feira, 26, \u00a0a distribui\u00e7\u00e3o de 500 feiras do Programa Cesta Social criado pela prefeita Anna Lorena, beneficiando fam\u00edlias que se encontram em situa\u00e7\u00e3o de vulnerabilidade social. Os trabalhos foram coordenados pela secret\u00e1ria Rosa Aleixo e sua equipe.<\/p>\n<p>Uma das benefici\u00e1rias, que tem dois filhos e mora no bairro Alto do Cemit\u00e9rio, disse que a feira chegou na hora que a mesma mais precisava. \u00a0\u201cEstou muito satisfeita com a atua\u00e7\u00e3o da prefeita \u00a0Lorena e desejo que Deus continue a aben\u00e7oando para que ela continue ajudando os mais carentes e fazendo o bem\u201d.<\/p>\n<p>Uma outra benefici\u00e1ria do Programa, residente no bairro Alto S\u00e3o Vicente, destacou a import\u00e2ncia da Cesta Social, principalmente nessa \u00e9poca de crise, afirmando que sem a feira ficaria mais dif\u00edcil de enfrentar a situa\u00e7\u00e3o e alimentar a fam\u00edlia. Minha Prefeita \u00e9 show, declarou a benefici\u00e1ria, manifestando o seu carinho e admira\u00e7\u00e3o pela gestora monteirense.<\/p>\n<p>O Programa Cesta Social foi criado e implementado pela prefeita Anna Lorena \u00a0antes da pandemia e se constitui um dos programas sociais de maior repercuss\u00e3o na regi\u00e3o do Cariri, enfatiza a secret\u00e1ria Rosa Aleixo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Desenvolvimento Social da Prefeitura de Monteiro realizou na tarde da \u00faltima sexta-feira, 26, \u00a0a distribui\u00e7\u00e3o de 500 feiras do Programa Cesta Social&hellip; <\/p>\n","protected":false},"author":6,"featured_media":235947,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[81],"tags":[],"class_list":["post-235946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-monteiro"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/235946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=235946"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/235946\/revisions"}],"predecessor-version":[{"id":235948,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/235946\/revisions\/235948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/235947"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=235946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=235946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=235946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}