{"id":236070,"date":"2021-12-01T08:36:10","date_gmt":"2021-12-01T11:36:10","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=236070"},"modified":"2021-12-01T08:36:10","modified_gmt":"2021-12-01T11:36:10","slug":"mega-sena-pode-pagar-r-12-milhoes-nesta-quarta-feira-2","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2021\/12\/01\/mega-sena-pode-pagar-r-12-milhoes-nesta-quarta-feira-2\/","title":{"rendered":"Mega-Sena pode pagar R$ 12 milh\u00f5es nesta quarta-feira"},"content":{"rendered":"<p>O concurso 2.433 da Mega-Sena pode pagar um pr\u00eamio de R$ 12 milh\u00f5es para quem acertar as seis dezenas. O sorteio ocorre \u00e0s 20h desta quarta-feira (1\u00ba) no Espa\u00e7o Loterias Caixa, no terminal Rodovi\u00e1rio Tiet\u00ea, na cidade de S\u00e3o Paulo. A aposta m\u00ednima custa R$ 4,50 e pode ser realizada tamb\u00e9m pela internet at\u00e9 19h.<\/p>\n<p>Para apostar na Mega-Sena<br \/>\nAs apostas podem ser feitas at\u00e9 as 19h (hor\u00e1rio de Bras\u00edlia), em qualquer lot\u00e9rica do pa\u00eds ou pela internet, no site da Caixa Econ\u00f4mica Federal \u2013 acess\u00edvel por celular, computador ou outros dispositivos. \u00c9 necess\u00e1rio fazer um cadastro, ser maior de idade (18 anos ou mais) e preencher o n\u00famero do cart\u00e3o de cr\u00e9dito.<\/p>\n<p>Probabilidades<br \/>\nA probabilidade de vencer em cada concurso varia de acordo com o n\u00famero de dezenas jogadas e do tipo de aposta realizada. Para a aposta simples, com apenas seis dezenas, com pre\u00e7o de R$ 4,50, a probabilidade de ganhar o pr\u00eamio milion\u00e1rio \u00e9 de 1 em 50.063.860, segundo a Caixa.<\/p>\n<p>J\u00e1 para uma aposta com 15 dezenas (limite m\u00e1ximo), com o pre\u00e7o de R$ 22.522,50, a probabilidade de acertar o pr\u00eamio \u00e9 de 1 em 10.003, ainda segundo a Caixa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O concurso 2.433 da Mega-Sena pode pagar um pr\u00eamio de R$ 12 milh\u00f5es para quem acertar as seis dezenas. O sorteio ocorre \u00e0s 20h desta&hellip; <\/p>\n","protected":false},"author":6,"featured_media":236071,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-236070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/236070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=236070"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/236070\/revisions"}],"predecessor-version":[{"id":236072,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/236070\/revisions\/236072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/236071"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=236070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=236070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=236070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}