{"id":244392,"date":"2022-04-04T11:14:31","date_gmt":"2022-04-04T14:14:31","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=244392"},"modified":"2022-04-04T11:14:31","modified_gmt":"2022-04-04T14:14:31","slug":"prefeitura-de-caraubas-inicia-inscricoes-para-o-uso-do-novo-mercado-publico-do-municipio-saiba-como-fazer","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2022\/04\/04\/prefeitura-de-caraubas-inicia-inscricoes-para-o-uso-do-novo-mercado-publico-do-municipio-saiba-como-fazer\/","title":{"rendered":"Prefeitura de Cara\u00fabas inicia inscri\u00e7\u00f5es para o uso do novo Mercado P\u00fablico do munic\u00edpio; saiba como fazer"},"content":{"rendered":"<p>Est\u00e3o abertas a partir desta segunda-feira (04), as inscri\u00e7\u00f5es para as pessoas interessadas em comercializar no novo Mercado P\u00fablico Municipal Manoel Clementino Neves, na cidade de Cara\u00fabas. A Secretaria da Administra\u00e7\u00e3o e do Planejamento, lan\u00e7ou edital na \u00faltima sexta-feira, que foi submetido ao Conselho Municipal do Turismo, da Cultura e do Desporto para aprova\u00e7\u00e3o.<\/p>\n<p>De acordo com o edital as inscri\u00e7\u00f5es devem ser realizadas no per\u00edodo de 4 a 8 de Abril, no hor\u00e1rio comercial das 7h30min \u00e1s 12h e das 14h \u00e0s 17h na sala do empreendedor situada na secretaria da Administra\u00e7\u00e3o no pr\u00e9dio sede do Centro Administrativo Municipal. J\u00e1 no per\u00edodo de 11 a 14 de Abril acontecer\u00e1 as entrevistas presenciais que far\u00e3o parte do processo de sele\u00e7\u00e3o.<\/p>\n<p>As fichas de inscri\u00e7\u00e3o ser\u00e3o disponibilizadas inicialmente para a forma presencial, mais tamb\u00e9m ser\u00e3o disponibilizadas de forma remota no site oficial da Prefeitura Municipal de Cara\u00fabas no endere\u00e7o eletr\u00f4nico caraubas.pb.gov.br. J\u00e1 no per\u00edodo de 18 a 22 de Abril ser\u00e1 o per\u00edodo onde os comerciantes selecionados ir\u00e3o passar por uma capacita\u00e7\u00e3o e assinatura do contrato de concess\u00e3o de uso da \u00e1rea.<\/p>\n<p>Na nova estrutura do Mercado P\u00fablico ser\u00e3o disponibilizadas 38 (trinta e oito) novas lojas, sendo 04 (quatro) na pra\u00e7a de alimenta\u00e7\u00e3o, 16 (Dezesseis) para o setor de carnes, frios e hortifrutigranjeiros, bem como, 18 (dezoito) para o setor de artesanato local, vestu\u00e1rio e afins. No novo espa\u00e7o tamb\u00e9m ser\u00e3o entregues baterias de sanit\u00e1rios masculino e feminino e para portadores de necessidades especiais.<\/p>\n<p>O novo Mercado P\u00fablico Municipal Manoel Clementino das Neves ser\u00e1 inaugurado em 6 de maio, durante a programa\u00e7\u00e3o de anivers\u00e1rio dos 25 anos da Emancipa\u00e7\u00e3o Pol\u00edtica do munic\u00edpio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e3o abertas a partir desta segunda-feira (04), as inscri\u00e7\u00f5es para as pessoas interessadas em comercializar no novo Mercado P\u00fablico Municipal Manoel Clementino Neves, na cidade&hellip; <\/p>\n","protected":false},"author":6,"featured_media":244393,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[73],"tags":[],"class_list":["post-244392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caraubas"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/244392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=244392"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/244392\/revisions"}],"predecessor-version":[{"id":244394,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/244392\/revisions\/244394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/244393"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=244392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=244392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=244392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}