{"id":248414,"date":"2022-06-06T07:13:41","date_gmt":"2022-06-06T10:13:41","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=248414"},"modified":"2022-06-06T07:13:41","modified_gmt":"2022-06-06T10:13:41","slug":"mundo-registra-780-casos-de-variola-dos-macacos-fora-da-africa","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2022\/06\/06\/mundo-registra-780-casos-de-variola-dos-macacos-fora-da-africa\/","title":{"rendered":"Mundo registra 780 casos de var\u00edola dos macacos fora da \u00c1frica"},"content":{"rendered":"<p>A\u00a0Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS)\u00a0informou neste domingo (5) que j\u00e1 foram confirmados 780 casos de\u00a0var\u00edola dos macacos\u00a0em todo mundo.<\/p>\n<p>O n\u00famero corresponde ao intervalo entre 13 de maio e 2 de junho e contabiliza apenas pacientes identificados em locais onde a doen\u00e7a n\u00e3o \u00e9 end\u00eamica. Segundo a organiza\u00e7\u00e3o, investiga\u00e7\u00f5es epidemiol\u00f3gicas est\u00e3o em curso.<\/p>\n<p>&#8220;A repentina e inesperada apari\u00e7\u00e3o de var\u00edola dos macacos simultaneamente em variados pa\u00edses onde a doen\u00e7a n\u00e3o \u00e9 end\u00eamica sugere a possibilidade de transmiss\u00e3o desconhecida j\u00e1 por algum tempo, seguida de eventos recentes que espalharam o v\u00edrus&#8221;, afirmou a OMS.<\/p>\n<p>At\u00e9 2 de junho, a var\u00edola dos macacos j\u00e1 havia chegado a 27 pa\u00edses fora da \u00c1frica e n\u00e3o h\u00e1 qualquer registro de morte em decorr\u00eancia da doen\u00e7a nestes locais.<\/p>\n<p>Nas regi\u00f5es onde a var\u00edola dos macacos \u00e9 end\u00eamica, no entanto, houve 66 mortes desde o in\u00edcio do ano &#8211; a maioria delas, concentrada na Rep\u00fablica Democr\u00e1tica do Congo, onde 58 pessoas morreram.<\/p>\n<p>Os Centros de Preven\u00e7\u00e3o e Controle de Doen\u00e7as (CDC, na sigla em ingl\u00eas), dos Estados Unidos (EUA), afirmaram contabilizar 700 casos em todo o mundo, 21 deles no pr\u00f3prio pa\u00eds. A informa\u00e7\u00e3o \u00e9 da Ag\u00eancia France Presse (AFP).<\/p>\n<p>&#8220;H\u00e1 alguns casos nos EUA que sabemos que est\u00e3o vinculados a outros casos conhecidos&#8221;, afirmou a vice-diretora do departamento de Pat\u00f3genos e Patologia de Alta Consequ\u00eancia do CDC, Jennifer McQuiston. &#8220;Al\u00e9m disso, h\u00e1 pelo menos um caso nos EUA que n\u00e3o est\u00e1 relacionado a viagens e do qual n\u00e3o sabemos como foi adquirida a infec\u00e7\u00e3o&#8221;, disse.<\/p>\n<p>A exce\u00e7\u00e3o \u00e9 de um paciente que n\u00e3o tem qualquer rela\u00e7\u00e3o com outras transmiss\u00f5es.<\/p>\n<p>g1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A\u00a0Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS)\u00a0informou neste domingo (5) que j\u00e1 foram confirmados 780 casos de\u00a0var\u00edola dos macacos\u00a0em todo mundo. O n\u00famero corresponde ao intervalo entre&hellip; <\/p>\n","protected":false},"author":6,"featured_media":248415,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[50,103,16],"tags":[],"class_list":["post-248414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-mundo","category-saude"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/248414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=248414"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/248414\/revisions"}],"predecessor-version":[{"id":248416,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/248414\/revisions\/248416"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/248415"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=248414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=248414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=248414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}