{"id":252065,"date":"2022-08-04T11:54:15","date_gmt":"2022-08-04T14:54:15","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=252065"},"modified":"2022-08-04T11:54:15","modified_gmt":"2022-08-04T14:54:15","slug":"apos-volta-do-recesso-parlamentar-camara-de-sao-joao-do-tigre-realiza-sessao-ordinaria-e-debate-assuntos-de-interesse-da-populacao","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2022\/08\/04\/apos-volta-do-recesso-parlamentar-camara-de-sao-joao-do-tigre-realiza-sessao-ordinaria-e-debate-assuntos-de-interesse-da-populacao\/","title":{"rendered":"Ap\u00f3s volta do recesso parlamentar, C\u00e2mara de S\u00e3o Jo\u00e3o do Tigre realiza sess\u00e3o ordin\u00e1ria e debate assuntos de interesse da popula\u00e7\u00e3o"},"content":{"rendered":"<p>A C\u00e2mara de S\u00e3o Jo\u00e3o do Tigre retornou do recesso parlamentar e realizou na manh\u00e3 desta quinta-feira (04), mais uma sess\u00e3o ordin\u00e1ria. Na oportunidade, os parlamentares debateram v\u00e1rios temas de interesse da popula\u00e7\u00e3o tigrense, e propuseram requerimentos verbais em benef\u00edcio dos mun\u00edcipes.<\/p>\n<p>O presidente da casa, vereador Arn\u00f3bio Pereira, falou sobre a sess\u00e3o desta quinta e afirmou sobre o compromisso da casa em defender os interesses da popula\u00e7\u00e3o de S\u00e3o Jo\u00e3o do Tigre.<\/p>\n<p>\u201cHoje retornanamos do recesso parlamentar e realizamos mais uma sess\u00e3o ordin\u00e1ria, onde discutimos diversos temas de interesse da popula\u00e7\u00e3o, e a propusermos requerimentos verbais em benef\u00edcio dos mun\u00edcipes,\u201d disse.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter lazyload\" data-src=\"https:\/\/scontent.fjpa4-1.fna.fbcdn.net\/v\/t1.15752-9\/297559978_747876502996820_924263313998395823_n.jpg?_nc_cat=106&amp;ccb=1-7&amp;_nc_sid=ae9488&amp;_nc_eui2=AeGGnGRlrdrGAZN2U5IT2Sfpr7u7kRRRjgyvu7uRFFGODHv0TEc7Y0YETTizD7PvovUWrv0cYYQMQjLpkbPz_l7q&amp;_nc_ohc=_nMF9wymT4oAX-u3o7u&amp;_nc_oc=AQlgqR1RxBmvxIAVIbAqP5CKFU1h8fn664RzpleTKykwPAK-_A3Cb0quJHcdqaqFkx8uwwp4zfPwTbWWn-MiWtGL&amp;_nc_ht=scontent.fjpa4-1.fna&amp;oh=03_AVKXKZn_ncy8T6pY3uSonL2OCsLTrvt1xINDYymDv25UjQ&amp;oe=6311323F\" alt=\"Nenhuma descri\u00e7\u00e3o dispon\u00edvel.\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p><strong>CARIRI EM A\u00c7\u00c3O<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara de S\u00e3o Jo\u00e3o do Tigre retornou do recesso parlamentar e realizou na manh\u00e3 desta quinta-feira (04), mais uma sess\u00e3o ordin\u00e1ria. Na oportunidade, os&hellip; <\/p>\n","protected":false},"author":6,"featured_media":252066,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[89],"tags":[],"class_list":["post-252065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sao-joao-do-tigre"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/252065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=252065"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/252065\/revisions"}],"predecessor-version":[{"id":252067,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/252065\/revisions\/252067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/252066"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=252065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=252065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=252065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}