{"id":25615,"date":"2017-08-08T09:13:19","date_gmt":"2017-08-08T12:13:19","guid":{"rendered":"http:\/\/caririemacao.com\/1\/?p=25615"},"modified":"2017-08-08T09:13:19","modified_gmt":"2017-08-08T12:13:19","slug":"setembro-sera-um-bom-momento-para-analisar-meta-fiscal-diz-meirelles","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2017\/08\/08\/setembro-sera-um-bom-momento-para-analisar-meta-fiscal-diz-meirelles\/","title":{"rendered":"Setembro &#8216;ser\u00e1 um bom momento&#8217; para analisar meta fiscal, diz Meirelles"},"content":{"rendered":"<article>\n<div class=\"mc-column content-media content-media--normal content-photo\" data-block-type=\"backstage-photo\">O ministro da Fazenda, Henrique Meirelles, voltou a dizer nesta segunda-feira (7) que o governo est\u00e1 &#8220;estudando&#8221; uma poss\u00edvel revis\u00e3o da\u00a0meta fiscal, e disse que o m\u00eas de setembro &#8220;ser\u00e1 um bom momento&#8221; para avaliar a necessidade de mudar ou n\u00e3o a previs\u00e3o dos resultados das contas p\u00fablicas para este ano.<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"49\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">&#8220;N\u00e3o h\u00e1 um prazo definido&#8221;, disse ele ao ser questionado por jornalistas sobre quando haver\u00e1 uma defini\u00e7\u00e3o para a meta fiscal, atualmente estabelecida em um rombo de R$ 139 bilh\u00f5es. &#8220;N\u00f3s vamos analisar. Certamente, no relat\u00f3rio bimestral fiscal de setembro ser\u00e1 um bom momento para n\u00f3s avaliarmos essa situa\u00e7\u00e3o.&#8221;<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"71\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A declara\u00e7\u00e3o foi dada pelo ministro ap\u00f3s participar de um evento em S\u00e3o Paulo. Mais uma vez, ele disse que uma poss\u00edvel revis\u00e3o da meta fiscal seria fruto da frustra\u00e7\u00e3o de receitas do governo. No entanto, o ministro afirmou que espera uma recupera\u00e7\u00e3o das arrecada\u00e7\u00e3o nos pr\u00f3ximos meses, com a retomada da atividade da economia e com a ades\u00e3o das empresas ao programa de refinanciamento de d\u00edvidas (Refis) com o governo<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"25\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O ministro voltou a dizer que o\u00a0governo vai apresentar um novo Refis, ap\u00f3s o Congresso fazer mudan\u00e7as no anterior e reduzir o montante arrecadado.<\/p>\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Governo prepara novo projeto para o Refis<\/p>\n<\/div>\n<div class=\"mc-column content-media content-media--normal content-video\" data-block-type=\"backstage-video\">\n<div class=\"content-media__container content-media__container--loaded\">\n<div class=\"content-video__height\"><strong>Impostos<\/strong><\/div>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"40\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Na semana passada, o\u00a0aumento dos impostos sobre os combust\u00edveisfoi novamente suspenso por decis\u00e3o judicial. Questionado se o governo pretende aumentar outros impostos, Meirelles disse que est\u00e1 &#8220;trabalhando com a hip\u00f3tese de que vai prevalecer a decis\u00e3o do aumento&#8221;.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"29\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Ele defendeu que a Advocacia Geral da Uni\u00e3o (AGU) &#8220;est\u00e1 bastante s\u00f3lida na sua argumenta\u00e7\u00e3o&#8221;. &#8220;J\u00e1 houve a suspens\u00e3o de algumas liminares. Isso \u00e9 normal, faz parte da democracia.&#8221;<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"20\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">&#8220;N\u00f3s acreditamos que isso vai prevalecer e n\u00e3o ser\u00e3o necess\u00e1rias outras taxas, outros impostos que venham a substituir isso&#8221;, resumiu.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"55\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Em seguida, Meirelles foi questionado sobre um poss\u00edvel pacote de aumento de impostos para 2018. &#8220;Olha, o governo hoje (&#8230;) est\u00e1 sempre pensando em coisas o tempo todo&#8221;, respondeu. &#8220;Mas eu tenho uma posi\u00e7\u00e3o muito firme a esse tipo de coisa em geral: quando \u00e9 tomada uma decis\u00e3o, eu anuncio a decis\u00e3o. N\u00e3o ficamos especulando.&#8221;<\/p>\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><strong>&#8216;Ciclo de reformas&#8217;<\/strong><\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"45\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Meirelles disse que a previs\u00e3o do governo \u00e9 terminar o &#8220;ciclo de reformas&#8221; ainda neste ano, incluindo, al\u00e9m do\u00a0teto para os gastos p\u00fablicos\u00a0e\u00a0reforma trabalhista, j\u00e1 aprovados pelo Congresso, a\u00a0reforma da Previd\u00eancia, em tramita\u00e7\u00e3o, e a tribut\u00e1ria, que ainda n\u00e3o foi apresentada.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"44\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O ministro falou ainda sobre a reforma pol\u00edtica. &#8220;Evidentemente, tamb\u00e9m se discute a\u00a0reforma pol\u00edtica&#8221;, disse. &#8220;Ela tem prazos importantes e relativamente curtos para ter validade em 2018. Ent\u00e3o, ela dever\u00e1 ser decidida rapidamente e ser votada nos pr\u00f3ximos pouco mais de 30 dias&#8221;.<\/p>\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><strong>Reonera\u00e7\u00e3o da folha<\/strong><\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"27\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Meirelles afirmou que a reonera\u00e7\u00e3o da folha de pagamento ser\u00e1 apresentada como Projeto de Lei ao Congresso em regime de urg\u00eancia, &#8220;exatamente pelo vencimento da medida provis\u00f3ria&#8221;.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"8\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">&#8220;Esperamos que seja aprovada o mais r\u00e1pido poss\u00edvel.&#8221;<\/p>\n<p><strong>CARIRI EM A\u00c7\u00c3O<\/strong><\/p>\n<p><em>Com G1 \/Foto: Google<\/em><\/p>\n<p><strong>Leia mais not\u00edcias em\u00a0<\/strong><a href=\"http:\/\/www.caririemacao.com\/\"><strong>caririemacao.com<\/strong><\/a><strong>, siga nossa p\u00e1gina no\u00a0<\/strong><a href=\"https:\/\/www.facebook.com\/CaririEmAcao\/?ref=aymt_homepage_panel\"><strong>Facebook<\/strong><\/a>,<strong>\u00a0<\/strong><a href=\"https:\/\/www.instagram.com\/cariri_em_acao\/?hl=pt-br\"><strong>Instagram<\/strong><\/a><strong>\u00a0e <\/strong><a href=\"https:\/\/www.youtube.com\/channel\/UCAptA0jQuYQy8vMhLt2m4qg\"><strong>Youtube<\/strong><\/a><strong>\u00a0e veja nossas mat\u00e9rias, v\u00eddeos e fotos. Voc\u00ea tamb\u00e9m pode enviar informa\u00e7\u00f5es \u00e0 Reda\u00e7\u00e3o do Portal Cariri em A\u00e7\u00e3o pelo WhatsApp (83) 9 9634.5791, (83) 9 9601-1162.<\/strong><\/p>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>O ministro da Fazenda, Henrique Meirelles, voltou a dizer nesta segunda-feira (7) que o governo est\u00e1 &#8220;estudando&#8221; uma poss\u00edvel revis\u00e3o da\u00a0meta fiscal, e disse que&hellip; <\/p>\n","protected":false},"author":2,"featured_media":25616,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[11],"tags":[],"class_list":["post-25615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/25615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=25615"}],"version-history":[{"count":0,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/25615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/25616"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=25615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=25615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=25615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}