{"id":25646,"date":"2017-08-08T10:35:16","date_gmt":"2017-08-08T13:35:16","guid":{"rendered":"http:\/\/caririemacao.com\/1\/?p=25646"},"modified":"2017-08-08T10:35:16","modified_gmt":"2017-08-08T13:35:16","slug":"chapecoense-e-goleada-mas-sai-feliz-de-jogo-com-barcelona","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2017\/08\/08\/chapecoense-e-goleada-mas-sai-feliz-de-jogo-com-barcelona\/","title":{"rendered":"Chapecoense \u00e9 goleada, mas sai feliz de jogo com Barcelona"},"content":{"rendered":"<p>A goleada de 5&#215;0 foi o que menos importou para a Chapecoense nesta segunda-feira (7), na disputa do Trof\u00e9u Joan Gamper com o Barcelona, no Est\u00e1dio Nou Camp, na capital da Catalunha, na Espanha. O time catarinense, mesmo perdendo, ficou honrado com as homenagens recebidas de um dos clubes mais poderosos do mundo, financeira e esportivamente, e no qual, at\u00e9 a semana passada jogava Neymar, o maior craque brasileiro da atualidade e tamb\u00e9m o mais caro do mundo, cuja transfer\u00eancia para o Paris Saint Germain, da Fran\u00e7a, custou 222 milh\u00f5es de euros (R$ 818 milh\u00f5es), s\u00f3 de multa resciss\u00f3ria paga ao Barcelona.\u00a0<strong><a href=\"http:\/\/portalcorreio.com.br\/esportes\" target=\"_blank\" rel=\"noopener\"><br \/>\n<\/a><\/strong><br \/>\nO jogo foi decidido logo no primeiro tempo, quando o Barcelona fez 3&#215;0, gols de Deulofeu, Busquets e Messi. Na segunda etapa, Luiz Su\u00e1rez e Denis Su\u00e1rez fecharam o placar e o goleiro Artur Moraes ainda defendeu um p\u00eanalti, cobrado por Alc\u00e1cer. O substituto de Neymar foi Deulofeu, jogador revelado pelo Barcelona e que atuou em v\u00e1rios clubes da Europa antes de retornar ao clube este ano para a temporada 2017\/18.<\/p>\n<p>O Trof\u00e9u Joan Gamper homenageia o fundador do Barcelona, nascido na cidade su\u00ed\u00e7a de Winterthur e que, na verdade, era Hans-Max Gamper Haessig, mas que ficou conhecido na Catalunha pelo nome espanhol, Joan. Ele praticou diversas modalidades esportivas, mas, principalmente, o futebol.<\/p>\n<p>O Trof\u00e9u Joan Gamper foi criado na d\u00e9cada de 1960 pelo Barcelona e, inicialmente tinha a participa\u00e7\u00e3o de quatro clubes, mas nos \u00faltimos anos passou a ser disputado em partida \u00fanica.<\/p>\n<p>O Internacional foi o \u00fanico clube brasileiro que venceu a disputa. Este ano, a Chapecoense foi convidada, numa homenagem do Barcelona \u00e0 equipe catarinense ap\u00f3s o acidente a\u00e9reo de 29 de novembro de 2016, na Col\u00f4mbia, em que morreram 71 pessoas, incluindo quase toda a equipe de Chapec\u00f3 (SC), que seguia para jogar a final da Copa Sul-Americana em Medellin.<\/p>\n<p>A partida desta segunda-feira foi a primeira do Barcelona em seu est\u00e1dio na temporada 2017\/2018, que ir\u00e1 at\u00e9 agosto do pr\u00f3ximo ano. Desde o in\u00edcio, um clima de emo\u00e7\u00e3o marcou o encontro dos brasileiros com a equipe de Messi, Lu\u00eds Su\u00e1rez e outros craques do futebol mundial.<\/p>\n<p>Um dos momentos mais emocionantes envolveu os tr\u00eas jogadores que sobreviveram ao acidente e foram aplaudidos pelo p\u00fablico ao entrarem em campo: Alan Ruschell, lateral esquerdo que, pela primeira vez depois do acidente voltou a disputar uma partida de futebol; o zagueiro Neto, que ficou no banco, e o ex-goleiro Jackson Follman, que perdeu parte de uma perna no acidente a\u00e9reo e agora \u00e9 funcion\u00e1rio da Chapecoense. Aos 35 minutos de jogo, Ruschell foi substitu\u00eddo por Penilla e no intervalo trocou a camisa com Messi.<\/p>\n<p>A Chapecoense segue agora para a Fran\u00e7a, onde far\u00e1 um jogo treino com o Lyon, depois far\u00e1 um jogo no Jap\u00e3o, contra o campe\u00e3o japon\u00eas, em disputa pelo Trof\u00e9u Suruga, e poder\u00e1 ir a Roma e ser recebida pelo Papa Francisco, que \u00e9 um f\u00e3 do futebol e torcedor fervoroso do San Lorenzo de Almagro, da Argentina, sua p\u00e1tria.<\/p>\n<p><strong>CARIRI EM A\u00c7\u00c3O<\/strong><\/p>\n<p><em>Com Ag\u00eancia Brasil\/Foto:Reprodu\u00e7\u00e3o\/Instagram\/chapecoensereal<\/em><\/p>\n<p><strong>Leia mais not\u00edcias em\u00a0<a href=\"http:\/\/www.caririemacao.com\/\">caririemacao.com<\/a>, siga nossa p\u00e1gina no\u00a0<a href=\"https:\/\/www.facebook.com\/CaririEmAcao\/?ref=aymt_homepage_panel\">Facebook<\/a>,\u00a0<a href=\"https:\/\/www.instagram.com\/cariri_em_acao\/?hl=pt-br\">Instagram<\/a>\u00a0e <a href=\"https:\/\/www.youtube.com\/channel\/UCAptA0jQuYQy8vMhLt2m4qg\">Youtube<\/a>\u00a0e veja nossas mat\u00e9rias, v\u00eddeos e fotos. Voc\u00ea tamb\u00e9m pode enviar informa\u00e7\u00f5es \u00e0 Reda\u00e7\u00e3o do Portal Cariri em A\u00e7\u00e3o pelo WhatsApp (83) 9 9634.5791, (83) 9 9601-1162.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A goleada de 5&#215;0 foi o que menos importou para a Chapecoense nesta segunda-feira (7), na disputa do Trof\u00e9u Joan Gamper com o Barcelona, no&hellip; <\/p>\n","protected":false},"author":2,"featured_media":25647,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-25646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/25646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=25646"}],"version-history":[{"count":0,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/25646\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/25647"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=25646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=25646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=25646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}