{"id":256984,"date":"2022-09-26T10:21:14","date_gmt":"2022-09-26T13:21:14","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=256984"},"modified":"2022-09-26T10:21:14","modified_gmt":"2022-09-26T13:21:14","slug":"campanha-de-vacinacao-contra-a-polio-termina-nesta-sexta-feira","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2022\/09\/26\/campanha-de-vacinacao-contra-a-polio-termina-nesta-sexta-feira\/","title":{"rendered":"Campanha de vacina\u00e7\u00e3o contra a p\u00f3lio termina nesta sexta-feira"},"content":{"rendered":"<h3 class=\"col-10 offset-1 animated fadeInDown dealy-900 display-8 display-md-8 alt-font font-italic my-1 text-center\">Campanha inclui imunizantes contra outras doen\u00e7as preven\u00edveis<\/h3>\n<p>A Campanha Nacional de Vacina\u00e7\u00e3o contra a Poliomielite e Multivacina\u00e7\u00e3o termina na pr\u00f3xima sexta-feira (30). A proposta \u00e9 refor\u00e7ar as coberturas vacinais contra a p\u00f3lio e outras doen\u00e7as que podem ser prevenidas, al\u00e9m de evitar a reintrodu\u00e7\u00e3o de v\u00edrus que j\u00e1 foram eliminados do pa\u00eds.<img decoding=\"async\" data-src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1484291&amp;o=node\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><img decoding=\"async\" data-src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1484291&amp;o=node\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/p>\n<p>A campanha\u00a0<a href=\"https:\/\/agenciabrasil.ebc.com.br\/saude\/noticia\/2022-09\/baixa-adesao-leva-saude-prorrogar-campanha-nacional-de-vacinacao\" target=\"_blank\" rel=\"noopener\">chegou a ser prorrogada<\/a>\u00a0pelo Minist\u00e9rio da Sa\u00fade por conta da baixa ades\u00e3o. As doses est\u00e3o dispon\u00edveis em mais de 40 mil pontos de vacina\u00e7\u00e3o. A meta da pasta \u00e9 imunizar contra a p\u00f3lio 95% do p\u00fablico-alvo, formado por 14,3 milh\u00f5es de crian\u00e7as menores de 5 anos.<\/p>\n<p>Crian\u00e7as de 1 a 4 anos devem receber uma dose da Vacina Oral Poliomielite (VOP), desde que j\u00e1 tenham recebido as tr\u00eas doses da Vacina Inativada Poliomielite (VIP) previstas no esquema b\u00e1sico. At\u00e9 o \u00faltimo s\u00e1bado (24), 6 milh\u00f5es de doses contra a p\u00f3lio haviam sido aplicadas durante a campanha.<\/p>\n<h2>Multivacina\u00e7\u00e3o<\/h2>\n<p>Para a campanha de multivacina\u00e7\u00e3o, as doses dispon\u00edveis s\u00e3o: Hepatite A e B, Penta (DTP\/Hib\/Hep B), Pneumoc\u00f3cica 10 valente, VRH (Vacina Rotav\u00edrus Humano), Meningoc\u00f3cica C (conjugada), Febre amarela, Tr\u00edplice viral (Sarampo, Rub\u00e9ola, Caxumba), Tetraviral (Sarampo, Rub\u00e9ola, Caxumba, Varicela), DTP (tr\u00edplice bacteriana), Varicela e HPV quadrivalente (Papilomav\u00edrus Humano).<\/p>\n<p>Entre adolescentes com idade at\u00e9 15 anos, est\u00e3o dispon\u00edveis as vacinas HPV, dT (dupla adulto), Febre amarela, Tr\u00edplice viral, Hepatite B, dTpa e Meningoc\u00f3cica ACWY (conjugada). O minist\u00e9rio refor\u00e7a que todos os imunizantes que integram o Programa Nacional de Imuniza\u00e7\u00f5es (PNI) s\u00e3o seguros e foram aprovados pela Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa).<\/p>\n<h2>Covid-19<\/h2>\n<p>A Campanha Nacional de Vacina\u00e7\u00e3o contra a Poliomielite e Multivacina\u00e7\u00e3o coincide com a imuniza\u00e7\u00e3o contra a covid-19, j\u00e1 em andamento no pa\u00eds. Segundo a pasta, as vacinas contra a covid-19 podem ser administradas, em crian\u00e7as a partir de 3 anos, de maneira simult\u00e2nea ou com qualquer intervalo com as demais vacinas que integram o calend\u00e1rio nacional.<\/p>\n<p>\u201cA atualiza\u00e7\u00e3o da situa\u00e7\u00e3o vacinal aumenta a prote\u00e7\u00e3o contra as doen\u00e7as imunopreven\u00edveis, evitando a ocorr\u00eancia de surtos e hospitaliza\u00e7\u00f5es, sequelas, tratamentos de reabilita\u00e7\u00e3o e \u00f3bitos\u201d, refor\u00e7ou o minist\u00e9rio.<\/p>\n<p>FONTE: Ag\u00eancia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Campanha inclui imunizantes contra outras doen\u00e7as preven\u00edveis A Campanha Nacional de Vacina\u00e7\u00e3o contra a Poliomielite e Multivacina\u00e7\u00e3o termina na pr\u00f3xima sexta-feira (30). A proposta \u00e9&hellip; <\/p>\n","protected":false},"author":6,"featured_media":256985,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[50,16],"tags":[],"class_list":["post-256984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-saude"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/256984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=256984"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/256984\/revisions"}],"predecessor-version":[{"id":256986,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/256984\/revisions\/256986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/256985"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=256984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=256984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=256984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}