{"id":257189,"date":"2022-09-29T06:51:40","date_gmt":"2022-09-29T09:51:40","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=257189"},"modified":"2022-09-29T06:51:40","modified_gmt":"2022-09-29T09:51:40","slug":"mega-sena-acumula-e-pagara-r-300-milhoes-no-sabado","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2022\/09\/29\/mega-sena-acumula-e-pagara-r-300-milhoes-no-sabado\/","title":{"rendered":"Mega-Sena acumula e pagar\u00e1 R$ 300 milh\u00f5es no s\u00e1bado"},"content":{"rendered":"<p><strong>O concurso 2525, no s\u00e1bado (1\u00ba), dever\u00e1 pagar R$ 300 milh\u00f5es, segundo a estimativa da Caixa Econ\u00f4mica Federal.<\/strong><\/p>\n<p>Mais uma vez n\u00e3o houve ganhador do pr\u00eamio principal da Mega-Sena. O concurso 2524 foi sorteado na noite desta quarta-feira (28), com o valor total de R$ 201.900.503,81 para quem acertasse as seis dezenas. No entanto, sem acertador, o concurso 2525, no s\u00e1bado (1\u00ba), dever\u00e1 pagar R$ 300 milh\u00f5es, segundo a estimativa da Caixa Econ\u00f4mica Federal.<\/p>\n<p>Os n\u00fameros sorteados no Espa\u00e7o da Sorte, em S\u00e3o Paulo, foram: 03 &#8211; 20 &#8211; 22 &#8211; 37 &#8211; 41 &#8211; 43.<\/p>\n<p>De acordo com a Caixa, 404 apostas tiveram cinco acertos e v\u00e3o levar R$ 43.914,62 cada uma. Outros 30.194 apostadores fizeram a quadra e v\u00e3o ganhar um pr\u00eamio de R$ 839,40 cada.<\/p>\n<p>A aposta simples para a Mega-Sena custa R$ 4,50 e pode ser feita em uma casa lot\u00e9rica ou pela internet, por meio do aplicativo Loterias Caixa ou pelo site de loterias da Caixa.<\/p>\n<p>A probabilidade de acerto para quem faz uma aposta de seis n\u00fameros (no valor de R$ 4,50) da Mega-Sena \u00e9 de uma em mais de 50 milh\u00f5es. Na aposta com sete n\u00fameros (que custa R$ 31,50), a chance sobe para uma em 7,1 milh\u00f5es.<\/p>\n<p>O maior pr\u00eamio j\u00e1 pago neste ano at\u00e9 ent\u00e3o foi em 19 de mar\u00e7o, no concurso 2.464, quando duas apostas ganhadoras dividiram R$ 189.381.872,36. Naquela ocasi\u00e3o, a Mega estava acumulada havia 12 concursos.<\/p>\n<p>Pela internet, \u00e9 necess\u00e1rio que o valor m\u00ednimo seja de R$ 30. Ou seja, no caso da Mega-Sena, \u00e9 necess\u00e1rio fazer pelo menos sete apostas com seis n\u00fameros ou uma com sete dezenas. Tamb\u00e9m \u00e9 poss\u00edvel mesclar com outros jogos, como Quina ou Lotomania.<\/p>\n<p>O apostador que ganhar algum pr\u00eamio tem at\u00e9 90 dias para retirar o dinheiro. A Caixa informa que, ap\u00f3s esse per\u00edodo, a pessoa perde o direito de retirar o dinheiro, que \u00e9 repassado ao Tesouro Nacional para aplica\u00e7\u00e3o no Fies (Fundo de Financiamento ao Estudante do Ensino Superior).<\/p>\n<p>Veja como jogar<\/p>\n<p><strong>PELO SITE<\/strong><br \/>\n&#8211; Acesse o site Loterias Online<br \/>\n&#8211; Confirme se tem mais de 18 anos. Depois, clique em &#8220;acessar&#8221;, no canto superior direito. Se for o primeiro acesso, cadastre-se. Caso contr\u00e1rio, fa\u00e7a seu login usando CPF e senha<br \/>\n&#8211; Role a tela para baixo e, na op\u00e7\u00e3o da Mega-Sena, clique no \u00edcone &#8220;Aposte Agora!&#8221;<br \/>\n&#8211; Escolha as dezenas que quer apostar<br \/>\n&#8211; Informe se quer apostar com mais n\u00fameros e se quer ativar a surpresinha e\/ou a teimosinha<br \/>\n&#8211; Quando acabar tudo, clique em &#8220;colocar no carrinho&#8221;, logo abaixo<br \/>\n&#8211; Quando o valor total da compra for superior a R$ 30, selecione a op\u00e7\u00e3o &#8220;ir para pagamento&#8221;, do lado direito<br \/>\n&#8211; Informe os dados do seu cart\u00e3o de cr\u00e9dito e confirme a compra<br \/>\n&#8211; Ap\u00f3s o sorteio, entre no site, fa\u00e7a login e clique em &#8220;minha conta&#8221;. Em seguida, em &#8220;apostas&#8221; e, depois, em &#8220;conferir apostas&#8221;. Se voc\u00ea tiver ganhado, ir\u00e1 aparecer o pr\u00eamio que receber\u00e1 e os procedimentos para retirada<\/p>\n<p><strong>PELO APLICATIVO<\/strong><br \/>\n&#8211; Baixe o aplicativo Loterias Caixa, dispon\u00edvel gratuitamente para Android e iOS<br \/>\n&#8211; Ap\u00f3s a introdu\u00e7\u00e3o, fa\u00e7a login ou cadastre-se<br \/>\n&#8211; Na tela inicial, localize a Mega-Sena e clique em &#8220;aposte&#8221;<br \/>\n&#8211; Selecione as dezenas desejadas e informe se quer usar mais n\u00fameros e se pretende ativar a teimosinha e a surpresinha<br \/>\n&#8211; Quando acabar, selecione &#8220;adicionar ao carrinho de apostas&#8221;, na parte de baixo da tela<br \/>\n&#8211; Assim como no site, o valor m\u00ednimo \u00e9 de R$ 30. Se n\u00e3o deu esse valor, volte ao in\u00edcio e fa\u00e7a outros jogos at\u00e9 atingir a quantia.<br \/>\n&#8211; Ao terminar, clique em &#8220;carrinho de apostas&#8221;<br \/>\n&#8211; Confira as apostas e, se estiver tudo certo, v\u00e1 em &#8220;avan\u00e7ar para a forma de pagamento&#8221;<br \/>\n&#8211; Informe os dados do cart\u00e3o e clique em &#8220;apostar e autorizar cobran\u00e7a&#8221;<br \/>\n&#8211; Depois do sorteio, acesse o aplicativo. Abra o menu, clicando no bot\u00e3o no canto superior esquerdo e escolha &#8220;minha \u00e1rea&#8221; e, em seguida, &#8220;minhas apostas&#8221;. Nessa \u00e1rea ir\u00e1 aparecer se voc\u00ea ganhou ou n\u00e3o<\/p>\n<p><strong>PELO INTERNET BANKING<\/strong><br \/>\n&#8211; Acesse a plataforma do Internet Banking com seu login e senha<br \/>\n&#8211; Clique em loterias<br \/>\n&#8211; Escolha Mega-Sena e depois apostar (o limite para esta forma de aposta \u00e9 de R$ 500 por dia, das 7h \u00e0s 22h, limitado ao hor\u00e1rio limite para fechamento das apostas)<br \/>\n&#8211; Selecione a quantidade de n\u00fameros do seu jogo (de 6 a 9 por cartela)<br \/>\n&#8211; Escolha suas dezenas e clique em &#8220;incluir aposta&#8221;<br \/>\n&#8211; Se quiser, repita essa opera\u00e7\u00e3o para completar tr\u00eas jogos e ent\u00e3o clique em &#8220;finalizar&#8221;<br \/>\n&#8211; Ent\u00e3o, \u00e9 s\u00f3 digitar os seis n\u00fameros de sua senha eletr\u00f4nica para confirmar o pagamento<br \/>\n&#8211; Depois \u00e9 s\u00f3 voltar \u00e0 tela inicial das loterias e clicar em &#8220;minhas apostas&#8221; para confirmar os jogos realizados.<\/p>\n<p>FONTE: Click PB<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O concurso 2525, no s\u00e1bado (1\u00ba), dever\u00e1 pagar R$ 300 milh\u00f5es, segundo a estimativa da Caixa Econ\u00f4mica Federal. Mais uma vez n\u00e3o houve ganhador do&hellip; <\/p>\n","protected":false},"author":6,"featured_media":257190,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[50,2],"tags":[],"class_list":["post-257189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-geral"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/257189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=257189"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/257189\/revisions"}],"predecessor-version":[{"id":257191,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/257189\/revisions\/257191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/257190"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=257189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=257189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=257189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}