{"id":264031,"date":"2023-03-03T09:52:55","date_gmt":"2023-03-03T12:52:55","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=264031"},"modified":"2023-03-03T09:52:55","modified_gmt":"2023-03-03T12:52:55","slug":"prefeito-de-caraubas-e-vice-presidente-da-amcap-participa-do-encontro-de-gestores-do-pacto-novo-cariri","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2023\/03\/03\/prefeito-de-caraubas-e-vice-presidente-da-amcap-participa-do-encontro-de-gestores-do-pacto-novo-cariri\/","title":{"rendered":"Prefeito de Cara\u00fabas e vice-presidente da Amcap participa do encontro de gestores do pacto novo Cariri"},"content":{"rendered":"<p>O prefeito de Cara\u00fabas e vice presidente da AMCAP, Silvano Dudu, participou na manh\u00e3 desta quinta-feira, dia 2\/3, na cidade de Monteiro, do Encontro de gestores do novo Pacto do Cariri, promovido pelo SEBRAE.<\/p>\n<p>Na oportunidade, o prefeito esteve acompanhado do secret\u00e1rio da Agricultura Rone Feitoza onde foi discutido o fortalecimento da cadeia produtiva da regi\u00e3o como forma de reunir esfor\u00e7os na retomada do desenvolvimento regional, impulsionando a gera\u00e7\u00e3o de emprego e renda e o desenvolvimento de atividades importantes.<\/p>\n<p>O prefeito Silvano Dudu saiu satisfeito do Encontro e falou da import\u00e2ncia do trabalho integrado dos munic\u00edpios com a implanta\u00e7\u00e3o do Selo de Inspe\u00e7\u00e3o Municipal para comercializa\u00e7\u00e3o dos produtos de origem animal. Cara\u00fabas j\u00e1 tem implantado o Selo, estamos organizando ainda mais o nosso setor atrav\u00e9s de uma reforma que iremos realizar no Matadouro P\u00fablico Municipal e ainda essa semana recebemos a visita de uma empresa que pretende instalar um cont\u00eainer para deposi\u00e7\u00e3o dos res\u00edduos carneos da regi\u00e3o, afirmou o prefeito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Cara\u00fabas e vice presidente da AMCAP, Silvano Dudu, participou na manh\u00e3 desta quinta-feira, dia 2\/3, na cidade de Monteiro, do Encontro de&hellip; <\/p>\n","protected":false},"author":6,"featured_media":264032,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[73],"tags":[],"class_list":["post-264031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caraubas"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/264031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=264031"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/264031\/revisions"}],"predecessor-version":[{"id":264033,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/264031\/revisions\/264033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/264032"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=264031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=264031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=264031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}