{"id":275786,"date":"2023-10-10T09:20:44","date_gmt":"2023-10-10T12:20:44","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=275786"},"modified":"2023-10-10T09:20:44","modified_gmt":"2023-10-10T12:20:44","slug":"empresa-divulga-locais-e-horarios-de-prova-do-concurso-publico-de-serra-branca-confira","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2023\/10\/10\/empresa-divulga-locais-e-horarios-de-prova-do-concurso-publico-de-serra-branca-confira\/","title":{"rendered":"Empresa divulga locais e hor\u00e1rios de prova do Concurso P\u00fablico de Serra Branca; confira"},"content":{"rendered":"<p>J\u00e1 est\u00e3o disponibilizados para os candidatos inscritos no Concurso P\u00fablico da Prefeitura Municipal de Serra Branca os locais e hor\u00e1rios da aplica\u00e7\u00e3o das provas do certame que acontecer\u00e1 neste domingo.<\/p>\n<p>Atrav\u00e9s do site oficial da empresa IDIB, empresa realizadora do certame, os candidatos j\u00e1 podem ter acesso aos locais e hor\u00e1rios da aplica\u00e7\u00e3o da prova.<\/p>\n<p>O Concurso P\u00fablico de Serra Branca acontece neste domingo, dia 15, e ser\u00e3o realizados nos turnos da manh\u00e3, de 09 \u00e0s 12h, e da tarde, das 14 \u00e0s 17h.<\/p>\n<p>Para saber qual o local de prova para cada cargo desejado, os candidatos dever\u00e3o acessar o<a href=\"https:\/\/idib.org.br\/\">\u00a0site<\/a>, localizar o edital do Concurso P\u00fablico e clicar em \u201c\u00c1rea do Candidato\u201d.<\/p>\n<p>\u00c9 indicado que os candidatos devem comparecer ao local da prova com anteced\u00eancia m\u00ednima de uma hora. E aten\u00e7\u00e3o, n\u00e3o ser\u00e1 permitido o ingresso de candidatos ap\u00f3s o fechamento dos port\u00f5es. \u00c9 preciso ficar atento para as proibi\u00e7\u00f5es durante a realiza\u00e7\u00e3o das provas.<\/p>\n<p>O candidato dever\u00e3o levar o comprovante de inscri\u00e7\u00e3o, documento de identidade com foto e caneta esferogr\u00e1fica de tinta azul ou preta de material transparente.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>CARIRI EM A\u00c7\u00c3O<\/strong><\/p>\n<p>Com De Olho no Cariri<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 est\u00e3o disponibilizados para os candidatos inscritos no Concurso P\u00fablico da Prefeitura Municipal de Serra Branca os locais e hor\u00e1rios da aplica\u00e7\u00e3o das provas do&hellip; <\/p>\n","protected":false},"author":6,"featured_media":272269,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[50,93],"tags":[],"class_list":["post-275786","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-serra-branca"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/275786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=275786"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/275786\/revisions"}],"predecessor-version":[{"id":275787,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/275786\/revisions\/275787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/272269"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=275786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=275786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=275786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}