{"id":28198,"date":"2017-09-09T05:13:19","date_gmt":"2017-09-09T08:13:19","guid":{"rendered":"http:\/\/caririemacao.com\/1\/?p=28198"},"modified":"2017-09-09T05:13:19","modified_gmt":"2017-09-09T08:13:19","slug":"eua-ampliam-estado-de-emergencia-por-passagem-do-furacao-irma-pela-georgia","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2017\/09\/09\/eua-ampliam-estado-de-emergencia-por-passagem-do-furacao-irma-pela-georgia\/","title":{"rendered":"EUA ampliam estado de emerg\u00eancia por passagem do furac\u00e3o Irma pela Ge\u00f3rgia"},"content":{"rendered":"<p>O governo dos Estados Unidos ampliou nesta sexta-feira (8) o decreto de estado de emerg\u00eancia para as regi\u00f5es possivelmente afetadas pela passagem do furac\u00e3o Irma para a Ge\u00f3rgia, que deve ser atingida na segunda-feira (11), informaram fontes oficiais.<\/p>\n<p>Nos \u00faltimos dias, a Casa Branca tinha declarado estado de emerg\u00eancia para Porto Rico e para as Ilhas Virgens Brit\u00e2nicas, por onde o furac\u00e3o passou com categoria 5, a maior na escala Saffir-Simpson, para a Fl\u00f3rida, onde o Irma deve chegar na madrugada de domingo (10), e tamb\u00e9m para a Carolina do Sul.<\/p>\n<p>&#8220;O presidente Donald Trump declarou hoje que existe uma situa\u00e7\u00e3o de emerg\u00eancia no estado da Ge\u00f3rgia e ordenou a destina\u00e7\u00e3o de recursos federais para complementar os esfor\u00e7os estaduais e locais&#8221;, indicou a Casa Branca em um comunicado divulgado hoje.<\/p>\n<p>A declara\u00e7\u00e3o de estado de emerg\u00eancia agiliza os repasses de dinheiro do governo federal em casos de desastre.<\/p>\n<p>&#8220;O meu governo est\u00e1 trabalhando com nossos parceiros estaduais e locais com o objetivo de salvar vidas, proteger fam\u00edlias e ajudar os necessitados&#8221;, disse Trump em um v\u00eddeo divulgado no Twitter.<\/p>\n<p>Desde a \u00faltima ter\u00e7a-feira (5), o governador da Fl\u00f3rida, Rick Scott, anunciou uma s\u00e9rie de medidas para facilitar a retirada da popula\u00e7\u00e3o dos locais de risco por causa do furac\u00e3o, que j\u00e1 deixou 18 mortos em sua passagem por v\u00e1rias ilhas do Caribe.<\/p>\n<p><strong>CARIRI EM A\u00c7\u00c3O<\/strong><\/p>\n<p><em>Com Ag\u00eancia Brasil\/Foto: Google<\/em><\/p>\n<p><strong>Leia mais not\u00edcias em\u00a0<\/strong><a href=\"http:\/\/www.caririemacao.com\/\"><strong>caririemacao.com<\/strong><\/a><strong>, siga nossa p\u00e1gina no\u00a0<\/strong><a href=\"https:\/\/www.facebook.com\/CaririEmAcao\/?ref=aymt_homepage_panel\"><strong>Facebook<\/strong><\/a>,<strong>\u00a0<\/strong><a href=\"https:\/\/www.instagram.com\/cariri_em_acao\/?hl=pt-br\"><strong>Instagram<\/strong><\/a><strong>\u00a0e <\/strong><a href=\"https:\/\/www.youtube.com\/channel\/UCAptA0jQuYQy8vMhLt2m4qg\"><strong>Youtube<\/strong><\/a><strong>\u00a0e veja nossas mat\u00e9rias, v\u00eddeos e fotos. Voc\u00ea tamb\u00e9m pode enviar informa\u00e7\u00f5es \u00e0 Reda\u00e7\u00e3o do Portal Cariri em A\u00e7\u00e3o pelo WhatsApp (83) 9 9634.5791, (83) 9 9601-1162.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governo dos Estados Unidos ampliou nesta sexta-feira (8) o decreto de estado de emerg\u00eancia para as regi\u00f5es possivelmente afetadas pela passagem do furac\u00e3o Irma&hellip; <\/p>\n","protected":false},"author":2,"featured_media":28199,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-28198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/28198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=28198"}],"version-history":[{"count":0,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/28198\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/28199"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=28198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=28198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=28198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}