{"id":28201,"date":"2017-09-09T05:17:35","date_gmt":"2017-09-09T08:17:35","guid":{"rendered":"http:\/\/caririemacao.com\/1\/?p=28201"},"modified":"2017-09-09T05:17:35","modified_gmt":"2017-09-09T08:17:35","slug":"ministerio-da-saude-investe-r-520-milhoes-na-aquisicao-de-ambulancias","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2017\/09\/09\/ministerio-da-saude-investe-r-520-milhoes-na-aquisicao-de-ambulancias\/","title":{"rendered":"Minist\u00e9rio da Sa\u00fade investe R$ 520 milh\u00f5es na aquisi\u00e7\u00e3o de ambul\u00e2ncias"},"content":{"rendered":"<p>O Minist\u00e9rio da Sa\u00fade liberou R$ 520 milh\u00f5es para aquisi\u00e7\u00e3o de 6,5 mil ambul\u00e2ncias brancas usadas no transporte sanit\u00e1rio. Esses ve\u00edculos s\u00e3o usados no transporte de pacientes que necessitam de locomo\u00e7\u00e3o para os servi\u00e7os de sa\u00fade, al\u00e9m de garantir o transporte de pacientes entre munic\u00edpios e servi\u00e7os de refer\u00eancia em outras cidades. Essa a\u00e7\u00e3o facilita o acesso a consultas, exames e interna\u00e7\u00e3o para cirurgias eletivas, beneficiando diretamente milh\u00f5es de pessoas em todo o Brasil.<\/p>\n<p>A portaria regulamenta o investimento para aquisi\u00e7\u00e3o desses ve\u00edculos utilizando recursos program\u00e1ticos da pasta, o que facilita o acesso da gest\u00e3o local \u00e0 amplia\u00e7\u00e3o desses servi\u00e7os, de forma menos burocr\u00e1tica e mais \u00e1gil, tendo em vista que at\u00e9 ent\u00e3o esse tipo de ambul\u00e2ncia s\u00f3 poderia ser adquirida por meio de emendas parlamentares. A compra ser\u00e1 feita pelo Minist\u00e9rio da Sa\u00fade, de forma centralizada, e a distribui\u00e7\u00e3o aos munic\u00edpios se dar\u00e1 de acordo com crit\u00e9rios a serem estabelecidos.<\/p>\n<p>\u201cEm julho, j\u00e1 hav\u00edamos anunciados a compra dessas ambul\u00e2ncias. Agora, estamos oficializando esse compromisso com todo o Brasil, uma vez que os 5.570 munic\u00edpios est\u00e3o aptos a receber as novas ambul\u00e2ncias, desde que tenham indica\u00e7\u00e3o parlamentar. Vamos priorizar, nesse momento, os munic\u00edpios menores, porque s\u00e3o as regi\u00f5es que mais precisam de aten\u00e7\u00e3o e investimento na \u00e1rea de sa\u00fade nesse momento\u201d, explicou o ministro da Sa\u00fade, Ricardo Barros.<\/p>\n<p>Ainda dentro do crit\u00e9rio de distribui\u00e7\u00e3o, os munic\u00edpios que tiverem at\u00e9 20 mil habitantes ter\u00e3o direito a uma ambul\u00e2ncia; os que tiverem de 21 mil a 50 mil ter\u00e3o direito a duas; os que tiverem de 51 mil a 100 mil ter\u00e3o direito a tr\u00eas, e os munic\u00edpios que tiverem mais de 100 mil habitantes ter\u00e3o direito a quatro ambul\u00e2ncias.<\/p>\n<p><strong>NOVAS AMBUL\u00c2NCIAS \u2013<\/strong>\u00a0Em julho, o Minist\u00e9rio da Sa\u00fade anunciou a libera\u00e7\u00e3o de R$ 467,6 milh\u00f5es para a compra de ambul\u00e2ncias do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU 192) e 1.000 vans para atender as necessidades da popula\u00e7\u00e3o.<\/p>\n<p>Das ambul\u00e2ncias do SAMU, o Minist\u00e9rio da Sa\u00fade ir\u00e1 ofertar 1.098 unidades para renova\u00e7\u00e3o da frota existente, com mais de cinco anos de uso. Outras 402 ser\u00e3o destinadas para expans\u00e3o da oferta.\u00a0 A medida ir\u00e1 beneficiar 134 regi\u00f5es que n\u00e3o possuem esse tipo de servi\u00e7o. Com isso, a cobertura da popula\u00e7\u00e3o chegar\u00e1 a 83,4%. Atualmente, o Pa\u00eds possui 3.215 ambul\u00e2ncias em funcionamento, com custeio de mais de R$ 1 bilh\u00e3o. S\u00f3 nessa gest\u00e3o, outras 929 ambul\u00e2ncias est\u00e3o sendo adquiridas para renova\u00e7\u00e3o e expans\u00e3o.<\/p>\n<p><strong>A\u00c7\u00d5ES DE GEST\u00c3O \u2013<\/strong>\u00a0Em mais de um ano de gest\u00e3o, o ministro Ricardo Barros economizou R$ 3,8 bilh\u00f5es de recursos sendo totalmente reinvestidos na habilita\u00e7\u00e3o de novos servi\u00e7os. Do total de recursos, a pasta liberou R$ 2 bilh\u00f5es para o custeio de 12.138 novos agentes comunit\u00e1rios de sa\u00fade, 3.103 novas equipes de Sa\u00fade da Fam\u00edlia, 2.299 novas equipes Bucal, 882 novos N\u00facleos de Apoio \u00e0 Sa\u00fade da Fam\u00edlia, 113 novas equipes de Sa\u00fade Prisional e 34 novos consult\u00f3rios na rua.<\/p>\n<p>A medida, que beneficia 1.787 munic\u00edpios e representa cobertura de mais 22 milh\u00f5es de pessoas na aten\u00e7\u00e3o b\u00e1sica, tamb\u00e9m prev\u00ea o credenciamento de 34 Unidades Odontol\u00f3gicas M\u00f3veis (UOMs) e a aquisi\u00e7\u00e3o de 10 mil cadeiras para consult\u00f3rios odontol\u00f3gicos, com raio-x, que funcionam nas Unidades B\u00e1sicas de Sa\u00fade (UBS).<\/p>\n<p><strong>CARIRI EM A\u00c7\u00c3O<\/strong><\/p>\n<p><em>Com paraiba.com\/Foto: Google<\/em><\/p>\n<p><strong>Leia mais not\u00edcias em\u00a0<\/strong><a href=\"http:\/\/www.caririemacao.com\/\"><strong>caririemacao.com<\/strong><\/a><strong>, siga nossa p\u00e1gina no\u00a0<\/strong><a href=\"https:\/\/www.facebook.com\/CaririEmAcao\/?ref=aymt_homepage_panel\"><strong>Facebook<\/strong><\/a>,<strong>\u00a0<\/strong><a href=\"https:\/\/www.instagram.com\/cariri_em_acao\/?hl=pt-br\"><strong>Instagram<\/strong><\/a><strong>\u00a0e <\/strong><a href=\"https:\/\/www.youtube.com\/channel\/UCAptA0jQuYQy8vMhLt2m4qg\"><strong>Youtube<\/strong><\/a><strong>\u00a0e veja nossas mat\u00e9rias, v\u00eddeos e fotos. Voc\u00ea tamb\u00e9m pode enviar informa\u00e7\u00f5es \u00e0 Reda\u00e7\u00e3o do Portal Cariri em A\u00e7\u00e3o pelo WhatsApp (83) 9 9634.5791, (83) 9 9601-1162.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio da Sa\u00fade liberou R$ 520 milh\u00f5es para aquisi\u00e7\u00e3o de 6,5 mil ambul\u00e2ncias brancas usadas no transporte sanit\u00e1rio. Esses ve\u00edculos s\u00e3o usados no transporte&hellip; <\/p>\n","protected":false},"author":2,"featured_media":28202,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[16],"tags":[],"class_list":["post-28201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/28201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=28201"}],"version-history":[{"count":0,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/28201\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/28202"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=28201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=28201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=28201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}