{"id":28204,"date":"2017-09-09T05:20:34","date_gmt":"2017-09-09T08:20:34","guid":{"rendered":"http:\/\/caririemacao.com\/1\/?p=28204"},"modified":"2017-09-09T05:20:34","modified_gmt":"2017-09-09T08:20:34","slug":"petrobras-reajusta-precos-da-gasolina-e-do-diesel-neste-sabado","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2017\/09\/09\/petrobras-reajusta-precos-da-gasolina-e-do-diesel-neste-sabado\/","title":{"rendered":"Petrobras reajusta pre\u00e7os da gasolina e do diesel neste s\u00e1bado"},"content":{"rendered":"<p>Os pre\u00e7os de venda da gasolina e do diesel \u00e0s distribuidoras ser\u00e3o reajustados amanh\u00e3 (9) em 2,6% e 1,5%, respectivamente, segundo informou hoje (8) a Petrobras.<\/p>\n<p>De acordo com a pol\u00edtica de pre\u00e7os adotada pela empresa no final de junho, que passou a vigorar no dia 3 de julho, reajustes podem ser aplicados a qualquer momento, at\u00e9 diariamente, desde que a varia\u00e7\u00e3o acumulada no m\u00eas por produto esteja dentro da faixa de +7% ou -7%.<\/p>\n<p>Segundo informou a assessoria de imprensa da Petrobras, quando se atinge no m\u00eas mais de 7% ou menos de 7% de reajuste, o Grupo Executivo de Mercado e Pre\u00e7os da companhia se re\u00fane e analisa se vai haver alguma corre\u00e7\u00e3o.<\/p>\n<p>No ajuste anterior, que passou a vigorar ontem (7), o aumento para o diesel foi 0,7%, enquanto para a gasolina houve redu\u00e7\u00e3o de 3,8%.<\/p>\n<p>Segundo a companhia, a revis\u00e3o da pol\u00edtica aprovada em junho \u201cpermitir\u00e1 maior ader\u00eancia dos pre\u00e7os do mercado dom\u00e9stico ao mercado internacional no curto prazo e possibilitar\u00e1 a companhia competir de maneira mais \u00e1gil e eficiente\u201d.<\/p>\n<p><strong>CARIRI EM A\u00c7\u00c3O<\/strong><\/p>\n<p><em>Com Ag\u00eancia\u00a0Brasil \/Foto: Google<\/em><\/p>\n<p><strong>Leia mais not\u00edcias em\u00a0<\/strong><a href=\"http:\/\/www.caririemacao.com\/\"><strong>caririemacao.com<\/strong><\/a><strong>, siga nossa p\u00e1gina no\u00a0<\/strong><a href=\"https:\/\/www.facebook.com\/CaririEmAcao\/?ref=aymt_homepage_panel\"><strong>Facebook<\/strong><\/a>,<strong>\u00a0<\/strong><a href=\"https:\/\/www.instagram.com\/cariri_em_acao\/?hl=pt-br\"><strong>Instagram<\/strong><\/a><strong>\u00a0e <\/strong><a href=\"https:\/\/www.youtube.com\/channel\/UCAptA0jQuYQy8vMhLt2m4qg\"><strong>Youtube<\/strong><\/a><strong>\u00a0e veja nossas mat\u00e9rias, v\u00eddeos e fotos. Voc\u00ea tamb\u00e9m pode enviar informa\u00e7\u00f5es \u00e0 Reda\u00e7\u00e3o do Portal Cariri em A\u00e7\u00e3o pelo WhatsApp (83) 9 9634.5791, (83) 9 9601-1162.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os pre\u00e7os de venda da gasolina e do diesel \u00e0s distribuidoras ser\u00e3o reajustados amanh\u00e3 (9) em 2,6% e 1,5%, respectivamente, segundo informou hoje (8) a&hellip; <\/p>\n","protected":false},"author":2,"featured_media":28205,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-28204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/28204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=28204"}],"version-history":[{"count":0,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/28204\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/28205"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=28204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=28204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=28204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}