{"id":283791,"date":"2024-04-13T09:00:21","date_gmt":"2024-04-13T12:00:21","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=283791"},"modified":"2024-04-13T09:00:21","modified_gmt":"2024-04-13T12:00:21","slug":"apesar-de-palco-montado-paineis-e-ate-slogan-quero-quero-sergio-queiroz-adia-decisao-final-sobre-ser-vice-de-queiroga","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2024\/04\/13\/apesar-de-palco-montado-paineis-e-ate-slogan-quero-quero-sergio-queiroz-adia-decisao-final-sobre-ser-vice-de-queiroga\/","title":{"rendered":"Apesar de palco montado, pain\u00e9is e at\u00e9 slogan \u201cQuero Quero\u201d, S\u00e9rgio Queiroz adia \u201cdecis\u00e3o final\u201d sobre ser vice de Queiroga"},"content":{"rendered":"<p><span class=\"\">Na noite desta sexta-feira (12), o pastor S\u00e9rgio Queiroz (Novo) surpreendeu ao adiar o an\u00fancio do vice na chapa liderada por Marcelo Queiroga (PL) para a Prefeitura de Jo\u00e3o Pessoa.\u00a0<\/span><span class=\"\">O evento, realizado na Domus Hall e marcado para oficializar a chapa, contou com pain\u00e9is exibindo as fotos de Queiroga e Queiroz, sob o slogan \u201cQuero-Quero\u201d<\/span><span class=\"\">, e a presen\u00e7a do ex-presidente Jair Bolsonaro (PL).<\/span><\/p>\n<p class=\"query-text ng-star-inserted\" dir=\"ltr\">\u201cAdiamos o an\u00fancio de como o Novo vai participar dessa pr\u00f3xima campanha eleitoral. Adiamos por mais uns dias para que possamos tomar uma decis\u00e3o final. Vamos ter que aguardar um pouquinho\u201d, disse Queiroz em postagem nas redes sociais.<\/p>\n<p dir=\"ltr\">Ap\u00f3s alian\u00e7a firmada em Jo\u00e3o Pessoa, Cabedelo e Bayeux, ficou decidido que o Novo indicaria o vice da chapa de Queiroga e a grande expectativa e apelo dos membros do PL era para Queiroz ser o vice.<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\">PB Agora<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite desta sexta-feira (12), o pastor S\u00e9rgio Queiroz (Novo) surpreendeu ao adiar o an\u00fancio do vice na chapa liderada por Marcelo Queiroga (PL) para&hellip; <\/p>\n","protected":false},"author":6,"featured_media":283792,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[50,104,11],"tags":[],"class_list":["post-283791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-paraiba","category-politica"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/283791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=283791"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/283791\/revisions"}],"predecessor-version":[{"id":283793,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/283791\/revisions\/283793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/283792"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=283791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=283791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=283791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}