{"id":292595,"date":"2024-11-11T10:55:47","date_gmt":"2024-11-11T13:55:47","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=292595"},"modified":"2024-11-11T10:55:47","modified_gmt":"2024-11-11T13:55:47","slug":"boa-vista-implanta-projeto-de-seguranca-e-saude-nas-escolas-da-rede-municipal","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2024\/11\/11\/boa-vista-implanta-projeto-de-seguranca-e-saude-nas-escolas-da-rede-municipal\/","title":{"rendered":"Boa Vista implanta projeto de seguran\u00e7a e sa\u00fade nas escolas da rede Municipal"},"content":{"rendered":"<p>A Prefeitura de Boa Vista, implantou na rede Municipal de ensino, o Projeto Seguran\u00e7a e Sa\u00fade nas Escolas, objetivando fortalecer ainda mais as medidas de promo\u00e7\u00e3o \u00e0 sa\u00fade do trabalhador.<\/p>\n<p>A a\u00e7\u00e3o \u00e9 realizada atrav\u00e9s das secretarias de sa\u00fade e de educa\u00e7\u00e3o, em parceria com o Minist\u00e9rio P\u00fablico do Trabalho (MPT).<\/p>\n<p>De acordo com o prefeito, Andr\u00e9 Gomes, o objetivo do projeto \u00e9 preparar crian\u00e7as, adolescentes e jovens para o mundo do trabalho, de forma segura, sustent\u00e1vel, saud\u00e1vel e digna. Para isso, a a\u00e7\u00e3o busca estimular a inclus\u00e3o do tema Sa\u00fade Seguran\u00e7a do Trabalho (SST) nos curr\u00edculos de todos os n\u00edveis de ensino.<\/p>\n<p>Al\u00e9m disso, objetiva sensibilizar e informar sobre o mundo do trabalho, de forma a desenvolver compet\u00eancias em SST nas futuras gera\u00e7\u00f5es; reduzir os \u00edndices de acidente, adoecimento e mortalidade relacionados ao trabalho; e implantar uma cultura de preven\u00e7\u00e3o e respeito junto aos estudantes e profissionais.<\/p>\n<p>A iniciativa seguran\u00e7a e da\u00fade nas escolas apresenta uma s\u00e9rie de informa\u00e7\u00f5es para o alcance do objetivo de promover mudan\u00e7as comportamentais positivas nos estudantes e em toda a comunidade escolar, possibilitando \u00e0s escolas, aos professores e aos estudantes ter apoio na implementa\u00e7\u00e3o das a\u00e7\u00f5es que est\u00e3o sendo desenvolvidas no \u00e2mbito escolar.<\/p>\n<p>\u201cO Programa Sa\u00fade na Escola em Boa Vista, integra sa\u00fade e educa\u00e7\u00e3o, promovendo o bem-estar e o desenvolvimento integral dos estudantes. A\u00e7\u00f5es de preven\u00e7\u00e3o e promo\u00e7\u00e3o da sa\u00fade envolvem toda a comunidade escolar, unindo escolas, centros de sa\u00fade e gestores\u201d, frisa Andr\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Boa Vista, implantou na rede Municipal de ensino, o Projeto Seguran\u00e7a e Sa\u00fade nas Escolas, objetivando fortalecer ainda mais as medidas de&hellip; <\/p>\n","protected":false},"author":6,"featured_media":292596,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[69,50],"tags":[],"class_list":["post-292595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boa-vista","category-destaque"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/292595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=292595"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/292595\/revisions"}],"predecessor-version":[{"id":292597,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/292595\/revisions\/292597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/292596"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=292595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=292595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=292595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}