{"id":292604,"date":"2024-11-11T15:16:48","date_gmt":"2024-11-11T18:16:48","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=292604"},"modified":"2024-11-11T15:16:48","modified_gmt":"2024-11-11T18:16:48","slug":"informe-publicitario-prefeitura-de-sume-celebra-a-entrega-de-13-casas-em-parceria-com-o-governo-do-estado","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2024\/11\/11\/informe-publicitario-prefeitura-de-sume-celebra-a-entrega-de-13-casas-em-parceria-com-o-governo-do-estado\/","title":{"rendered":"INFORME PUBLICIT\u00c1RIO: Prefeitura de Sum\u00e9 celebra a entrega de 13 casas em parceria com o Governo do Estado"},"content":{"rendered":"<p>O \u00faltimo s\u00e1bado (9) foi marcado por emo\u00e7\u00e3o e realiza\u00e7\u00e3o de sonhos em Sum\u00e9. A entrega de 13 unidades habitacionais do Conjunto Sebasti\u00e3o Vitorino, como parte do programa estadual \u201cParceiros da Habita\u00e7\u00e3o\u201d. O evento reuniu autoridades, benefici\u00e1rios e a comunidade em um evento que simbolizou a transforma\u00e7\u00e3o na vida de fam\u00edlias vulner\u00e1veis.<\/p>\n<p>O governador em exerc\u00edcio, Lucas Ribeiro, e o prefeito de Sum\u00e9, \u00c9den Duarte, lideraram a cerim\u00f4nia de entrega, destacando o impacto social do projeto. Ao todo, 56 casas est\u00e3o sendo constru\u00eddas em parceria entre o Governo do Estado e a Prefeitura.<\/p>\n<p>A Companhia Estadual de Habita\u00e7\u00e3o Popular (Cehap) \u00e9 respons\u00e1vel pela execu\u00e7\u00e3o, acompanhamento e fiscaliza\u00e7\u00e3o da obra, enquanto o munic\u00edpio cedeu os terrenos e conduziu o rigoroso processo de sele\u00e7\u00e3o dos benefici\u00e1rios.<\/p>\n<p>A presidente da Cehap, Em\u00edlia Correia, enfatizou a import\u00e2ncia do momento. \u201cA casa pr\u00f3pria representa dignidade, seguran\u00e7a e uma base s\u00f3lida para buscar novas possibilidades. Este projeto resgata o amor pr\u00f3prio e transforma a qualidade de vida das fam\u00edlias\u201d, afirmou. Ela tamb\u00e9m parabenizou a gest\u00e3o municipal pela condu\u00e7\u00e3o transparente e criteriosa do processo seletivo.<\/p>\n<p>O prefeito \u00c9den Duarte expressou sua alegria em ver fam\u00edlias vulner\u00e1veis sendo contempladas e destacou os esfor\u00e7os para minimizar o d\u00e9ficit habitacional, um desafio enfrentado por gestores em todo o Brasil. Ele mencionou que sua administra\u00e7\u00e3o j\u00e1 cadastrou quase 40 novas unidades habitacionais no programa federal, refor\u00e7ando o compromisso com a causa.<\/p>\n<p>O secret\u00e1rio de Assist\u00eancia Social, \u00c9dson Cavalcante, celebrou o resultado do trabalho realizado com dedica\u00e7\u00e3o e responsabilidade. Ele destacou que questionamentos feitos ao Minist\u00e9rio P\u00fablico sobre a sele\u00e7\u00e3o foram arquivados, uma vez que o processo demonstrou total lisura e impessoalidade.<\/p>\n<p>A cerim\u00f4nia foi marcada por depoimentos emocionados de benefici\u00e1rias como \u00c9lida, Luciana e Fernanda. \u00c9lida, visivelmente emocionada, afirmou: \u201cHoje em dia a gente n\u00e3o tem condi\u00e7\u00f5es nem de fazer uma feira direito, imagina comprar uma casa\u201d. J\u00e1 Luciana declarou: \u201cN\u00e3o tenho palavras para agradecer, \u00e9 s\u00f3 felicidade. S\u00f3 quem passa por isso sabe o que significa\u201d.<\/p>\n<p>As 13 primeiras fam\u00edlias contempladas receberam das m\u00e3os das autoridades as chaves e os documentos das suas novas resid\u00eancias. O governador em exerc\u00edcio, Lucas Ribeiro, ressaltou o impacto transformador da a\u00e7\u00e3o. \u201c\u00c9 gratificante proporcionar dignidade e um lar para quem mais precisa. Este \u00e9 o papel de um governo comprometido com as pessoas\u201d, afirmou.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-24955 aligncenter\" src=\"https:\/\/i0.wp.com\/paraibadagente.com.br\/site\/wp-content\/uploads\/2022\/11\/LOGO-SUME.jpg?resize=394%2C394&amp;ssl=1\" sizes=\"(max-width: 394px) 100vw, 394px\" srcset=\"https:\/\/i0.wp.com\/paraibadagente.com.br\/site\/wp-content\/uploads\/2022\/11\/LOGO-SUME.jpg?w=206&amp;ssl=1 206w, https:\/\/i0.wp.com\/paraibadagente.com.br\/site\/wp-content\/uploads\/2022\/11\/LOGO-SUME.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/paraibadagente.com.br\/site\/wp-content\/uploads\/2022\/11\/LOGO-SUME.jpg?resize=180%2C180&amp;ssl=1 180w\" alt=\"\" width=\"394\" height=\"394\" data-recalc-dims=\"1\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O \u00faltimo s\u00e1bado (9) foi marcado por emo\u00e7\u00e3o e realiza\u00e7\u00e3o de sonhos em Sum\u00e9. A entrega de 13 unidades habitacionais do Conjunto Sebasti\u00e3o Vitorino, como&hellip; <\/p>\n","protected":false},"author":6,"featured_media":292605,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[50,95],"tags":[],"class_list":["post-292604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-sume"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/292604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=292604"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/292604\/revisions"}],"predecessor-version":[{"id":292606,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/292604\/revisions\/292606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/292605"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=292604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=292604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=292604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}