{"id":293903,"date":"2024-12-12T09:16:43","date_gmt":"2024-12-12T12:16:43","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=293903"},"modified":"2024-12-12T09:16:43","modified_gmt":"2024-12-12T12:16:43","slug":"prefeito-eleito-de-sume-anuncia-nome-de-ivandro-queiroz-como-novo-secretario-de-cultura","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2024\/12\/12\/prefeito-eleito-de-sume-anuncia-nome-de-ivandro-queiroz-como-novo-secretario-de-cultura\/","title":{"rendered":"Prefeito eleito de Sum\u00e9 anuncia nome de Ivandro Queiroz como novo secret\u00e1rio de cultura"},"content":{"rendered":"<p>Nesta quarta-feira (12), o prefeito eleito de Sum\u00e9, Manezinho Louren\u00e7o, anunciou Ivandro Queiroz como o novo Secret\u00e1rio de Cultura, Esporte e Turismo do munic\u00edpio, cargo que ser\u00e1 assumido a partir de janeiro de 2025.<\/p>\n<p>Ivandro Queiroz \u00e9 mestre em Hist\u00f3ria Cultural pela Universidade Federal de Campina Grande (UFCG), professor de Hist\u00f3ria no governo do Estado da Para\u00edba h\u00e1 mais de 20 anos e graduado em Hist\u00f3ria pela Universidade Estadual da Para\u00edba (UEPB). Ele tamb\u00e9m possui especializa\u00e7\u00e3o em Ensino de Jovens e Adultos pela UFCG.<\/p>\n<p>Sua trajet\u00f3ria cultural inclui a atua\u00e7\u00e3o como ativista no coletivo respons\u00e1vel pela organiza\u00e7\u00e3o da SECAS (Semana de Cultura e Arte de Sum\u00e9), evento realizado entre 2006 e 2013. Atualmente, Ivandro est\u00e1 expandindo seus conhecimentos na \u00e1rea de fotografia e artes visuais.<\/p>\n<p>Ao longo dos anos, Ivandro tem se dedicado a promover o acesso \u00e0 cultura, reconhecendo-a como um direito fundamental de todos os cidad\u00e3os. Para ele, a cultura n\u00e3o apenas fortalece a identidade do povo, mas tamb\u00e9m desempenha um papel vital no crescimento econ\u00f4mico da cidade, especialmente quando associada ao potencial tur\u00edstico de Sum\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta quarta-feira (12), o prefeito eleito de Sum\u00e9, Manezinho Louren\u00e7o, anunciou Ivandro Queiroz como o novo Secret\u00e1rio de Cultura, Esporte e Turismo do munic\u00edpio, cargo&hellip; <\/p>\n","protected":false},"author":6,"featured_media":293904,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[50,95],"tags":[],"class_list":["post-293903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-sume"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/293903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=293903"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/293903\/revisions"}],"predecessor-version":[{"id":293905,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/293903\/revisions\/293905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/293904"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=293903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=293903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=293903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}