{"id":30401,"date":"2017-10-10T05:26:46","date_gmt":"2017-10-10T08:26:46","guid":{"rendered":"http:\/\/caririemacao.com\/1\/?p=30401"},"modified":"2017-10-10T05:31:44","modified_gmt":"2017-10-10T08:31:44","slug":"acham-que-nao-tenho-forca-como-cabo-eleitoral-diz-lula","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2017\/10\/10\/acham-que-nao-tenho-forca-como-cabo-eleitoral-diz-lula\/","title":{"rendered":"Acham que n\u00e3o tenho for\u00e7a como cabo eleitoral&#8217;, diz Lula"},"content":{"rendered":"<p>Condenado a 9 anos e 6 meses de pris\u00e3o em primeira inst\u00e2ncia, o ex-presidente Luiz In\u00e1cio Lula da Silva voltou a desafiar ontem seus acusadores a ver o que acontecer\u00e1 no Pa\u00eds se o impedirem de ser candidato \u00e0 Presid\u00eancia em 2018. \u201cEles agem todo santo dia para me tirar da disputa. Juntam meia d\u00fazia de juiz e votam. N\u00e3o me deixam ser candidato e pronto. Se eles acham que, me tirando da disputa, est\u00e1 resolvido o problema deles, fa\u00e7am e vamos ver o que acontece no Pa\u00eds. Se acham que n\u00e3o vou ter for\u00e7a para ser cabo eleitoral, testem\u201d, disse o petista em ato em defesa das universidades p\u00fablicas em Bras\u00edlia.<\/p>\n<p>O ex-presidente afirmou ainda que est\u00e1 \u201clascado\u201d, mas que espera um pedido de desculpas do juiz S\u00e9rgio Moro. \u201cN\u00e3o quero nem que o Moro me absolva, s\u00f3 quero que pe\u00e7a desculpas.\u201d Muito aplaudido pela plateia, Lula prosseguiu em sua ofensiva contra a Lava Jato.<\/p>\n<p>&nbsp;<\/p>\n<p>Em quase 40 minutos de discurso, ressuscitou o discurso do \u201cn\u00f3s contra eles\u201d, disse n\u00e3o poder mais aceitar tantas \u201cmentiras\u201d e afirmou n\u00e3o ter medo da opera\u00e7\u00e3o. Disse ainda que, se o objetivo da Lava Jato \u00e9 n\u00e3o deix\u00e1-lo ser candidato, os investigadores n\u00e3o deveriam deixar \u201co povo sofrer\u201d por causa disso.<\/p>\n<p>Apesar de condenado no caso do triplex do Guaruj\u00e1, ser r\u00e9u em seis a\u00e7\u00f5es penais e estar denunciado em outros dois casos, o ex-presidente lidera as pesquisas de inten\u00e7\u00e3o de voto.<\/p>\n<p>Acompanhado do ex-prefeito Fernando Haddad, Lula criticou o deputado Jair Bolsonaro (PSC-RJ), presidenci\u00e1vel em 2018. \u201cSe o Bolsonaro agrada ao mercado, n\u00f3s do PT temos de desagradar ao mercado.\u201d<\/p>\n<p><strong>Recibos.<\/strong>\u00a0Moro mandou ontem a defesa de Lula \u201cesclarecer expressamente\u201d se tem os originais dos recibos do aluguel do apartamento em S\u00e3o Bernardo do Campo (SP). O im\u00f3vel \u00e9 vizinho ao de Lula e um dos piv\u00f4s da a\u00e7\u00e3o penal na qual o ex-presidente \u00e9 r\u00e9u por corrup\u00e7\u00e3o e lavagem de dinheiro na Lava Jato.<\/p>\n<p>A defesa de Lula apresentou recibos de pagamento. Dois dos comprovantes, no entanto, t\u00eam datas que n\u00e3o existem no calend\u00e1rio. O advogado Cristiano Zanin Martins disse que \u201ca per\u00edcia nos recibos vai demonstrar que eles s\u00e3o id\u00f4neos\u201d.<\/p>\n<p><strong>CARIRI EM A\u00c7\u00c3O<\/strong><\/p>\n<p><em>Com Estad\u00e3o \/Foto:Reprodu\u00e7\u00e3o &#8211; Google\u00a0\u00a0 <\/em><\/p>\n<p><strong>Leia mais not\u00edcias em\u00a0<\/strong><a href=\"http:\/\/www.caririemacao.com\/\"><strong>caririemacao.com<\/strong><\/a><strong>, siga nossa p\u00e1gina no\u00a0<\/strong><a href=\"https:\/\/www.facebook.com\/CaririEmAcao\/?ref=aymt_homepage_panel\"><strong>Facebook<\/strong><\/a>,<strong>\u00a0<\/strong><a href=\"https:\/\/www.instagram.com\/cariri_em_acao\/?hl=pt-br\"><strong>Instagram<\/strong><\/a><strong>\u00a0e <\/strong><a href=\"https:\/\/www.youtube.com\/channel\/UCAptA0jQuYQy8vMhLt2m4qg\"><strong>Youtube<\/strong><\/a><strong>\u00a0e veja nossas mat\u00e9rias, v\u00eddeos e fotos. Voc\u00ea tamb\u00e9m pode enviar informa\u00e7\u00f5es \u00e0 Reda\u00e7\u00e3o do Portal Cariri em A\u00e7\u00e3o pelo WhatsApp (83) 9 9634.5791, (83) 9 9601-1162.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Condenado a 9 anos e 6 meses de pris\u00e3o em primeira inst\u00e2ncia, o ex-presidente Luiz In\u00e1cio Lula da Silva voltou a desafiar ontem seus acusadores&hellip; <\/p>\n","protected":false},"author":2,"featured_media":18940,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[11],"tags":[],"class_list":["post-30401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/30401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=30401"}],"version-history":[{"count":0,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/30401\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/18940"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=30401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=30401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=30401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}