{"id":30416,"date":"2017-10-10T06:02:07","date_gmt":"2017-10-10T09:02:07","guid":{"rendered":"http:\/\/caririemacao.com\/1\/?p=30416"},"modified":"2017-10-10T06:02:07","modified_gmt":"2017-10-10T09:02:07","slug":"mpf-nuzman-tentou-usar-r-55-mi-da-rio-2016-para-pagar-advogado","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2017\/10\/10\/mpf-nuzman-tentou-usar-r-55-mi-da-rio-2016-para-pagar-advogado\/","title":{"rendered":"MPF: Nuzman tentou usar R$ 5,5 mi da Rio-2016 para pagar advogado"},"content":{"rendered":"<p>Ao\u00a0pedir a pris\u00e3o preventiva\u00a0do presidente afastado do\u00a0Comit\u00ea Ol\u00edmpico do Brasil (COB),\u00a0Carlos Arthur Nuzman, o\u00a0Minist\u00e9rio P\u00fablico Federal (MPF)\u00a0afirma que ele tentou usar a estrutura da institui\u00e7\u00e3o \u201cem benef\u00edcio pr\u00f3prio\u201d, ao propor que os honor\u00e1rios do escrit\u00f3rio do advogado criminalista que o defende fossem pagos com dinheiro do Comit\u00ea Organizador das Olimp\u00edadas do Rio de Janeiro. Nuzman foi preso temporariamente na segunda fase da\u00a0Opera\u00e7\u00e3o Unfair Play, que investiga compra de votos para fazer do Rio a sede dos Jogos de 2016.<\/p>\n<p>Entre os documentos apresentados pelos procuradores a\u00a0Bretas, est\u00e3o e-mails trocados entre Carlos Nuzman e M\u00e1rio Andrada, diretor de comunica\u00e7\u00e3o do comit\u00ea Rio-2016, nos quais o dirigente pediu que fosse paga uma nota fiscal no valor de 5,5 milh\u00f5es de reais emitida pelo escrit\u00f3rio do advogado Nelio Machado. O comit\u00ea da Rio-2016 deve cerca de 120 milh\u00f5es de reais a fornecedores.<\/p>\n<p>Apreendidos na primeira fase da Unfair Play, os e-mails foram enviados entre os dias 25 e 29 de setembro, cerca de vinte dias depois da deflagra\u00e7\u00e3o da opera\u00e7\u00e3o. Na ocasi\u00e3o, Nuzman foi conduzido coercitivamente a depor \u00e0 Pol\u00edcia Federal.<\/p>\n<p>Na primeira mensagem enviada a Andrada, no dia 25 de setembro, o dirigente orienta que \u201cface a urg\u00eancia\u201d, a nota fiscal deveria ser paga. A ordem foi dada antes da aprova\u00e7\u00e3o da despesa no conselho do comit\u00ea. \u201cEsse assunto ser\u00e1 levado a delibera\u00e7\u00e3o do Conselho Diretor Rio 2016 no dia 27 de setembro de 2017\u201d, completou o dirigente.<\/p>\n<p>Quatro dias depois, j\u00e1 no dia 29, Nuzman informa o subordinado sobre a autoriza\u00e7\u00e3o do pagamento. \u201cA Diretoria Estatut\u00e1ria do Comit\u00ea Rio 2016 deliberou, em reuni\u00e3o realizada no dia 27 de setembro passado, aprovar o contrato de presta\u00e7\u00e3o de servi\u00e7os advocat\u00edcios com o escrit\u00f3rio Nelio Machado Advogados. O pagamento da quantia contratada, no valor de R$ 5.500.000,00, est\u00e1 autorizado e deve ser realizado e efetivado\u201d, diz Carlos Nuzman\u00a0<em>(veja abaixo)<\/em>.<\/p>\n<p>No pedido de pris\u00e3o preventiva de Carlos Arthur Nuzman, os procuradores do MPF afirmam que o e-mail \u201cdemonstra o poder que Carlos Nuzman ainda exercia junto ao Comit\u00ea Ol\u00edmpico Brasileiro\u201d e que ele \u201ccontinua a atuar em benef\u00edcio pr\u00f3prio, usando os instrumentos do Comit\u00ea Ol\u00edmpico Brasileiro, bem como sua influ\u00eancia sobre as pessoas que l\u00e1 trabalham\u201d.<\/p>\n<p>Ao decretar a pris\u00e3o preventiva do dirigente, o juiz Marcelo Bretas diz que, aparentemente, Nuzman est\u00e1 usando recursos do COB \u201cpara fazer face a despesas pessoais\u201d e indaga: \u201cqual seria a urg\u00eancia mencionada pelo investigado em seu e-mail que n\u00e3o a sua defesa em poss\u00edveis medidas cautelares pessoais no futuro?\u201d.<\/p>\n<p>Apesar da informa\u00e7\u00e3o, pelo pr\u00f3prio Nuzman, de que o pagamento estava autorizado e deveria ser efetuado, o comit\u00ea Rio-2016 disse a VEJA que os conselheiros voltaram atr\u00e1s na decis\u00e3o diante da desaprova\u00e7\u00e3o da \u00e1rea de governan\u00e7a e que a nota fiscal foi cancelada\u00a0<em>(veja abaixo)<\/em>.<\/p>\n<p>O escrit\u00f3rio de Nelio Machado informa que n\u00e3o recebeu o valor e cancelou a nota porque a decis\u00e3o do conselho do comit\u00ea sobre o pagamento n\u00e3o foi un\u00e2nime. A banca ainda afirma que os honor\u00e1rios seriam pagos em rela\u00e7\u00e3o a servi\u00e7os prestados ao COB e ao comit\u00ea Rio-2016, e n\u00e3o a Carlos Nuzman.<\/p>\n<p><strong>CARIRI EM A\u00c7\u00c3O<\/strong><\/p>\n<p><em>Com VEJA.com\/Foto: Reprodu\u00e7\u00e3o Reuters \u00a0<\/em><\/p>\n<p><strong>Leia mais not\u00edcias em\u00a0<\/strong><a href=\"http:\/\/www.caririemacao.com\/\"><strong>caririemacao.com<\/strong><\/a><strong>, siga nossa p\u00e1gina no\u00a0<\/strong><a href=\"https:\/\/www.facebook.com\/CaririEmAcao\/?ref=aymt_homepage_panel\"><strong>Facebook<\/strong><\/a>,<strong>\u00a0<\/strong><a href=\"https:\/\/www.instagram.com\/cariri_em_acao\/?hl=pt-br\"><strong>Instagram<\/strong><\/a><strong>\u00a0e <\/strong><a href=\"https:\/\/www.youtube.com\/channel\/UCAptA0jQuYQy8vMhLt2m4qg\"><strong>Youtube<\/strong><\/a><strong>\u00a0e veja nossas mat\u00e9rias, v\u00eddeos e fotos. Voc\u00ea tamb\u00e9m pode enviar informa\u00e7\u00f5es \u00e0 Reda\u00e7\u00e3o do Portal Cariri em A\u00e7\u00e3o pelo WhatsApp (83) 9 9634.5791, (83) 9 9601-1162.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao\u00a0pedir a pris\u00e3o preventiva\u00a0do presidente afastado do\u00a0Comit\u00ea Ol\u00edmpico do Brasil (COB),\u00a0Carlos Arthur Nuzman, o\u00a0Minist\u00e9rio P\u00fablico Federal (MPF)\u00a0afirma que ele tentou usar a estrutura da institui\u00e7\u00e3o&hellip; <\/p>\n","protected":false},"author":2,"featured_media":30423,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-30416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/30416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=30416"}],"version-history":[{"count":0,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/30416\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/30423"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=30416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=30416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=30416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}