{"id":317387,"date":"2026-07-14T08:40:00","date_gmt":"2026-07-14T11:40:00","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=317387"},"modified":"2026-07-14T08:40:00","modified_gmt":"2026-07-14T11:40:00","slug":"em-agendas-na-paraiba-joao-diz-ouvir-da-populacao-que-o-governo-fez-muito","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2026\/07\/14\/em-agendas-na-paraiba-joao-diz-ouvir-da-populacao-que-o-governo-fez-muito\/","title":{"rendered":"Em agendas na Para\u00edba, Jo\u00e3o diz ouvir da popula\u00e7\u00e3o que \u2018o governo fez muito\u2019"},"content":{"rendered":"<p>O ex-governador da Para\u00edba, Jo\u00e3o Azev\u00eado (PSB), afirmou em entrevista \u00e0\u00a0Rede Mais\u00a0que tem escutado nas viagens pela Para\u00edba que \u2018o governo [dele] fez muito\u2019.<\/p>\n<p>\u201cN\u00f3s somos recebidos com um carinho t\u00e3o grande em cada munic\u00edpio que a gente passa. Esse carinho demonstrado pela popula\u00e7\u00e3o est\u00e1 associado a entrega e \u00e9 uma m\u00e1xima que voc\u00ea escuta o tempo todo, \u00e9: \u2018Foi um governo que trabalhou muito, foi um governo que entregou muito\u2019. E n\u00f3s sabemos disso, porque n\u00f3s fomos um time muito coeso, de uma equipe extraordin\u00e1ria que conseguiu fazer isso em todos os lugares\u201d, afirmou o ex-gestor.<\/p>\n<p>O pr\u00e9-candidato ao Senado est\u00e1 em uma s\u00e9rie de viagens pelo estado e afirmou estar em fase de planejamento para o in\u00edcio oficial da campanha eleitoral.<\/p>\n<p data-path-to-node=\"2\">\u201cEstamos numa reta final porque s\u00e3o menos de 90 dias para para a campanha e que n\u00f3s temos trabalhar para que, a partir de de agosto, quando a legisla\u00e7\u00e3o permitir, come\u00e7ar as grandes caravanas, a campanha eleitoral, efetivamente, que vai come\u00e7ar a partir de 15 de agosto. Est\u00e1 com tudo planejado e vamos p\u00f4r em pr\u00e1tica e fazer uma bela campanha Para\u00edba afora\u201d, concluiu<\/p>\n<p data-path-to-node=\"2\">FONTE: MaisPB<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ex-governador da Para\u00edba, Jo\u00e3o Azev\u00eado (PSB), afirmou em entrevista \u00e0\u00a0Rede Mais\u00a0que tem escutado nas viagens pela Para\u00edba que \u2018o governo [dele] fez muito\u2019. \u201cN\u00f3s&hellip; <\/p>\n","protected":false},"author":6,"featured_media":317389,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[50,104,11],"tags":[],"class_list":["post-317387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-paraiba","category-politica"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/317387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=317387"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/317387\/revisions"}],"predecessor-version":[{"id":317390,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/317387\/revisions\/317390"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/317389"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=317387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=317387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=317387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}