{"id":317425,"date":"2026-07-15T06:00:45","date_gmt":"2026-07-15T09:00:45","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=317425"},"modified":"2026-07-14T22:38:12","modified_gmt":"2026-07-15T01:38:12","slug":"queijo-de-leite-de-cabra-produzido-em-sao-joao-do-cariri-ganha-medalha-de-ouro-em-concurso-internacional","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2026\/07\/15\/queijo-de-leite-de-cabra-produzido-em-sao-joao-do-cariri-ganha-medalha-de-ouro-em-concurso-internacional\/","title":{"rendered":"Queijo de leite de cabra produzido em S\u00e3o Jo\u00e3o do Cariri ganha medalha de ouro em concurso internacional"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A produ\u00e7\u00e3o de queijos artesanais da Para\u00edba voltou a se destacar no cen\u00e1rio global com a conquista da medalha de ouro na Expo Queijo, em Arax\u00e1 (MG). O pr\u00eamio internacional foi concedido ao \u2018queijo mofado azul\u2019, produzido por Renato Brito no Capril Encanto da Macambira, em S\u00e3o Jo\u00e3o do Cariri.<\/p>\n<p class=\"wp-block-paragraph\">O queijo paraibano, produzido a partir do leite de cabra e em um processo de matura\u00e7\u00e3o que dura entre 30 e 40 dias, se destacou pela rea\u00e7\u00e3o rara durante a produ\u00e7\u00e3o, que produziu uma colora\u00e7\u00e3o azulada na superf\u00edcie do alimento. De acordo com o Renato Brito, a rea\u00e7\u00e3o \u00e9 o resultado do tipo do leite utilizado, aliada ao contexto clim\u00e1tico da regi\u00e3o e alimenta\u00e7\u00e3o das cabras.<\/p>\n<p class=\"wp-block-paragraph\">\u201cO queijo tem um mofo azul na composi\u00e7\u00e3o, que \u00e9 caracter\u00edstico da nossa regi\u00e3o. Foram feitas an\u00e1lises e chegamos \u00e0 conclus\u00e3o que \u00e9 devido ao nosso clima, alimenta\u00e7\u00e3o das cabras e o modo de preparo\u201d, explica o empreendedor Renato Brito. Ele lembrou ainda que o produto foi batizado de \u2018queijo aventureiro\u2019. O nome, segundo ele, \u00e9 uma resposta a uma provoca\u00e7\u00e3o que ouviu durante um dos concursos anteriores que participou.<\/p>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cTem esse nome por conta de uma situa\u00e7\u00e3o que aconteceu, em 2024, quando uma pessoa criticou os queijeiros da Para\u00edba, dizendo que n\u00f3s \u00e9ramos aventureiros e n\u00e3o sab\u00edamos fazer queijo. Eu falei para os meus amigos, que tamb\u00e9m s\u00e3o queijeiros, que eu faria um queijo, daria o nome de aventureiro e que esse queijo ganharia uma medalha de ouro\u201d, contou o produtor.<\/p>\n<\/blockquote>\n<figure class=\"wp-block-image\"><img decoding=\"async\" class=\"aligncenter lazyload\" data-src=\"https:\/\/assent-2k25.wscom.com.br\/wp-content\/uploads\/2026\/07\/Queijo-Capril-Macambira_Divulgacao-2-300x200.jpeg\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\" \/><\/figure>\n<p class=\"wp-block-paragraph\">(Foto: Divulga\u00e7\u00e3o)<\/p>\n<p class=\"wp-block-paragraph\">Antes de conquistar a primeira coloca\u00e7\u00e3o na Expo Queijo Arax\u00e1, o queijo de Renato Brito conquistou recentemente medalha de prata em um outro concurso internacional, realizado em S\u00e3o Paulo. \u201cS\u00e3o conquistas muito importantes para mim e para a nossa regi\u00e3o que vem se destacando. Isso faz com que a gente sempre esteja levando o nome da Para\u00edba e da caprinocultura pelo Brasil\u201d, acrescentou o empreendedor. Ele ainda lembrou que a Capril Encanto da Macambira tem o apoio do Sebrae\/PB, desde 2022, na otimiza\u00e7\u00e3o de processos e gest\u00e3o empresarial.<\/p>\n<h3 class=\"wp-block-heading\">Apoio ao produtor<\/h3>\n<p class=\"wp-block-paragraph\">Um dos gestores do Sebrae que acompanha os pequenos empreendedores do agroneg\u00f3cio na Para\u00edba, Pablo Queiroz, lembra que o produtor rural pode buscar apoio para o desenvolvimento de suas atividades rurais nas ag\u00eancias espalhadas pelo estado. O Sebrae\/PB oferece consultorias desde o apoio para a melhoria da gest\u00e3o do neg\u00f3cio at\u00e9 a participa\u00e7\u00e3o em eventos do setor e feiras de destaque no pa\u00eds.<\/p>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cO Sebrae continua atuando junto ao produtor rural, desde o manejo ao mercado, com o beneficiamento a certifica\u00e7\u00e3o e adequa\u00e7\u00e3o, como tamb\u00e9m \u00e0 presen\u00e7a no mercado e \u00e0 participa\u00e7\u00e3o em eventos do setor\u201d, disse Pablo Queiroz.<\/p>\n<\/blockquote>\n<p class=\"wp-block-paragraph\">O gestor ainda parabenizou o empreendedor pela premia\u00e7\u00e3o na Expo Queijo. \u201cCom essa conquista da Capril, a Para\u00edba mostra o seu poder de competitividade, n\u00e3o somente diante de outros estados, mas tamb\u00e9m fora do pa\u00eds. Esse \u00e9 um queijo que n\u00e3o \u00e9 tradicional na Para\u00edba, mas o produtor mostra que tem capacidade de fazer produtos de qualidade e se igualar a qualquer outra regi\u00e3o\u201d, acrescentou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A produ\u00e7\u00e3o de queijos artesanais da Para\u00edba voltou a se destacar no cen\u00e1rio global com a conquista da medalha de ouro na Expo Queijo, em&hellip; <\/p>\n","protected":false},"author":6,"featured_media":317426,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[50,2,88],"tags":[],"class_list":["post-317425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-geral","category-sao-joao-do-cariri"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/317425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=317425"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/317425\/revisions"}],"predecessor-version":[{"id":317427,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/317425\/revisions\/317427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/317426"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=317425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=317425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=317425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}