{"id":317464,"date":"2026-07-15T13:37:05","date_gmt":"2026-07-15T16:37:05","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=317464"},"modified":"2026-07-15T13:41:13","modified_gmt":"2026-07-15T16:41:13","slug":"tce-pb-aprova-por-unanimidade-contas-de-2023-do-prefeito-felicio-queiroz-de-sao-jose-dos-cordeiros","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2026\/07\/15\/tce-pb-aprova-por-unanimidade-contas-de-2023-do-prefeito-felicio-queiroz-de-sao-jose-dos-cordeiros\/","title":{"rendered":"TCE-PB aprova por unanimidade contas de 2023 do prefeito Fel\u00edcio Queiroz de S\u00e3o Jos\u00e9 dos Cordeiros"},"content":{"rendered":"<p class=\"wp-block-paragraph\">O Tribunal de Contas do Estado da Para\u00edba (TCE-PB) aprovou, por unanimidade, nesta quarta-feira (15), a Presta\u00e7\u00e3o de Contas Anuais da Prefeitura de S\u00e3o Jos\u00e9 dos Cordeiros referente ao exerc\u00edcio financeiro de 2023. As contas s\u00e3o de responsabilidade do prefeito Fel\u00edcio Queiroz.<\/p>\n<p class=\"wp-block-paragraph\">Com a decis\u00e3o, a atual gest\u00e3o alcan\u00e7a a terceira presta\u00e7\u00e3o de contas aprovada pela Corte de Contas, refor\u00e7ando o compromisso da administra\u00e7\u00e3o municipal com a correta aplica\u00e7\u00e3o dos recursos p\u00fablicos, o equil\u00edbrio das contas, o cumprimento dos \u00edndices constitucionais e a transpar\u00eancia na gest\u00e3o.<\/p>\n<p class=\"wp-block-paragraph\">Outro destaque \u00e9 o hist\u00f3rico administrativo do prefeito Fel\u00edcio Queiroz. Desde 2009, quando passou a atuar como ordenador de despesas do munic\u00edpio, ele nunca teve uma presta\u00e7\u00e3o de contas reprovada pelo Tribunal de Contas do Estado, mantendo uma trajet\u00f3ria marcada pela regularidade na gest\u00e3o dos recursos p\u00fablicos.<\/p>\n<p class=\"wp-block-paragraph\">A aprova\u00e7\u00e3o tamb\u00e9m evidencia o trabalho desenvolvido por toda a equipe da Prefeitura de S\u00e3o Jos\u00e9 dos Cordeiros, incluindo secret\u00e1rios, servidores e assessores, que atuam na execu\u00e7\u00e3o das pol\u00edticas p\u00fablicas e na organiza\u00e7\u00e3o administrativa do munic\u00edpio.<\/p>\n<p class=\"wp-block-paragraph\">O resultado ainda reconhece o trabalho t\u00e9cnico da equipe da Complan, respons\u00e1vel pela contabilidade e planejamento da gest\u00e3o e tamb\u00e9m a assessoria Jur\u00eddica coordenada por Jos\u00e9 Maviael que contribui para a elabora\u00e7\u00e3o das presta\u00e7\u00f5es de contas e para a manuten\u00e7\u00e3o da regularidade fiscal do munic\u00edpio.<\/p>\n<p class=\"wp-block-paragraph\">A decis\u00e3o do TCE-PB representa mais um reconhecimento \u00e0 condu\u00e7\u00e3o administrativa da Prefeitura de S\u00e3o Jos\u00e9 dos Cordeiros e fortalece a credibilidade da gest\u00e3o, que segue mantendo um hist\u00f3rico de contas aprovadas e responsabilidade na aplica\u00e7\u00e3o dos recursos p\u00fablicos.<\/p>\n<p class=\"wp-block-paragraph\">Assessoria<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal de Contas do Estado da Para\u00edba (TCE-PB) aprovou, por unanimidade, nesta quarta-feira (15), a Presta\u00e7\u00e3o de Contas Anuais da Prefeitura de S\u00e3o Jos\u00e9&hellip; <\/p>\n","protected":false},"author":6,"featured_media":317465,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[50,2,91],"tags":[],"class_list":["post-317464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-geral","category-sao-jose-dos-cordeiros"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/317464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=317464"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/317464\/revisions"}],"predecessor-version":[{"id":317466,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/317464\/revisions\/317466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/317465"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=317464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=317464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=317464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}